{"id":457497,"date":"2022-07-22T10:40:16","date_gmt":"2022-07-22T08:40:16","guid":{"rendered":"https:\/\/www.locabarcelona.com\/property\/splendid-2-bedroom-apartment-with-balcony-for-rent\/"},"modified":"2026-07-15T01:31:16","modified_gmt":"2026-07-14T23:31:16","slug":"splendide-appartement-2-chambres-avec-balcon-a-louer","status":"publish","type":"property","link":"https:\/\/www.locabarcelona.com\/fr\/splendide-appartement-2-chambres-avec-balcon-a-louer\/","title":{"rendered":"Splendide appartement 2 chambres avec balcon \u00e0 louer"},"content":{"rendered":"<p>Num\u00e9ro d&#8217;enregistrement AICAT 11525<br \/>Num\u00e9ro API A13529<br \/>L&#8217;appartement est en parfait \u00e9tat.<br \/>Statut au cours des 5 derni\u00e8res ann\u00e9es : Non Lou\u00e9.<br \/>Certificat d&#8217;habitabilit\u00e9: CHB06853416001<br \/>Certificat \u00e9nerg\u00e9tique avec note G  . Inscription KWNSR5PT7  .<br \/>Augmentation annuelle &#8211; IPC.<br \/>Le propri\u00e9taire n&#8217;est pas un grand propri\u00e9taire<br \/><strong>NRU:<\/strong> ESFCTU00000807300010308000000000000000HUTB-001081-854<\/p>\n<h1><strong>\u00c0 propos de ce logement<\/strong><\/h1>\n<p><\/p>\n<p>Appartement touristique de 50 m\u00b2 situ\u00e9 rue Mallorca, \u00e0 trois p\u00e2t\u00e9s de maisons de la Sagrada Fam\u00edlia. Il peut accueillir jusqu\u2019\u00e0 4 personnes et dispose de deux chambres (une double et une avec lits superpos\u00e9s), d\u2019une salle de bain avec douche, d\u2019un salon lumineux climatis\u00e9 et d\u2019un petit balcon. Climatisation par split dans le salon et les deux chambres. Immeuble avec ascenseur, proche des commerces, restaurants et transports en commun.<\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<h2>Le logement<\/h2>\n<p><\/p>\n<p>Bienvenue dans ce charmant appartement touristique situ\u00e9 rue Mallorca, \u00e0 seulement trois p\u00e2t\u00e9s de maisons de l\u2019embl\u00e9matique Sagrada Fam\u00edlia, l\u2019un des monuments les plus c\u00e9l\u00e8bres de Barcelone. Son excellente situation vous permet de profiter de la ville en toute simplicit\u00e9, avec un acc\u00e8s facile aux principales attractions et \u00e0 tous les services essentiels.<\/p>\n<p><\/p>\n<p>L\u2019appartement offre une superficie d\u2019environ 50 m\u00b2 et peut accueillir confortablement jusqu\u2019\u00e0 3 personnes. Il est id\u00e9al pour les familles, les couples ou les petits groupes d\u2019amis. Sa distribution pratique et fonctionnelle permet d\u2019optimiser l\u2019espace et d\u2019assurer un s\u00e9jour agr\u00e9able.<\/p>\n<p><\/p>\n<p>Il dispose de deux chambres : une chambre double, parfaite pour se reposer, et une seconde chambre avec lits superpos\u00e9s, id\u00e9ale pour les enfants ou les autres voyageurs. Les deux chambres sont \u00e9quip\u00e9es de la climatisation par split, garantissant une temp\u00e9rature agr\u00e9able toute l\u2019ann\u00e9e. L\u2019appartement comprend \u00e9galement une salle de bain compl\u00e8te avec douche, moderne et confortable pour un usage quotidien.<\/p>\n<p><\/p>\n<p>Le salon est lumineux et accueillant, offrant un cadre id\u00e9al pour se d\u00e9tendre apr\u00e8s une journ\u00e9e de d\u00e9couverte de la ville. Il est \u00e9galement \u00e9quip\u00e9 de la climatisation par split, assurant un confort optimal m\u00eame pendant les mois les plus chauds. Depuis le salon, vous acc\u00e9dez \u00e0 un petit balcon, un espace charmant pour profiter de la lumi\u00e8re naturelle, prendre un caf\u00e9 le matin ou se relaxer en fin de journ\u00e9e.<\/p>\n<p><\/p>\n<p>L\u2019immeuble dispose d\u2019un ascenseur, apportant un confort suppl\u00e9mentaire, notamment pour les familles ou les s\u00e9jours avec bagages.<\/p>\n<p><\/p>\n<p>Gr\u00e2ce \u00e0 sa situation dans le quartier de l\u2019Eixample, vous trouverez \u00e0 proximit\u00e9 imm\u00e9diate de nombreux restaurants, caf\u00e9s, supermarch\u00e9s, boutiques et transports en commun, vous permettant de vous d\u00e9placer facilement dans Barcelone et de d\u00e9couvrir aussi bien ses sites touristiques que sa vie locale authentique.<\/p>\n<p><\/p>\n<p>Cet appartement r\u00e9unit emplacement privil\u00e9gi\u00e9, luminosit\u00e9, fonctionnalit\u00e9 et confort, et constitue le choix id\u00e9al pour un s\u00e9jour agr\u00e9able et inoubliable \u00e0 Barcelone, \u00e0 quelques minutes de la Sagrada Fam\u00edlia.<\/p>\n<p><\/p>\n<p>Veuillez noter les informations importantes suivantes avant de r\u00e9server&nbsp;:<\/p>\n<p><\/p>\n<p>&#8211; Les serviettes, les draps ainsi que le papier toilette sont inclus \u00e0 l&#8217;arriv\u00e9e, cependant le remplacement ou le changement pendant votre s\u00e9jour n&#8217;est pas inclus<\/p>\n<p><\/p>\n<p>&#8211; Lit b\u00e9b\u00e9&nbsp;:<\/p>\n<p>Prix \u200b\u200b: 30,00 EUR par r\u00e9servation. Ce n&#8217;est pas garanti, les clients doivent en faire la demande 24 \u00e0 48 heures \u00e0 l&#8217;avance et si disponible, nous le fournirons.<\/p>\n<p><\/p>\n<p>-Voyageur additionnel:<\/p>\n<p>Chaque voyageur suppl\u00e9mentaire non inclus dans la r\u00e9servation sera factur\u00e9&nbsp;10\u202f\u20ac&nbsp;par&nbsp;nuit.<\/p>\n<p><\/p>\n<p>-Arriv\u00e9e en dehors des heures d&#8217;ouverture&nbsp;:<\/p>\n<p><\/p>\n<p>L&#8217;enregistrement s&#8217;effectue de 15 h \u00e0 19 h, du lundi au vendredi (veuillez nous contacter si vous souhaitez vous enregistrer plus t\u00f4t). En dehors de ces horaires, un suppl\u00e9ment de 30 \u20ac en esp\u00e8ces vous sera factur\u00e9 ; apr\u00e8s 22 h, ce suppl\u00e9ment sera de 50 \u20ac et apr\u00e8s minuit, de 80 \u20ac.<\/p>\n<p><\/p>\n<p>&#8211; Si le jour d&#8217;arriv\u00e9e est un jour f\u00e9ri\u00e9 local ou national ou un week-end, le co\u00fbt sera de 30 \u20ac jusqu&#8217;\u00e0 22 h, de 50 \u20ac apr\u00e8s 22 h et de 80 \u20ac apr\u00e8s minuit.<\/p>\n<p><\/p>\n<p>&#8211; Si le jour d&#8217;arriv\u00e9e est le 25\/12, le 26\/12 ou le 01\/01, les frais seront les suivants : 50 \u20ac jusqu&#8217;\u00e0 22 h, 100 \u20ac apr\u00e8s 22 h.<\/p>\n<p><\/p>\n<p>&#8211; La taxe de s\u00e9jour en vigueur \u00e0 Barcelone en 2026 sera appliqu\u00e9e (9,50 \u20ac par personne et par nuit, pour les personnes \u00e2g\u00e9es de plus de 16 ans et jusqu&#8217;\u00e0 7 nuits). De plus, des frais de service de 15 \u20ac s&#8217;appliqueront.<\/p>\n<p><\/p>\n<p>&#8211; Il est INTERDIT de fumer sous aucun pr\u00e9texte. Recevoir un rapport ou avoir la preuve que fumer dans l&#8217;appartement entra\u00eenera l&#8217;expulsion imm\u00e9diate de l&#8217;appartement et une amende d&#8217;au moins 400 euros. Il est strictement interdit de fumer dans toutes les pi\u00e8ces de l&#8217;appartement, y compris sur le balcon.<\/p>\n<p><\/p>\n<p>&#8211; Les f\u00eates ou r\u00e9unions ne sont en aucun cas AUTORIS\u00c9ES. Si nous recevons un signalement et\/ou que la police, la s\u00e9curit\u00e9 ou des voisins interviennent, vous devrez payer une amende de 500 \u20ac (en plus de l&#8217;amende de police).<\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<h2>Acc\u00e8s des voyageurs<\/h2>\n<p><\/p>\n<p>Les voyageurs ont acc\u00e8s \u00e0 tout l\u2019appartement.<\/p>\n<p><\/p>\n<p>Situ\u00e9 dans la rue Mallorca, tout pr\u00e8s de la Sagrada Fam\u00edlia, cet appartement est le point de d\u00e9part id\u00e9al pour d\u00e9couvrir l\u2019un des quartiers les plus embl\u00e9matiques et authentiques de Barcelone. Le quartier allie monuments c\u00e9l\u00e8bres, architecture moderniste, vie locale et une large offre gastronomique et culturelle.<\/p>\n<p><\/p>\n<p>\u00c0 quelques pas se trouve la Sagrada Fam\u00edlia, le chef-d\u2019\u0153uvre inachev\u00e9 d\u2019Antoni Gaud\u00ed et l\u2019un des symboles les plus reconnus de la ville. Se promener dans ses environs permet d\u2019admirer la basilique sous diff\u00e9rents angles, de profiter de ses places et de capturer des photos inoubliables, de jour comme de nuit.<\/p>\n<p><\/p>\n<p>\u00c0 proximit\u00e9 se trouve \u00e9galement le Recinte Modernista de Sant Pau, class\u00e9 au patrimoine mondial de l\u2019UNESCO. Cet ancien h\u00f4pital moderniste est parfait pour une promenade tranquille parmi les jardins, les pavillons historiques et une architecture unique qui refl\u00e8te la splendeur du modernisme catalan.<\/p>\n<p><\/p>\n<p>Le quartier invite \u00e0 fl\u00e2ner tranquillement dans l\u2019Eixample, \u00e0 d\u00e9couvrir ses larges rues, ses fa\u00e7ades modernistes et la vie quotidienne de Barcelone. Une promenade sur le Passeig de Sant Joan ou dans les rues environnantes permet de combiner architecture, espaces verts et caf\u00e9s charmants.<\/p>\n<p><\/p>\n<p>Pour les amateurs de gastronomie, la zone offre une grande vari\u00e9t\u00e9 de restaurants locaux, de bars \u00e0 tapas, de boulangeries et de caf\u00e9s, o\u00f9 vous pourrez d\u00e9guster une cuisine catalane traditionnelle ainsi que des options internationales. C\u2019est l\u2019endroit parfait pour le petit-d\u00e9jeuner, le brunch ou le d\u00eener apr\u00e8s une journ\u00e9e de visites.<\/p>\n<p><\/p>\n<p>Pour un moment de d\u00e9tente, les parcs et places \u00e0 proximit\u00e9 de la Sagrada Fam\u00edlia sont id\u00e9aux pour s\u2019asseoir, lire ou simplement profiter de l\u2019ambiance du quartier. C\u2019est \u00e9galement une zone agr\u00e9able pour courir ou se promener le matin.<\/p>\n<p><\/p>\n<p>Gr\u00e2ce aux excellentes connexions en m\u00e9tro et en bus, depuis l\u2019appartement, vous pouvez facilement rejoindre d\u2019autres points cl\u00e9s de la ville tels que le Passeig de Gr\u00e0cia, le centre historique, Gr\u00e0cia, la Barceloneta ou le Parc G\u00fcell.<\/p>\n<p><\/p>\n<p>Ce quartier combine parfaitement culture, architecture, gastronomie et vie locale, offrant une exp\u00e9rience compl\u00e8te pour ceux qui souhaitent d\u00e9couvrir Barcelone depuis un environnement authentique et bien connect\u00e9.<\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<h2>Autres remarques<\/h2>\n<p><\/p>\n<p>La propri\u00e9t\u00e9 ne sera en aucun cas tenue responsable des vols, cambriolages ou autres vols de biens qui pourraient se produire dans les installations de nos appartements.<\/p>\n<p>Il est vivement conseill\u00e9 aux h\u00f4tes de prendre les pr\u00e9cautions n\u00e9cessaires pour la conservation de leurs objets de valeur, y compris l&#8217;utilisation de coffres-forts s&#8217;ils sont disponibles, et de garder les portes et fen\u00eatres correctement ferm\u00e9es et s\u00e9curis\u00e9es.<\/p>\n<p>La s\u00e9curit\u00e9 des biens personnels rel\u00e8ve de la seule responsabilit\u00e9 du client.<\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<p><\/p>\n<h2>D\u00e9tails de l&#8217;enregistrement<\/h2>\n<p><\/p>\n<p>Espagne&nbsp;\u2013 Num\u00e9ro d&#8217;enregistrement national<\/p>\n<p>ESFCTU00000807300010308000000000000000HUTB-001081-854<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Num\u00e9ro d&#8217;enregistrement AICAT 11525Num\u00e9ro API A13529L&#8217;appartement est en parfait \u00e9tat.Statut au cours des 5 derni\u00e8res ann\u00e9es : Non Lou\u00e9.Certificat d&#8217;habitabilit\u00e9: CHB06853416001Certificat \u00e9nerg\u00e9tique avec note G . Inscription KWNSR5PT7 .Augmentation annuelle &#8211; IPC.Le propri\u00e9taire n&#8217;est pas un grand propri\u00e9taireNRU: ESFCTU00000807300010308000000000000000HUTB-001081-854 \u00c0 propos de ce logement Appartement touristique de 50 m\u00b2 situ\u00e9 rue Mallorca, \u00e0 trois p\u00e2t\u00e9s&#8230;<\/p>\n","protected":false},"author":1,"featured_media":913166,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","property-feature":[437,604,603,133,88,189,517,440,207,135,105,103,70,505,68,508,552,605,107,433,537,443,523,542,546,2002],"property-type":[95],"property-city":[90,679],"property-status":[421],"property-sale-labels":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.6 (Yoast SEO v22.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Splendide appartement 2 chambres avec balcon \u00e0 louer | Locabarcelona<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.locabarcelona.com\/fr\/splendide-appartement-2-chambres-avec-balcon-a-louer\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Splendide appartement 2 chambres avec balcon \u00e0 louer | Locabarcelona\" \/>\n<meta property=\"og:description\" content=\"Num\u00e9ro d&#8217;enregistrement AICAT 11525Num\u00e9ro API A13529L&#8217;appartement est en parfait \u00e9tat.Statut au cours des 5 derni\u00e8res ann\u00e9es : Non Lou\u00e9.Certificat d&#8217;habitabilit\u00e9: CHB06853416001Certificat \u00e9nerg\u00e9tique avec note G . Inscription KWNSR5PT7 .Augmentation annuelle &#8211; IPC.Le propri\u00e9taire n&#8217;est pas un grand propri\u00e9taireNRU: ESFCTU00000807300010308000000000000000HUTB-001081-854 \u00c0 propos de ce logement Appartement touristique de 50 m\u00b2 situ\u00e9 rue Mallorca, \u00e0 trois p\u00e2t\u00e9s...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.locabarcelona.com\/fr\/splendide-appartement-2-chambres-avec-balcon-a-louer\/\" \/>\n<meta property=\"og:site_name\" content=\"Locabarcelona\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T23:31:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c9b4c147-9ea5-4ac5-b76b-7a750748e78f-8-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.locabarcelona.com\/fr\/splendide-appartement-2-chambres-avec-balcon-a-louer\/\",\"url\":\"https:\/\/www.locabarcelona.com\/fr\/splendide-appartement-2-chambres-avec-balcon-a-louer\/\",\"name\":\"Splendide appartement 2 chambres avec balcon \u00e0 louer | Locabarcelona\",\"isPartOf\":{\"@id\":\"https:\/\/www.locabarcelona.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.locabarcelona.com\/fr\/splendide-appartement-2-chambres-avec-balcon-a-louer\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.locabarcelona.com\/fr\/splendide-appartement-2-chambres-avec-balcon-a-louer\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c9b4c147-9ea5-4ac5-b76b-7a750748e78f-8-scaled.jpg\",\"datePublished\":\"2022-07-22T08:40:16+00:00\",\"dateModified\":\"2026-07-14T23:31:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.locabarcelona.com\/fr\/splendide-appartement-2-chambres-avec-balcon-a-louer\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.locabarcelona.com\/fr\/splendide-appartement-2-chambres-avec-balcon-a-louer\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.locabarcelona.com\/fr\/splendide-appartement-2-chambres-avec-balcon-a-louer\/#primaryimage\",\"url\":\"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c9b4c147-9ea5-4ac5-b76b-7a750748e78f-8-scaled.jpg\",\"contentUrl\":\"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c9b4c147-9ea5-4ac5-b76b-7a750748e78f-8-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.locabarcelona.com\/fr\/splendide-appartement-2-chambres-avec-balcon-a-louer\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.locabarcelona.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Properties\",\"item\":\"https:\/\/www.locabarcelona.com\/fr\/appartement\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Splendide appartement 2 chambres avec balcon \u00e0 louer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.locabarcelona.com\/fr\/#website\",\"url\":\"https:\/\/www.locabarcelona.com\/fr\/\",\"name\":\"Loca Barcelona\",\"description\":\"Real Estate Services\",\"publisher\":{\"@id\":\"https:\/\/www.locabarcelona.com\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.locabarcelona.com\/fr\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.locabarcelona.com\/fr\/#organization\",\"name\":\"Loca Barcelona\",\"url\":\"https:\/\/www.locabarcelona.com\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.locabarcelona.com\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/10\/logo_locabarcelona_small.png\",\"contentUrl\":\"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/10\/logo_locabarcelona_small.png\",\"width\":250,\"height\":149,\"caption\":\"Loca Barcelona\"},\"image\":{\"@id\":\"https:\/\/www.locabarcelona.com\/fr\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Splendide appartement 2 chambres avec balcon \u00e0 louer | Locabarcelona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.locabarcelona.com\/fr\/splendide-appartement-2-chambres-avec-balcon-a-louer\/","og_locale":"fr_FR","og_type":"article","og_title":"Splendide appartement 2 chambres avec balcon \u00e0 louer | Locabarcelona","og_description":"Num\u00e9ro d&#8217;enregistrement AICAT 11525Num\u00e9ro API A13529L&#8217;appartement est en parfait \u00e9tat.Statut au cours des 5 derni\u00e8res ann\u00e9es : Non Lou\u00e9.Certificat d&#8217;habitabilit\u00e9: CHB06853416001Certificat \u00e9nerg\u00e9tique avec note G . Inscription KWNSR5PT7 .Augmentation annuelle &#8211; IPC.Le propri\u00e9taire n&#8217;est pas un grand propri\u00e9taireNRU: ESFCTU00000807300010308000000000000000HUTB-001081-854 \u00c0 propos de ce logement Appartement touristique de 50 m\u00b2 situ\u00e9 rue Mallorca, \u00e0 trois p\u00e2t\u00e9s...","og_url":"https:\/\/www.locabarcelona.com\/fr\/splendide-appartement-2-chambres-avec-balcon-a-louer\/","og_site_name":"Locabarcelona","article_modified_time":"2026-07-14T23:31:16+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c9b4c147-9ea5-4ac5-b76b-7a750748e78f-8-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.locabarcelona.com\/fr\/splendide-appartement-2-chambres-avec-balcon-a-louer\/","url":"https:\/\/www.locabarcelona.com\/fr\/splendide-appartement-2-chambres-avec-balcon-a-louer\/","name":"Splendide appartement 2 chambres avec balcon \u00e0 louer | Locabarcelona","isPartOf":{"@id":"https:\/\/www.locabarcelona.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.locabarcelona.com\/fr\/splendide-appartement-2-chambres-avec-balcon-a-louer\/#primaryimage"},"image":{"@id":"https:\/\/www.locabarcelona.com\/fr\/splendide-appartement-2-chambres-avec-balcon-a-louer\/#primaryimage"},"thumbnailUrl":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c9b4c147-9ea5-4ac5-b76b-7a750748e78f-8-scaled.jpg","datePublished":"2022-07-22T08:40:16+00:00","dateModified":"2026-07-14T23:31:16+00:00","breadcrumb":{"@id":"https:\/\/www.locabarcelona.com\/fr\/splendide-appartement-2-chambres-avec-balcon-a-louer\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.locabarcelona.com\/fr\/splendide-appartement-2-chambres-avec-balcon-a-louer\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.locabarcelona.com\/fr\/splendide-appartement-2-chambres-avec-balcon-a-louer\/#primaryimage","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c9b4c147-9ea5-4ac5-b76b-7a750748e78f-8-scaled.jpg","contentUrl":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c9b4c147-9ea5-4ac5-b76b-7a750748e78f-8-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/www.locabarcelona.com\/fr\/splendide-appartement-2-chambres-avec-balcon-a-louer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.locabarcelona.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Properties","item":"https:\/\/www.locabarcelona.com\/fr\/appartement\/"},{"@type":"ListItem","position":3,"name":"Splendide appartement 2 chambres avec balcon \u00e0 louer"}]},{"@type":"WebSite","@id":"https:\/\/www.locabarcelona.com\/fr\/#website","url":"https:\/\/www.locabarcelona.com\/fr\/","name":"Loca Barcelona","description":"Real Estate Services","publisher":{"@id":"https:\/\/www.locabarcelona.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.locabarcelona.com\/fr\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.locabarcelona.com\/fr\/#organization","name":"Loca Barcelona","url":"https:\/\/www.locabarcelona.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.locabarcelona.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/10\/logo_locabarcelona_small.png","contentUrl":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/10\/logo_locabarcelona_small.png","width":250,"height":149,"caption":"Loca Barcelona"},"image":{"@id":"https:\/\/www.locabarcelona.com\/fr\/#\/schema\/logo\/image\/"}}]}},"property_meta":{"REAL_HOMES_property_price":"250","REAL_HOMES_property_old_price":"","REAL_HOMES_property_price_prefix":"From","REAL_HOMES_property_price_postfix":"Per Night","REAL_HOMES_property_size":"50","REAL_HOMES_property_size_postfix":"m2","REAL_HOMES_property_lot_size":"","REAL_HOMES_property_lot_size_postfix":"","REAL_HOMES_property_bedrooms":"2","REAL_HOMES_property_bathrooms":"1","REAL_HOMES_property_garage":"","REAL_HOMES_property_id":"TUA63MAL1030","REAL_HOMES_property_floors":"7","REAL_HOMES_Lift":"1","REAL_HOMES_Wifi_included":"0","REAL_HOMES_Wifi_type":"Unknown","REAL_HOMES_public_address":"C de Mallorca","REAL_HOMES_underground_station":"Metro Encants","REAL_HOMES_Availability":"1","REAL_HOMES_property_startdate_override":"0","REAL_HOMES_property_startdate":"2026-08-06","REAL_HOMES_property_enddate":"","REAL_HOMES_property_starthour":"","REAL_HOMES_property_endhour":"","REAL_HOMES_property_deposit":"250","REAL_HOMES_property_itp":"0","REAL_HOMES_property_agencyfee_3months":"","REAL_HOMES_property_agencyfee_5months":"","REAL_HOMES_property_agencyfee_11months":"","REAL_HOMES_property_agencyfee_long_term":"","REAL_HOMES_property_vat":"0","REAL_HOMES_property_year_built":"","REAL_HOMES_featured":"0","REAL_HOMES_additional_details_list":[],"REAL_HOMES_property_location":{"latitude":"41.4066188","longitude":"2.1797721","zoom":"14"},"REAL_HOMES_property_address":"Barcelona","REAL_HOMES_property_map":"","REAL_HOMES_property_images":[{"width":150,"height":150,"file":"2022\/07\/3590b56c-5f37-483d-82fc-a375a7969bb4-4-scaled.jpg","filesize":650376,"sizes":{"medium":{"file":"3590b56c-5f37-483d-82fc-a375a7969bb4-4-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":29912,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/3590b56c-5f37-483d-82fc-a375a7969bb4-4-300x200.jpg"},"large":{"file":"3590b56c-5f37-483d-82fc-a375a7969bb4-4-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":130925,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/3590b56c-5f37-483d-82fc-a375a7969bb4-4-1024x683.jpg"},"thumbnail":{"file":"3590b56c-5f37-483d-82fc-a375a7969bb4-4-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":22512,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/3590b56c-5f37-483d-82fc-a375a7969bb4-4-150x150.jpg"},"medium_large":{"file":"3590b56c-5f37-483d-82fc-a375a7969bb4-4-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":85191,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/3590b56c-5f37-483d-82fc-a375a7969bb4-4-768x512.jpg"},"1536x1536":{"file":"3590b56c-5f37-483d-82fc-a375a7969bb4-4-1536x1024.jpg","width":1536,"height":1024,"mime-type":"image\/jpeg","filesize":255066,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/3590b56c-5f37-483d-82fc-a375a7969bb4-4-1536x1024.jpg"},"2048x2048":{"file":"3590b56c-5f37-483d-82fc-a375a7969bb4-4-2048x1365.jpg","width":2048,"height":1365,"mime-type":"image\/jpeg","filesize":430023,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/3590b56c-5f37-483d-82fc-a375a7969bb4-4-2048x1365.jpg"},"square":{"file":"3590b56c-5f37-483d-82fc-a375a7969bb4-4-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":59790,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/3590b56c-5f37-483d-82fc-a375a7969bb4-4-450x450.jpg"},"property-large-image":{"file":"3590b56c-5f37-483d-82fc-a375a7969bb4-4-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":161184,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/3590b56c-5f37-483d-82fc-a375a7969bb4-4-1170x780.jpg"},"post-thumbnail":{"file":"3590b56c-5f37-483d-82fc-a375a7969bb4-4-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":20350,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/3590b56c-5f37-483d-82fc-a375a7969bb4-4-150x100.jpg"},"modern-property-child-slider":{"file":"3590b56c-5f37-483d-82fc-a375a7969bb4-4-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":80099,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/3590b56c-5f37-483d-82fc-a375a7969bb4-4-680x510.jpg"},"property-thumb-image":{"file":"3590b56c-5f37-483d-82fc-a375a7969bb4-4-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":47695,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/3590b56c-5f37-483d-82fc-a375a7969bb4-4-488x326.jpg"},"property-detail-video-image":{"file":"3590b56c-5f37-483d-82fc-a375a7969bb4-4-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":81498,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/3590b56c-5f37-483d-82fc-a375a7969bb4-4-818x417.jpg"},"agent-image":{"file":"3590b56c-5f37-483d-82fc-a375a7969bb4-4-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":27896,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/3590b56c-5f37-483d-82fc-a375a7969bb4-4-210x210.jpg"},"partners-logo":{"file":"3590b56c-5f37-483d-82fc-a375a7969bb4-4-600x2132.jpg","width":600,"height":2132,"mime-type":"image\/jpeg","filesize":258183,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/3590b56c-5f37-483d-82fc-a375a7969bb4-4-600x2132.jpg"},"post-featured-image":{"file":"3590b56c-5f37-483d-82fc-a375a7969bb4-4-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":162526,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/3590b56c-5f37-483d-82fc-a375a7969bb4-4-1240x720.jpg"}},"image_meta":{"aperture":"11","credit":"Christian Ribas","camera":"Canon EOS 5D Mark IV","caption":"","created_timestamp":"1749828189","copyright":"www.christianribas.es","focal_length":"17","iso":"400","shutter_speed":"0.076923076923077","title":"","orientation":"1","keywords":[]},"original_image":"3590b56c-5f37-483d-82fc-a375a7969bb4-4.jpg","ID":"913170","name":"3590b56c-5f37-483d-82fc-a375a7969bb4-4-scaled.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2022\/07\/3590b56c-5f37-483d-82fc-a375a7969bb4-4-scaled.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/3590b56c-5f37-483d-82fc-a375a7969bb4-4-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/3590b56c-5f37-483d-82fc-a375a7969bb4-4-scaled.jpg","title":"3590b56c-5f37-483d-82fc-a375a7969bb4-4","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/3590b56c-5f37-483d-82fc-a375a7969bb4-4-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/3590b56c-5f37-483d-82fc-a375a7969bb4-4-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/3590b56c-5f37-483d-82fc-a375a7969bb4-4-210x210.jpg 210w"},{"width":150,"height":150,"file":"2022\/07\/db16539f-b961-4941-90ba-0117d6546c17-4-scaled.jpg","filesize":524828,"sizes":{"medium":{"file":"db16539f-b961-4941-90ba-0117d6546c17-4-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":28601,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/db16539f-b961-4941-90ba-0117d6546c17-4-300x200.jpg"},"large":{"file":"db16539f-b961-4941-90ba-0117d6546c17-4-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":117762,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/db16539f-b961-4941-90ba-0117d6546c17-4-1024x683.jpg"},"thumbnail":{"file":"db16539f-b961-4941-90ba-0117d6546c17-4-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":21143,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/db16539f-b961-4941-90ba-0117d6546c17-4-150x150.jpg"},"medium_large":{"file":"db16539f-b961-4941-90ba-0117d6546c17-4-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":78741,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/db16539f-b961-4941-90ba-0117d6546c17-4-768x512.jpg"},"1536x1536":{"file":"db16539f-b961-4941-90ba-0117d6546c17-4-1536x1024.jpg","width":1536,"height":1024,"mime-type":"image\/jpeg","filesize":220810,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/db16539f-b961-4941-90ba-0117d6546c17-4-1536x1024.jpg"},"2048x2048":{"file":"db16539f-b961-4941-90ba-0117d6546c17-4-2048x1365.jpg","width":2048,"height":1365,"mime-type":"image\/jpeg","filesize":357853,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/db16539f-b961-4941-90ba-0117d6546c17-4-2048x1365.jpg"},"square":{"file":"db16539f-b961-4941-90ba-0117d6546c17-4-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":51024,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/db16539f-b961-4941-90ba-0117d6546c17-4-450x450.jpg"},"property-large-image":{"file":"db16539f-b961-4941-90ba-0117d6546c17-4-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":144761,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/db16539f-b961-4941-90ba-0117d6546c17-4-1170x780.jpg"},"post-thumbnail":{"file":"db16539f-b961-4941-90ba-0117d6546c17-4-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":19813,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/db16539f-b961-4941-90ba-0117d6546c17-4-150x100.jpg"},"modern-property-child-slider":{"file":"db16539f-b961-4941-90ba-0117d6546c17-4-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":73169,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/db16539f-b961-4941-90ba-0117d6546c17-4-680x510.jpg"},"property-thumb-image":{"file":"db16539f-b961-4941-90ba-0117d6546c17-4-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":45286,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/db16539f-b961-4941-90ba-0117d6546c17-4-488x326.jpg"},"property-detail-video-image":{"file":"db16539f-b961-4941-90ba-0117d6546c17-4-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":73348,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/db16539f-b961-4941-90ba-0117d6546c17-4-818x417.jpg"},"agent-image":{"file":"db16539f-b961-4941-90ba-0117d6546c17-4-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":25351,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/db16539f-b961-4941-90ba-0117d6546c17-4-210x210.jpg"},"partners-logo":{"file":"db16539f-b961-4941-90ba-0117d6546c17-4-600x2132.jpg","width":600,"height":2132,"mime-type":"image\/jpeg","filesize":209284,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/db16539f-b961-4941-90ba-0117d6546c17-4-600x2132.jpg"},"post-featured-image":{"file":"db16539f-b961-4941-90ba-0117d6546c17-4-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":142430,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/db16539f-b961-4941-90ba-0117d6546c17-4-1240x720.jpg"}},"image_meta":{"aperture":"11","credit":"Christian Ribas","camera":"Canon EOS 5D Mark IV","caption":"","created_timestamp":"1749828521","copyright":"www.christianribas.es","focal_length":"19","iso":"200","shutter_speed":"0.16666666666667","title":"","orientation":"1","keywords":[]},"original_image":"db16539f-b961-4941-90ba-0117d6546c17-4.jpg","ID":"913174","name":"db16539f-b961-4941-90ba-0117d6546c17-4-scaled.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2022\/07\/db16539f-b961-4941-90ba-0117d6546c17-4-scaled.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/db16539f-b961-4941-90ba-0117d6546c17-4-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/db16539f-b961-4941-90ba-0117d6546c17-4-scaled.jpg","title":"db16539f-b961-4941-90ba-0117d6546c17-4","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/db16539f-b961-4941-90ba-0117d6546c17-4-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/db16539f-b961-4941-90ba-0117d6546c17-4-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/db16539f-b961-4941-90ba-0117d6546c17-4-210x210.jpg 210w"},{"width":150,"height":150,"file":"2022\/07\/fa7e78dc-14d8-40b6-9f5d-689233725e5c-4-scaled.jpg","filesize":422130,"sizes":{"medium":{"file":"fa7e78dc-14d8-40b6-9f5d-689233725e5c-4-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":26330,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/fa7e78dc-14d8-40b6-9f5d-689233725e5c-4-300x200.jpg"},"large":{"file":"fa7e78dc-14d8-40b6-9f5d-689233725e5c-4-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":98717,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/fa7e78dc-14d8-40b6-9f5d-689233725e5c-4-1024x683.jpg"},"thumbnail":{"file":"fa7e78dc-14d8-40b6-9f5d-689233725e5c-4-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":20707,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/fa7e78dc-14d8-40b6-9f5d-689233725e5c-4-150x150.jpg"},"medium_large":{"file":"fa7e78dc-14d8-40b6-9f5d-689233725e5c-4-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":66439,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/fa7e78dc-14d8-40b6-9f5d-689233725e5c-4-768x512.jpg"},"1536x1536":{"file":"fa7e78dc-14d8-40b6-9f5d-689233725e5c-4-1536x1024.jpg","width":1536,"height":1024,"mime-type":"image\/jpeg","filesize":181652,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/fa7e78dc-14d8-40b6-9f5d-689233725e5c-4-1536x1024.jpg"},"2048x2048":{"file":"fa7e78dc-14d8-40b6-9f5d-689233725e5c-4-2048x1365.jpg","width":2048,"height":1365,"mime-type":"image\/jpeg","filesize":291349,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/fa7e78dc-14d8-40b6-9f5d-689233725e5c-4-2048x1365.jpg"},"square":{"file":"fa7e78dc-14d8-40b6-9f5d-689233725e5c-4-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":46735,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/fa7e78dc-14d8-40b6-9f5d-689233725e5c-4-450x450.jpg"},"property-large-image":{"file":"fa7e78dc-14d8-40b6-9f5d-689233725e5c-4-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":120510,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/fa7e78dc-14d8-40b6-9f5d-689233725e5c-4-1170x780.jpg"},"post-thumbnail":{"file":"fa7e78dc-14d8-40b6-9f5d-689233725e5c-4-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":19083,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/fa7e78dc-14d8-40b6-9f5d-689233725e5c-4-150x100.jpg"},"modern-property-child-slider":{"file":"fa7e78dc-14d8-40b6-9f5d-689233725e5c-4-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":64220,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/fa7e78dc-14d8-40b6-9f5d-689233725e5c-4-680x510.jpg"},"property-thumb-image":{"file":"fa7e78dc-14d8-40b6-9f5d-689233725e5c-4-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":39976,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/fa7e78dc-14d8-40b6-9f5d-689233725e5c-4-488x326.jpg"},"property-detail-video-image":{"file":"fa7e78dc-14d8-40b6-9f5d-689233725e5c-4-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":59379,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/fa7e78dc-14d8-40b6-9f5d-689233725e5c-4-818x417.jpg"},"agent-image":{"file":"fa7e78dc-14d8-40b6-9f5d-689233725e5c-4-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":24468,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/fa7e78dc-14d8-40b6-9f5d-689233725e5c-4-210x210.jpg"},"partners-logo":{"file":"fa7e78dc-14d8-40b6-9f5d-689233725e5c-4-600x2132.jpg","width":600,"height":2132,"mime-type":"image\/jpeg","filesize":170867,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/fa7e78dc-14d8-40b6-9f5d-689233725e5c-4-600x2132.jpg"},"post-featured-image":{"file":"fa7e78dc-14d8-40b6-9f5d-689233725e5c-4-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":115720,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/fa7e78dc-14d8-40b6-9f5d-689233725e5c-4-1240x720.jpg"}},"image_meta":{"aperture":"11","credit":"Christian Ribas","camera":"Canon EOS 5D Mark IV","caption":"","created_timestamp":"1749827382","copyright":"www.christianribas.es","focal_length":"17","iso":"400","shutter_speed":"0.4","title":"","orientation":"1","keywords":[]},"original_image":"fa7e78dc-14d8-40b6-9f5d-689233725e5c-4.jpg","ID":"913178","name":"fa7e78dc-14d8-40b6-9f5d-689233725e5c-4-scaled.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2022\/07\/fa7e78dc-14d8-40b6-9f5d-689233725e5c-4-scaled.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/fa7e78dc-14d8-40b6-9f5d-689233725e5c-4-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/fa7e78dc-14d8-40b6-9f5d-689233725e5c-4-scaled.jpg","title":"fa7e78dc-14d8-40b6-9f5d-689233725e5c-4","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/fa7e78dc-14d8-40b6-9f5d-689233725e5c-4-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/fa7e78dc-14d8-40b6-9f5d-689233725e5c-4-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/fa7e78dc-14d8-40b6-9f5d-689233725e5c-4-210x210.jpg 210w"},{"width":150,"height":150,"file":"2022\/07\/4faffcc4-69bb-4617-94bd-ef6ff2aa91f3-4-scaled.jpg","filesize":570626,"sizes":{"medium":{"file":"4faffcc4-69bb-4617-94bd-ef6ff2aa91f3-4-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":28169,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/4faffcc4-69bb-4617-94bd-ef6ff2aa91f3-4-300x200.jpg"},"large":{"file":"4faffcc4-69bb-4617-94bd-ef6ff2aa91f3-4-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":126148,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/4faffcc4-69bb-4617-94bd-ef6ff2aa91f3-4-1024x683.jpg"},"thumbnail":{"file":"4faffcc4-69bb-4617-94bd-ef6ff2aa91f3-4-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":21061,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/4faffcc4-69bb-4617-94bd-ef6ff2aa91f3-4-150x150.jpg"},"medium_large":{"file":"4faffcc4-69bb-4617-94bd-ef6ff2aa91f3-4-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":81726,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/4faffcc4-69bb-4617-94bd-ef6ff2aa91f3-4-768x512.jpg"},"1536x1536":{"file":"4faffcc4-69bb-4617-94bd-ef6ff2aa91f3-4-1536x1024.jpg","width":1536,"height":1024,"mime-type":"image\/jpeg","filesize":242220,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/4faffcc4-69bb-4617-94bd-ef6ff2aa91f3-4-1536x1024.jpg"},"2048x2048":{"file":"4faffcc4-69bb-4617-94bd-ef6ff2aa91f3-4-2048x1365.jpg","width":2048,"height":1365,"mime-type":"image\/jpeg","filesize":393994,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/4faffcc4-69bb-4617-94bd-ef6ff2aa91f3-4-2048x1365.jpg"},"square":{"file":"4faffcc4-69bb-4617-94bd-ef6ff2aa91f3-4-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":51482,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/4faffcc4-69bb-4617-94bd-ef6ff2aa91f3-4-450x450.jpg"},"property-large-image":{"file":"4faffcc4-69bb-4617-94bd-ef6ff2aa91f3-4-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":155642,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/4faffcc4-69bb-4617-94bd-ef6ff2aa91f3-4-1170x780.jpg"},"post-thumbnail":{"file":"4faffcc4-69bb-4617-94bd-ef6ff2aa91f3-4-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":19522,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/4faffcc4-69bb-4617-94bd-ef6ff2aa91f3-4-150x100.jpg"},"modern-property-child-slider":{"file":"4faffcc4-69bb-4617-94bd-ef6ff2aa91f3-4-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":74383,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/4faffcc4-69bb-4617-94bd-ef6ff2aa91f3-4-680x510.jpg"},"property-thumb-image":{"file":"4faffcc4-69bb-4617-94bd-ef6ff2aa91f3-4-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":45195,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/4faffcc4-69bb-4617-94bd-ef6ff2aa91f3-4-488x326.jpg"},"property-detail-video-image":{"file":"4faffcc4-69bb-4617-94bd-ef6ff2aa91f3-4-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":74785,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/4faffcc4-69bb-4617-94bd-ef6ff2aa91f3-4-818x417.jpg"},"agent-image":{"file":"4faffcc4-69bb-4617-94bd-ef6ff2aa91f3-4-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":25407,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/4faffcc4-69bb-4617-94bd-ef6ff2aa91f3-4-210x210.jpg"},"partners-logo":{"file":"4faffcc4-69bb-4617-94bd-ef6ff2aa91f3-4-600x2132.jpg","width":600,"height":2132,"mime-type":"image\/jpeg","filesize":227140,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/4faffcc4-69bb-4617-94bd-ef6ff2aa91f3-4-600x2132.jpg"},"post-featured-image":{"file":"4faffcc4-69bb-4617-94bd-ef6ff2aa91f3-4-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":153658,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/4faffcc4-69bb-4617-94bd-ef6ff2aa91f3-4-1240x720.jpg"}},"image_meta":{"aperture":"10","credit":"Christian Ribas","camera":"Canon EOS 5D Mark IV","caption":"","created_timestamp":"1749828762","copyright":"www.christianribas.es","focal_length":"17","iso":"100","shutter_speed":"0.033333333333333","title":"","orientation":"1","keywords":[]},"original_image":"4faffcc4-69bb-4617-94bd-ef6ff2aa91f3-4.jpg","ID":"913182","name":"4faffcc4-69bb-4617-94bd-ef6ff2aa91f3-4-scaled.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2022\/07\/4faffcc4-69bb-4617-94bd-ef6ff2aa91f3-4-scaled.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/4faffcc4-69bb-4617-94bd-ef6ff2aa91f3-4-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/4faffcc4-69bb-4617-94bd-ef6ff2aa91f3-4-scaled.jpg","title":"4faffcc4-69bb-4617-94bd-ef6ff2aa91f3-4","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/4faffcc4-69bb-4617-94bd-ef6ff2aa91f3-4-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/4faffcc4-69bb-4617-94bd-ef6ff2aa91f3-4-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/4faffcc4-69bb-4617-94bd-ef6ff2aa91f3-4-210x210.jpg 210w"},{"width":150,"height":150,"file":"2022\/07\/af1146d7-0ca4-4b77-a40a-eee7b1db7c21-4-scaled.jpg","filesize":477004,"sizes":{"medium":{"file":"af1146d7-0ca4-4b77-a40a-eee7b1db7c21-4-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":28419,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/af1146d7-0ca4-4b77-a40a-eee7b1db7c21-4-300x200.jpg"},"large":{"file":"af1146d7-0ca4-4b77-a40a-eee7b1db7c21-4-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":111905,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/af1146d7-0ca4-4b77-a40a-eee7b1db7c21-4-1024x683.jpg"},"thumbnail":{"file":"af1146d7-0ca4-4b77-a40a-eee7b1db7c21-4-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":20937,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/af1146d7-0ca4-4b77-a40a-eee7b1db7c21-4-150x150.jpg"},"medium_large":{"file":"af1146d7-0ca4-4b77-a40a-eee7b1db7c21-4-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":75089,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/af1146d7-0ca4-4b77-a40a-eee7b1db7c21-4-768x512.jpg"},"1536x1536":{"file":"af1146d7-0ca4-4b77-a40a-eee7b1db7c21-4-1536x1024.jpg","width":1536,"height":1024,"mime-type":"image\/jpeg","filesize":204348,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/af1146d7-0ca4-4b77-a40a-eee7b1db7c21-4-1536x1024.jpg"},"2048x2048":{"file":"af1146d7-0ca4-4b77-a40a-eee7b1db7c21-4-2048x1365.jpg","width":2048,"height":1365,"mime-type":"image\/jpeg","filesize":326836,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/af1146d7-0ca4-4b77-a40a-eee7b1db7c21-4-2048x1365.jpg"},"square":{"file":"af1146d7-0ca4-4b77-a40a-eee7b1db7c21-4-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":48112,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/af1146d7-0ca4-4b77-a40a-eee7b1db7c21-4-450x450.jpg"},"property-large-image":{"file":"af1146d7-0ca4-4b77-a40a-eee7b1db7c21-4-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":135416,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/af1146d7-0ca4-4b77-a40a-eee7b1db7c21-4-1170x780.jpg"},"post-thumbnail":{"file":"af1146d7-0ca4-4b77-a40a-eee7b1db7c21-4-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":19885,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/af1146d7-0ca4-4b77-a40a-eee7b1db7c21-4-150x100.jpg"},"modern-property-child-slider":{"file":"af1146d7-0ca4-4b77-a40a-eee7b1db7c21-4-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":71214,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/af1146d7-0ca4-4b77-a40a-eee7b1db7c21-4-680x510.jpg"},"property-thumb-image":{"file":"af1146d7-0ca4-4b77-a40a-eee7b1db7c21-4-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":44424,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/af1146d7-0ca4-4b77-a40a-eee7b1db7c21-4-488x326.jpg"},"property-detail-video-image":{"file":"af1146d7-0ca4-4b77-a40a-eee7b1db7c21-4-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":66281,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/af1146d7-0ca4-4b77-a40a-eee7b1db7c21-4-818x417.jpg"},"agent-image":{"file":"af1146d7-0ca4-4b77-a40a-eee7b1db7c21-4-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":25153,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/af1146d7-0ca4-4b77-a40a-eee7b1db7c21-4-210x210.jpg"},"partners-logo":{"file":"af1146d7-0ca4-4b77-a40a-eee7b1db7c21-4-600x2132.jpg","width":600,"height":2132,"mime-type":"image\/jpeg","filesize":162709,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/af1146d7-0ca4-4b77-a40a-eee7b1db7c21-4-600x2132.jpg"},"post-featured-image":{"file":"af1146d7-0ca4-4b77-a40a-eee7b1db7c21-4-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":130168,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/af1146d7-0ca4-4b77-a40a-eee7b1db7c21-4-1240x720.jpg"}},"image_meta":{"aperture":"11","credit":"Christian Ribas","camera":"Canon EOS 5D Mark IV","caption":"","created_timestamp":"1749827107","copyright":"www.christianribas.es","focal_length":"17","iso":"400","shutter_speed":"0.3","title":"","orientation":"1","keywords":[]},"original_image":"af1146d7-0ca4-4b77-a40a-eee7b1db7c21-4.jpg","ID":"913186","name":"af1146d7-0ca4-4b77-a40a-eee7b1db7c21-4-scaled.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2022\/07\/af1146d7-0ca4-4b77-a40a-eee7b1db7c21-4-scaled.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/af1146d7-0ca4-4b77-a40a-eee7b1db7c21-4-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/af1146d7-0ca4-4b77-a40a-eee7b1db7c21-4-scaled.jpg","title":"af1146d7-0ca4-4b77-a40a-eee7b1db7c21-4","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/af1146d7-0ca4-4b77-a40a-eee7b1db7c21-4-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/af1146d7-0ca4-4b77-a40a-eee7b1db7c21-4-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/af1146d7-0ca4-4b77-a40a-eee7b1db7c21-4-210x210.jpg 210w"},{"width":150,"height":150,"file":"2022\/07\/f92c3093-7279-4c35-bc8d-95e2f2e122d7-4-scaled.jpg","filesize":1682239,"sizes":{"medium":{"file":"f92c3093-7279-4c35-bc8d-95e2f2e122d7-4-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":44367,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/f92c3093-7279-4c35-bc8d-95e2f2e122d7-4-300x200.jpg"},"large":{"file":"f92c3093-7279-4c35-bc8d-95e2f2e122d7-4-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":317305,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/f92c3093-7279-4c35-bc8d-95e2f2e122d7-4-1024x683.jpg"},"thumbnail":{"file":"f92c3093-7279-4c35-bc8d-95e2f2e122d7-4-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":26673,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/f92c3093-7279-4c35-bc8d-95e2f2e122d7-4-150x150.jpg"},"medium_large":{"file":"f92c3093-7279-4c35-bc8d-95e2f2e122d7-4-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":189649,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/f92c3093-7279-4c35-bc8d-95e2f2e122d7-4-768x512.jpg"},"1536x1536":{"file":"f92c3093-7279-4c35-bc8d-95e2f2e122d7-4-1536x1024.jpg","width":1536,"height":1024,"mime-type":"image\/jpeg","filesize":667453,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/f92c3093-7279-4c35-bc8d-95e2f2e122d7-4-1536x1024.jpg"},"2048x2048":{"file":"f92c3093-7279-4c35-bc8d-95e2f2e122d7-4-2048x1365.jpg","width":2048,"height":1365,"mime-type":"image\/jpeg","filesize":1132504,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/f92c3093-7279-4c35-bc8d-95e2f2e122d7-4-2048x1365.jpg"},"square":{"file":"f92c3093-7279-4c35-bc8d-95e2f2e122d7-4-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":107422,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/f92c3093-7279-4c35-bc8d-95e2f2e122d7-4-450x450.jpg"},"property-large-image":{"file":"f92c3093-7279-4c35-bc8d-95e2f2e122d7-4-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":405359,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/f92c3093-7279-4c35-bc8d-95e2f2e122d7-4-1170x780.jpg"},"post-thumbnail":{"file":"f92c3093-7279-4c35-bc8d-95e2f2e122d7-4-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":23244,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/f92c3093-7279-4c35-bc8d-95e2f2e122d7-4-150x100.jpg"},"modern-property-child-slider":{"file":"f92c3093-7279-4c35-bc8d-95e2f2e122d7-4-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":170094,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/f92c3093-7279-4c35-bc8d-95e2f2e122d7-4-680x510.jpg"},"property-thumb-image":{"file":"f92c3093-7279-4c35-bc8d-95e2f2e122d7-4-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":88998,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/f92c3093-7279-4c35-bc8d-95e2f2e122d7-4-488x326.jpg"},"property-detail-video-image":{"file":"f92c3093-7279-4c35-bc8d-95e2f2e122d7-4-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":169965,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/f92c3093-7279-4c35-bc8d-95e2f2e122d7-4-818x417.jpg"},"agent-image":{"file":"f92c3093-7279-4c35-bc8d-95e2f2e122d7-4-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":37012,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/f92c3093-7279-4c35-bc8d-95e2f2e122d7-4-210x210.jpg"},"partners-logo":{"file":"f92c3093-7279-4c35-bc8d-95e2f2e122d7-4-600x2132.jpg","width":600,"height":2132,"mime-type":"image\/jpeg","filesize":562894,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/f92c3093-7279-4c35-bc8d-95e2f2e122d7-4-600x2132.jpg"},"post-featured-image":{"file":"f92c3093-7279-4c35-bc8d-95e2f2e122d7-4-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":397677,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/f92c3093-7279-4c35-bc8d-95e2f2e122d7-4-1240x720.jpg"}},"image_meta":{"aperture":"11","credit":"Christian Ribas","camera":"Canon EOS 5D Mark IV","caption":"","created_timestamp":"1749826532","copyright":"www.christianribas.es","focal_length":"17","iso":"400","shutter_speed":"0.0125","title":"","orientation":"1","keywords":[]},"original_image":"f92c3093-7279-4c35-bc8d-95e2f2e122d7-4.jpg","ID":"913190","name":"f92c3093-7279-4c35-bc8d-95e2f2e122d7-4-scaled.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2022\/07\/f92c3093-7279-4c35-bc8d-95e2f2e122d7-4-scaled.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/f92c3093-7279-4c35-bc8d-95e2f2e122d7-4-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/f92c3093-7279-4c35-bc8d-95e2f2e122d7-4-scaled.jpg","title":"f92c3093-7279-4c35-bc8d-95e2f2e122d7-4","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/f92c3093-7279-4c35-bc8d-95e2f2e122d7-4-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/f92c3093-7279-4c35-bc8d-95e2f2e122d7-4-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/f92c3093-7279-4c35-bc8d-95e2f2e122d7-4-210x210.jpg 210w"},{"width":150,"height":150,"file":"2022\/07\/582edeeb-52fd-460c-857a-ec838113d15e-4-scaled.jpg","filesize":441949,"sizes":{"medium":{"file":"582edeeb-52fd-460c-857a-ec838113d15e-4-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":25406,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/582edeeb-52fd-460c-857a-ec838113d15e-4-300x200.jpg"},"large":{"file":"582edeeb-52fd-460c-857a-ec838113d15e-4-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":89528,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/582edeeb-52fd-460c-857a-ec838113d15e-4-1024x683.jpg"},"thumbnail":{"file":"582edeeb-52fd-460c-857a-ec838113d15e-4-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":20637,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/582edeeb-52fd-460c-857a-ec838113d15e-4-150x150.jpg"},"medium_large":{"file":"582edeeb-52fd-460c-857a-ec838113d15e-4-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":60771,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/582edeeb-52fd-460c-857a-ec838113d15e-4-768x512.jpg"},"1536x1536":{"file":"582edeeb-52fd-460c-857a-ec838113d15e-4-1536x1024.jpg","width":1536,"height":1024,"mime-type":"image\/jpeg","filesize":166640,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/582edeeb-52fd-460c-857a-ec838113d15e-4-1536x1024.jpg"},"2048x2048":{"file":"582edeeb-52fd-460c-857a-ec838113d15e-4-2048x1365.jpg","width":2048,"height":1365,"mime-type":"image\/jpeg","filesize":281420,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/582edeeb-52fd-460c-857a-ec838113d15e-4-2048x1365.jpg"},"square":{"file":"582edeeb-52fd-460c-857a-ec838113d15e-4-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":45390,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/582edeeb-52fd-460c-857a-ec838113d15e-4-450x450.jpg"},"property-large-image":{"file":"582edeeb-52fd-460c-857a-ec838113d15e-4-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":108790,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/582edeeb-52fd-460c-857a-ec838113d15e-4-1170x780.jpg"},"post-thumbnail":{"file":"582edeeb-52fd-460c-857a-ec838113d15e-4-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":18835,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/582edeeb-52fd-460c-857a-ec838113d15e-4-150x100.jpg"},"modern-property-child-slider":{"file":"582edeeb-52fd-460c-857a-ec838113d15e-4-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":58523,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/582edeeb-52fd-460c-857a-ec838113d15e-4-680x510.jpg"},"property-thumb-image":{"file":"582edeeb-52fd-460c-857a-ec838113d15e-4-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":37396,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/582edeeb-52fd-460c-857a-ec838113d15e-4-488x326.jpg"},"property-detail-video-image":{"file":"582edeeb-52fd-460c-857a-ec838113d15e-4-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":55982,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/582edeeb-52fd-460c-857a-ec838113d15e-4-818x417.jpg"},"agent-image":{"file":"582edeeb-52fd-460c-857a-ec838113d15e-4-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":24424,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/582edeeb-52fd-460c-857a-ec838113d15e-4-210x210.jpg"},"partners-logo":{"file":"582edeeb-52fd-460c-857a-ec838113d15e-4-600x2132.jpg","width":600,"height":2132,"mime-type":"image\/jpeg","filesize":217254,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/582edeeb-52fd-460c-857a-ec838113d15e-4-600x2132.jpg"},"post-featured-image":{"file":"582edeeb-52fd-460c-857a-ec838113d15e-4-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":106487,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/582edeeb-52fd-460c-857a-ec838113d15e-4-1240x720.jpg"}},"image_meta":{"aperture":"8","credit":"Christian Ribas","camera":"Canon EOS 5D Mark IV","caption":"","created_timestamp":"1749826584","copyright":"www.christianribas.es","focal_length":"17","iso":"3200","shutter_speed":"0.033333333333333","title":"","orientation":"1","keywords":[]},"original_image":"582edeeb-52fd-460c-857a-ec838113d15e-4.jpg","ID":"913194","name":"582edeeb-52fd-460c-857a-ec838113d15e-4-scaled.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2022\/07\/582edeeb-52fd-460c-857a-ec838113d15e-4-scaled.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/582edeeb-52fd-460c-857a-ec838113d15e-4-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/582edeeb-52fd-460c-857a-ec838113d15e-4-scaled.jpg","title":"582edeeb-52fd-460c-857a-ec838113d15e-4","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/582edeeb-52fd-460c-857a-ec838113d15e-4-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/582edeeb-52fd-460c-857a-ec838113d15e-4-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/582edeeb-52fd-460c-857a-ec838113d15e-4-210x210.jpg 210w"},{"width":150,"height":150,"file":"2022\/07\/a6ed0081-6bf2-401e-b9ce-47cfba0b5cbf-4-scaled.jpg","filesize":553991,"sizes":{"medium":{"file":"a6ed0081-6bf2-401e-b9ce-47cfba0b5cbf-4-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":27106,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/a6ed0081-6bf2-401e-b9ce-47cfba0b5cbf-4-300x200.jpg"},"large":{"file":"a6ed0081-6bf2-401e-b9ce-47cfba0b5cbf-4-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":102971,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/a6ed0081-6bf2-401e-b9ce-47cfba0b5cbf-4-1024x683.jpg"},"thumbnail":{"file":"a6ed0081-6bf2-401e-b9ce-47cfba0b5cbf-4-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":21143,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/a6ed0081-6bf2-401e-b9ce-47cfba0b5cbf-4-150x150.jpg"},"medium_large":{"file":"a6ed0081-6bf2-401e-b9ce-47cfba0b5cbf-4-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":69482,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/a6ed0081-6bf2-401e-b9ce-47cfba0b5cbf-4-768x512.jpg"},"1536x1536":{"file":"a6ed0081-6bf2-401e-b9ce-47cfba0b5cbf-4-1536x1024.jpg","width":1536,"height":1024,"mime-type":"image\/jpeg","filesize":194534,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/a6ed0081-6bf2-401e-b9ce-47cfba0b5cbf-4-1536x1024.jpg"},"2048x2048":{"file":"a6ed0081-6bf2-401e-b9ce-47cfba0b5cbf-4-2048x1365.jpg","width":2048,"height":1365,"mime-type":"image\/jpeg","filesize":340716,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/a6ed0081-6bf2-401e-b9ce-47cfba0b5cbf-4-2048x1365.jpg"},"square":{"file":"a6ed0081-6bf2-401e-b9ce-47cfba0b5cbf-4-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":50072,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/a6ed0081-6bf2-401e-b9ce-47cfba0b5cbf-4-450x450.jpg"},"property-large-image":{"file":"a6ed0081-6bf2-401e-b9ce-47cfba0b5cbf-4-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":124645,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/a6ed0081-6bf2-401e-b9ce-47cfba0b5cbf-4-1170x780.jpg"},"post-thumbnail":{"file":"a6ed0081-6bf2-401e-b9ce-47cfba0b5cbf-4-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":19236,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/a6ed0081-6bf2-401e-b9ce-47cfba0b5cbf-4-150x100.jpg"},"modern-property-child-slider":{"file":"a6ed0081-6bf2-401e-b9ce-47cfba0b5cbf-4-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":65792,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/a6ed0081-6bf2-401e-b9ce-47cfba0b5cbf-4-680x510.jpg"},"property-thumb-image":{"file":"a6ed0081-6bf2-401e-b9ce-47cfba0b5cbf-4-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":41263,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/a6ed0081-6bf2-401e-b9ce-47cfba0b5cbf-4-488x326.jpg"},"property-detail-video-image":{"file":"a6ed0081-6bf2-401e-b9ce-47cfba0b5cbf-4-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":64679,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/a6ed0081-6bf2-401e-b9ce-47cfba0b5cbf-4-818x417.jpg"},"agent-image":{"file":"a6ed0081-6bf2-401e-b9ce-47cfba0b5cbf-4-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":25494,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/a6ed0081-6bf2-401e-b9ce-47cfba0b5cbf-4-210x210.jpg"},"partners-logo":{"file":"a6ed0081-6bf2-401e-b9ce-47cfba0b5cbf-4-600x2132.jpg","width":600,"height":2132,"mime-type":"image\/jpeg","filesize":238072,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/a6ed0081-6bf2-401e-b9ce-47cfba0b5cbf-4-600x2132.jpg"},"post-featured-image":{"file":"a6ed0081-6bf2-401e-b9ce-47cfba0b5cbf-4-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":124223,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/a6ed0081-6bf2-401e-b9ce-47cfba0b5cbf-4-1240x720.jpg"}},"image_meta":{"aperture":"6.3","credit":"Christian Ribas","camera":"Canon EOS 5D Mark IV","caption":"","created_timestamp":"1749826592","copyright":"www.christianribas.es","focal_length":"17","iso":"3200","shutter_speed":"0.033333333333333","title":"","orientation":"1","keywords":[]},"original_image":"a6ed0081-6bf2-401e-b9ce-47cfba0b5cbf-4.jpg","ID":"913198","name":"a6ed0081-6bf2-401e-b9ce-47cfba0b5cbf-4-scaled.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2022\/07\/a6ed0081-6bf2-401e-b9ce-47cfba0b5cbf-4-scaled.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/a6ed0081-6bf2-401e-b9ce-47cfba0b5cbf-4-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/a6ed0081-6bf2-401e-b9ce-47cfba0b5cbf-4-scaled.jpg","title":"a6ed0081-6bf2-401e-b9ce-47cfba0b5cbf-4","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/a6ed0081-6bf2-401e-b9ce-47cfba0b5cbf-4-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/a6ed0081-6bf2-401e-b9ce-47cfba0b5cbf-4-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/a6ed0081-6bf2-401e-b9ce-47cfba0b5cbf-4-210x210.jpg 210w"},{"width":150,"height":150,"file":"2022\/07\/9d90d18a-f1ea-4707-ae41-8f8dca69763c-4-scaled.jpg","filesize":461859,"sizes":{"medium":{"file":"9d90d18a-f1ea-4707-ae41-8f8dca69763c-4-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":25804,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/9d90d18a-f1ea-4707-ae41-8f8dca69763c-4-300x200.jpg"},"large":{"file":"9d90d18a-f1ea-4707-ae41-8f8dca69763c-4-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":99467,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/9d90d18a-f1ea-4707-ae41-8f8dca69763c-4-1024x683.jpg"},"thumbnail":{"file":"9d90d18a-f1ea-4707-ae41-8f8dca69763c-4-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":20299,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/9d90d18a-f1ea-4707-ae41-8f8dca69763c-4-150x150.jpg"},"medium_large":{"file":"9d90d18a-f1ea-4707-ae41-8f8dca69763c-4-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":66093,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/9d90d18a-f1ea-4707-ae41-8f8dca69763c-4-768x512.jpg"},"1536x1536":{"file":"9d90d18a-f1ea-4707-ae41-8f8dca69763c-4-1536x1024.jpg","width":1536,"height":1024,"mime-type":"image\/jpeg","filesize":187902,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/9d90d18a-f1ea-4707-ae41-8f8dca69763c-4-1536x1024.jpg"},"2048x2048":{"file":"9d90d18a-f1ea-4707-ae41-8f8dca69763c-4-2048x1365.jpg","width":2048,"height":1365,"mime-type":"image\/jpeg","filesize":310385,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/9d90d18a-f1ea-4707-ae41-8f8dca69763c-4-2048x1365.jpg"},"square":{"file":"9d90d18a-f1ea-4707-ae41-8f8dca69763c-4-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":47392,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/9d90d18a-f1ea-4707-ae41-8f8dca69763c-4-450x450.jpg"},"property-large-image":{"file":"9d90d18a-f1ea-4707-ae41-8f8dca69763c-4-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":121451,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/9d90d18a-f1ea-4707-ae41-8f8dca69763c-4-1170x780.jpg"},"post-thumbnail":{"file":"9d90d18a-f1ea-4707-ae41-8f8dca69763c-4-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":18796,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/9d90d18a-f1ea-4707-ae41-8f8dca69763c-4-150x100.jpg"},"modern-property-child-slider":{"file":"9d90d18a-f1ea-4707-ae41-8f8dca69763c-4-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":63024,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/9d90d18a-f1ea-4707-ae41-8f8dca69763c-4-680x510.jpg"},"property-thumb-image":{"file":"9d90d18a-f1ea-4707-ae41-8f8dca69763c-4-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":38930,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/9d90d18a-f1ea-4707-ae41-8f8dca69763c-4-488x326.jpg"},"property-detail-video-image":{"file":"9d90d18a-f1ea-4707-ae41-8f8dca69763c-4-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":63261,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/9d90d18a-f1ea-4707-ae41-8f8dca69763c-4-818x417.jpg"},"agent-image":{"file":"9d90d18a-f1ea-4707-ae41-8f8dca69763c-4-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":24227,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/9d90d18a-f1ea-4707-ae41-8f8dca69763c-4-210x210.jpg"},"partners-logo":{"file":"9d90d18a-f1ea-4707-ae41-8f8dca69763c-4-600x2132.jpg","width":600,"height":2132,"mime-type":"image\/jpeg","filesize":205208,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/9d90d18a-f1ea-4707-ae41-8f8dca69763c-4-600x2132.jpg"},"post-featured-image":{"file":"9d90d18a-f1ea-4707-ae41-8f8dca69763c-4-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":121318,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/9d90d18a-f1ea-4707-ae41-8f8dca69763c-4-1240x720.jpg"}},"image_meta":{"aperture":"11","credit":"Christian Ribas","camera":"Canon EOS 5D Mark IV","caption":"","created_timestamp":"1749826907","copyright":"www.christianribas.es","focal_length":"17","iso":"400","shutter_speed":"0.4","title":"","orientation":"1","keywords":[]},"original_image":"9d90d18a-f1ea-4707-ae41-8f8dca69763c-4.jpg","ID":"913202","name":"9d90d18a-f1ea-4707-ae41-8f8dca69763c-4-scaled.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2022\/07\/9d90d18a-f1ea-4707-ae41-8f8dca69763c-4-scaled.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/9d90d18a-f1ea-4707-ae41-8f8dca69763c-4-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/9d90d18a-f1ea-4707-ae41-8f8dca69763c-4-scaled.jpg","title":"9d90d18a-f1ea-4707-ae41-8f8dca69763c-4","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/9d90d18a-f1ea-4707-ae41-8f8dca69763c-4-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/9d90d18a-f1ea-4707-ae41-8f8dca69763c-4-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/9d90d18a-f1ea-4707-ae41-8f8dca69763c-4-210x210.jpg 210w"},{"width":150,"height":150,"file":"2022\/07\/e5fe4221-6985-476f-9d8a-98c831a22093-4-scaled.jpg","filesize":357621,"sizes":{"medium":{"file":"e5fe4221-6985-476f-9d8a-98c831a22093-4-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":23709,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e5fe4221-6985-476f-9d8a-98c831a22093-4-300x200.jpg"},"large":{"file":"e5fe4221-6985-476f-9d8a-98c831a22093-4-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":78855,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e5fe4221-6985-476f-9d8a-98c831a22093-4-1024x683.jpg"},"thumbnail":{"file":"e5fe4221-6985-476f-9d8a-98c831a22093-4-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":19649,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e5fe4221-6985-476f-9d8a-98c831a22093-4-150x150.jpg"},"medium_large":{"file":"e5fe4221-6985-476f-9d8a-98c831a22093-4-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":54270,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e5fe4221-6985-476f-9d8a-98c831a22093-4-768x512.jpg"},"1536x1536":{"file":"e5fe4221-6985-476f-9d8a-98c831a22093-4-1536x1024.jpg","width":1536,"height":1024,"mime-type":"image\/jpeg","filesize":145289,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e5fe4221-6985-476f-9d8a-98c831a22093-4-1536x1024.jpg"},"2048x2048":{"file":"e5fe4221-6985-476f-9d8a-98c831a22093-4-2048x1365.jpg","width":2048,"height":1365,"mime-type":"image\/jpeg","filesize":239051,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e5fe4221-6985-476f-9d8a-98c831a22093-4-2048x1365.jpg"},"square":{"file":"e5fe4221-6985-476f-9d8a-98c831a22093-4-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":40944,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e5fe4221-6985-476f-9d8a-98c831a22093-4-450x450.jpg"},"property-large-image":{"file":"e5fe4221-6985-476f-9d8a-98c831a22093-4-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":95854,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e5fe4221-6985-476f-9d8a-98c831a22093-4-1170x780.jpg"},"post-thumbnail":{"file":"e5fe4221-6985-476f-9d8a-98c831a22093-4-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":18289,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e5fe4221-6985-476f-9d8a-98c831a22093-4-150x100.jpg"},"modern-property-child-slider":{"file":"e5fe4221-6985-476f-9d8a-98c831a22093-4-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":51906,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e5fe4221-6985-476f-9d8a-98c831a22093-4-680x510.jpg"},"property-thumb-image":{"file":"e5fe4221-6985-476f-9d8a-98c831a22093-4-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":34135,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e5fe4221-6985-476f-9d8a-98c831a22093-4-488x326.jpg"},"property-detail-video-image":{"file":"e5fe4221-6985-476f-9d8a-98c831a22093-4-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":50033,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e5fe4221-6985-476f-9d8a-98c831a22093-4-818x417.jpg"},"agent-image":{"file":"e5fe4221-6985-476f-9d8a-98c831a22093-4-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":22902,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e5fe4221-6985-476f-9d8a-98c831a22093-4-210x210.jpg"},"partners-logo":{"file":"e5fe4221-6985-476f-9d8a-98c831a22093-4-600x2132.jpg","width":600,"height":2132,"mime-type":"image\/jpeg","filesize":132868,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e5fe4221-6985-476f-9d8a-98c831a22093-4-600x2132.jpg"},"post-featured-image":{"file":"e5fe4221-6985-476f-9d8a-98c831a22093-4-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":93124,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e5fe4221-6985-476f-9d8a-98c831a22093-4-1240x720.jpg"}},"image_meta":{"aperture":"11","credit":"Christian Ribas","camera":"Canon EOS 5D Mark IV","caption":"","created_timestamp":"1749827035","copyright":"www.christianribas.es","focal_length":"19","iso":"400","shutter_speed":"0.4","title":"","orientation":"1","keywords":[]},"original_image":"e5fe4221-6985-476f-9d8a-98c831a22093-4.jpg","ID":"913206","name":"e5fe4221-6985-476f-9d8a-98c831a22093-4-scaled.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2022\/07\/e5fe4221-6985-476f-9d8a-98c831a22093-4-scaled.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e5fe4221-6985-476f-9d8a-98c831a22093-4-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e5fe4221-6985-476f-9d8a-98c831a22093-4-scaled.jpg","title":"e5fe4221-6985-476f-9d8a-98c831a22093-4","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e5fe4221-6985-476f-9d8a-98c831a22093-4-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e5fe4221-6985-476f-9d8a-98c831a22093-4-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e5fe4221-6985-476f-9d8a-98c831a22093-4-210x210.jpg 210w"},{"width":150,"height":150,"file":"2022\/07\/c0393680-d35b-450d-ad1e-4c1aa3ae237f-4-scaled.jpg","filesize":417185,"sizes":{"medium":{"file":"c0393680-d35b-450d-ad1e-4c1aa3ae237f-4-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":26794,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c0393680-d35b-450d-ad1e-4c1aa3ae237f-4-300x200.jpg"},"large":{"file":"c0393680-d35b-450d-ad1e-4c1aa3ae237f-4-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":97802,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c0393680-d35b-450d-ad1e-4c1aa3ae237f-4-1024x683.jpg"},"thumbnail":{"file":"c0393680-d35b-450d-ad1e-4c1aa3ae237f-4-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":20992,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c0393680-d35b-450d-ad1e-4c1aa3ae237f-4-150x150.jpg"},"medium_large":{"file":"c0393680-d35b-450d-ad1e-4c1aa3ae237f-4-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":66115,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c0393680-d35b-450d-ad1e-4c1aa3ae237f-4-768x512.jpg"},"1536x1536":{"file":"c0393680-d35b-450d-ad1e-4c1aa3ae237f-4-1536x1024.jpg","width":1536,"height":1024,"mime-type":"image\/jpeg","filesize":177670,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c0393680-d35b-450d-ad1e-4c1aa3ae237f-4-1536x1024.jpg"},"2048x2048":{"file":"c0393680-d35b-450d-ad1e-4c1aa3ae237f-4-2048x1365.jpg","width":2048,"height":1365,"mime-type":"image\/jpeg","filesize":284691,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c0393680-d35b-450d-ad1e-4c1aa3ae237f-4-2048x1365.jpg"},"square":{"file":"c0393680-d35b-450d-ad1e-4c1aa3ae237f-4-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":47990,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c0393680-d35b-450d-ad1e-4c1aa3ae237f-4-450x450.jpg"},"property-large-image":{"file":"c0393680-d35b-450d-ad1e-4c1aa3ae237f-4-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":118676,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c0393680-d35b-450d-ad1e-4c1aa3ae237f-4-1170x780.jpg"},"post-thumbnail":{"file":"c0393680-d35b-450d-ad1e-4c1aa3ae237f-4-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":19247,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c0393680-d35b-450d-ad1e-4c1aa3ae237f-4-150x100.jpg"},"modern-property-child-slider":{"file":"c0393680-d35b-450d-ad1e-4c1aa3ae237f-4-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":63340,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c0393680-d35b-450d-ad1e-4c1aa3ae237f-4-680x510.jpg"},"property-thumb-image":{"file":"c0393680-d35b-450d-ad1e-4c1aa3ae237f-4-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":40173,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c0393680-d35b-450d-ad1e-4c1aa3ae237f-4-488x326.jpg"},"property-detail-video-image":{"file":"c0393680-d35b-450d-ad1e-4c1aa3ae237f-4-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":60040,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c0393680-d35b-450d-ad1e-4c1aa3ae237f-4-818x417.jpg"},"agent-image":{"file":"c0393680-d35b-450d-ad1e-4c1aa3ae237f-4-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":25100,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c0393680-d35b-450d-ad1e-4c1aa3ae237f-4-210x210.jpg"},"partners-logo":{"file":"c0393680-d35b-450d-ad1e-4c1aa3ae237f-4-600x2132.jpg","width":600,"height":2132,"mime-type":"image\/jpeg","filesize":157469,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c0393680-d35b-450d-ad1e-4c1aa3ae237f-4-600x2132.jpg"},"post-featured-image":{"file":"c0393680-d35b-450d-ad1e-4c1aa3ae237f-4-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":114812,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c0393680-d35b-450d-ad1e-4c1aa3ae237f-4-1240x720.jpg"}},"image_meta":{"aperture":"11","credit":"Christian Ribas","camera":"Canon EOS 5D Mark IV","caption":"","created_timestamp":"1749827164","copyright":"www.christianribas.es","focal_length":"17","iso":"400","shutter_speed":"0.3","title":"","orientation":"1","keywords":[]},"original_image":"c0393680-d35b-450d-ad1e-4c1aa3ae237f-4.jpg","ID":"913210","name":"c0393680-d35b-450d-ad1e-4c1aa3ae237f-4-scaled.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2022\/07\/c0393680-d35b-450d-ad1e-4c1aa3ae237f-4-scaled.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c0393680-d35b-450d-ad1e-4c1aa3ae237f-4-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c0393680-d35b-450d-ad1e-4c1aa3ae237f-4-scaled.jpg","title":"c0393680-d35b-450d-ad1e-4c1aa3ae237f-4","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c0393680-d35b-450d-ad1e-4c1aa3ae237f-4-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c0393680-d35b-450d-ad1e-4c1aa3ae237f-4-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c0393680-d35b-450d-ad1e-4c1aa3ae237f-4-210x210.jpg 210w"},{"width":150,"height":150,"file":"2022\/07\/10a9f1dd-c323-4cb6-ae0c-bb7b8d3efe18-4-scaled.jpg","filesize":257402,"sizes":{"medium":{"file":"10a9f1dd-c323-4cb6-ae0c-bb7b8d3efe18-4-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":23904,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/10a9f1dd-c323-4cb6-ae0c-bb7b8d3efe18-4-300x200.jpg"},"large":{"file":"10a9f1dd-c323-4cb6-ae0c-bb7b8d3efe18-4-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":69129,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/10a9f1dd-c323-4cb6-ae0c-bb7b8d3efe18-4-1024x683.jpg"},"thumbnail":{"file":"10a9f1dd-c323-4cb6-ae0c-bb7b8d3efe18-4-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":18729,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/10a9f1dd-c323-4cb6-ae0c-bb7b8d3efe18-4-150x150.jpg"},"medium_large":{"file":"10a9f1dd-c323-4cb6-ae0c-bb7b8d3efe18-4-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":49595,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/10a9f1dd-c323-4cb6-ae0c-bb7b8d3efe18-4-768x512.jpg"},"1536x1536":{"file":"10a9f1dd-c323-4cb6-ae0c-bb7b8d3efe18-4-1536x1024.jpg","width":1536,"height":1024,"mime-type":"image\/jpeg","filesize":117569,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/10a9f1dd-c323-4cb6-ae0c-bb7b8d3efe18-4-1536x1024.jpg"},"2048x2048":{"file":"10a9f1dd-c323-4cb6-ae0c-bb7b8d3efe18-4-2048x1365.jpg","width":2048,"height":1365,"mime-type":"image\/jpeg","filesize":181171,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/10a9f1dd-c323-4cb6-ae0c-bb7b8d3efe18-4-2048x1365.jpg"},"square":{"file":"10a9f1dd-c323-4cb6-ae0c-bb7b8d3efe18-4-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":31646,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/10a9f1dd-c323-4cb6-ae0c-bb7b8d3efe18-4-450x450.jpg"},"property-large-image":{"file":"10a9f1dd-c323-4cb6-ae0c-bb7b8d3efe18-4-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":81658,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/10a9f1dd-c323-4cb6-ae0c-bb7b8d3efe18-4-1170x780.jpg"},"post-thumbnail":{"file":"10a9f1dd-c323-4cb6-ae0c-bb7b8d3efe18-4-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":18536,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/10a9f1dd-c323-4cb6-ae0c-bb7b8d3efe18-4-150x100.jpg"},"modern-property-child-slider":{"file":"10a9f1dd-c323-4cb6-ae0c-bb7b8d3efe18-4-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":44101,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/10a9f1dd-c323-4cb6-ae0c-bb7b8d3efe18-4-680x510.jpg"},"property-thumb-image":{"file":"10a9f1dd-c323-4cb6-ae0c-bb7b8d3efe18-4-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":32618,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/10a9f1dd-c323-4cb6-ae0c-bb7b8d3efe18-4-488x326.jpg"},"property-detail-video-image":{"file":"10a9f1dd-c323-4cb6-ae0c-bb7b8d3efe18-4-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":45154,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/10a9f1dd-c323-4cb6-ae0c-bb7b8d3efe18-4-818x417.jpg"},"agent-image":{"file":"10a9f1dd-c323-4cb6-ae0c-bb7b8d3efe18-4-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":21135,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/10a9f1dd-c323-4cb6-ae0c-bb7b8d3efe18-4-210x210.jpg"},"partners-logo":{"file":"10a9f1dd-c323-4cb6-ae0c-bb7b8d3efe18-4-600x2132.jpg","width":600,"height":2132,"mime-type":"image\/jpeg","filesize":66701,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/10a9f1dd-c323-4cb6-ae0c-bb7b8d3efe18-4-600x2132.jpg"},"post-featured-image":{"file":"10a9f1dd-c323-4cb6-ae0c-bb7b8d3efe18-4-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":76821,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/10a9f1dd-c323-4cb6-ae0c-bb7b8d3efe18-4-1240x720.jpg"}},"image_meta":{"aperture":"8","credit":"Christian Ribas","camera":"Canon EOS 5D Mark IV","caption":"","created_timestamp":"1749827223","copyright":"www.christianribas.es","focal_length":"40","iso":"200","shutter_speed":"0.2","title":"","orientation":"1","keywords":[]},"original_image":"10a9f1dd-c323-4cb6-ae0c-bb7b8d3efe18-4.jpg","ID":"913214","name":"10a9f1dd-c323-4cb6-ae0c-bb7b8d3efe18-4-scaled.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2022\/07\/10a9f1dd-c323-4cb6-ae0c-bb7b8d3efe18-4-scaled.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/10a9f1dd-c323-4cb6-ae0c-bb7b8d3efe18-4-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/10a9f1dd-c323-4cb6-ae0c-bb7b8d3efe18-4-scaled.jpg","title":"10a9f1dd-c323-4cb6-ae0c-bb7b8d3efe18-4","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/10a9f1dd-c323-4cb6-ae0c-bb7b8d3efe18-4-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/10a9f1dd-c323-4cb6-ae0c-bb7b8d3efe18-4-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/10a9f1dd-c323-4cb6-ae0c-bb7b8d3efe18-4-210x210.jpg 210w"},{"width":150,"height":150,"file":"2022\/07\/2b6e84f5-c9c5-4413-a8ea-37baff516ce6-4-scaled.jpg","filesize":291135,"sizes":{"medium":{"file":"2b6e84f5-c9c5-4413-a8ea-37baff516ce6-4-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":23101,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/2b6e84f5-c9c5-4413-a8ea-37baff516ce6-4-300x200.jpg"},"large":{"file":"2b6e84f5-c9c5-4413-a8ea-37baff516ce6-4-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":70394,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/2b6e84f5-c9c5-4413-a8ea-37baff516ce6-4-1024x683.jpg"},"thumbnail":{"file":"2b6e84f5-c9c5-4413-a8ea-37baff516ce6-4-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":19553,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/2b6e84f5-c9c5-4413-a8ea-37baff516ce6-4-150x150.jpg"},"medium_large":{"file":"2b6e84f5-c9c5-4413-a8ea-37baff516ce6-4-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":49627,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/2b6e84f5-c9c5-4413-a8ea-37baff516ce6-4-768x512.jpg"},"1536x1536":{"file":"2b6e84f5-c9c5-4413-a8ea-37baff516ce6-4-1536x1024.jpg","width":1536,"height":1024,"mime-type":"image\/jpeg","filesize":126820,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/2b6e84f5-c9c5-4413-a8ea-37baff516ce6-4-1536x1024.jpg"},"2048x2048":{"file":"2b6e84f5-c9c5-4413-a8ea-37baff516ce6-4-2048x1365.jpg","width":2048,"height":1365,"mime-type":"image\/jpeg","filesize":201432,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/2b6e84f5-c9c5-4413-a8ea-37baff516ce6-4-2048x1365.jpg"},"square":{"file":"2b6e84f5-c9c5-4413-a8ea-37baff516ce6-4-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":39194,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/2b6e84f5-c9c5-4413-a8ea-37baff516ce6-4-450x450.jpg"},"property-large-image":{"file":"2b6e84f5-c9c5-4413-a8ea-37baff516ce6-4-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":85229,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/2b6e84f5-c9c5-4413-a8ea-37baff516ce6-4-1170x780.jpg"},"post-thumbnail":{"file":"2b6e84f5-c9c5-4413-a8ea-37baff516ce6-4-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":18066,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/2b6e84f5-c9c5-4413-a8ea-37baff516ce6-4-150x100.jpg"},"modern-property-child-slider":{"file":"2b6e84f5-c9c5-4413-a8ea-37baff516ce6-4-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":47667,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/2b6e84f5-c9c5-4413-a8ea-37baff516ce6-4-680x510.jpg"},"property-thumb-image":{"file":"2b6e84f5-c9c5-4413-a8ea-37baff516ce6-4-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":31677,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/2b6e84f5-c9c5-4413-a8ea-37baff516ce6-4-488x326.jpg"},"property-detail-video-image":{"file":"2b6e84f5-c9c5-4413-a8ea-37baff516ce6-4-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":49796,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/2b6e84f5-c9c5-4413-a8ea-37baff516ce6-4-818x417.jpg"},"agent-image":{"file":"2b6e84f5-c9c5-4413-a8ea-37baff516ce6-4-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":22354,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/2b6e84f5-c9c5-4413-a8ea-37baff516ce6-4-210x210.jpg"},"partners-logo":{"file":"2b6e84f5-c9c5-4413-a8ea-37baff516ce6-4-600x2132.jpg","width":600,"height":2132,"mime-type":"image\/jpeg","filesize":100002,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/2b6e84f5-c9c5-4413-a8ea-37baff516ce6-4-600x2132.jpg"},"post-featured-image":{"file":"2b6e84f5-c9c5-4413-a8ea-37baff516ce6-4-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":88322,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/2b6e84f5-c9c5-4413-a8ea-37baff516ce6-4-1240x720.jpg"}},"image_meta":{"aperture":"11","credit":"Christian Ribas","camera":"Canon EOS 5D Mark IV","caption":"","created_timestamp":"1749827449","copyright":"www.christianribas.es","focal_length":"20","iso":"400","shutter_speed":"0.5","title":"","orientation":"1","keywords":[]},"original_image":"2b6e84f5-c9c5-4413-a8ea-37baff516ce6-4.jpg","ID":"913218","name":"2b6e84f5-c9c5-4413-a8ea-37baff516ce6-4-scaled.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2022\/07\/2b6e84f5-c9c5-4413-a8ea-37baff516ce6-4-scaled.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/2b6e84f5-c9c5-4413-a8ea-37baff516ce6-4-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/2b6e84f5-c9c5-4413-a8ea-37baff516ce6-4-scaled.jpg","title":"2b6e84f5-c9c5-4413-a8ea-37baff516ce6-4","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/2b6e84f5-c9c5-4413-a8ea-37baff516ce6-4-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/2b6e84f5-c9c5-4413-a8ea-37baff516ce6-4-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/2b6e84f5-c9c5-4413-a8ea-37baff516ce6-4-210x210.jpg 210w"},{"width":150,"height":150,"file":"2022\/07\/55128abc-c264-4065-b278-85229e67cb17-4-scaled.jpg","filesize":373969,"sizes":{"medium":{"file":"55128abc-c264-4065-b278-85229e67cb17-4-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":25160,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/55128abc-c264-4065-b278-85229e67cb17-4-300x200.jpg"},"large":{"file":"55128abc-c264-4065-b278-85229e67cb17-4-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":85951,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/55128abc-c264-4065-b278-85229e67cb17-4-1024x683.jpg"},"thumbnail":{"file":"55128abc-c264-4065-b278-85229e67cb17-4-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":19572,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/55128abc-c264-4065-b278-85229e67cb17-4-150x150.jpg"},"medium_large":{"file":"55128abc-c264-4065-b278-85229e67cb17-4-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":59505,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/55128abc-c264-4065-b278-85229e67cb17-4-768x512.jpg"},"1536x1536":{"file":"55128abc-c264-4065-b278-85229e67cb17-4-1536x1024.jpg","width":1536,"height":1024,"mime-type":"image\/jpeg","filesize":155704,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/55128abc-c264-4065-b278-85229e67cb17-4-1536x1024.jpg"},"2048x2048":{"file":"55128abc-c264-4065-b278-85229e67cb17-4-2048x1365.jpg","width":2048,"height":1365,"mime-type":"image\/jpeg","filesize":253395,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/55128abc-c264-4065-b278-85229e67cb17-4-2048x1365.jpg"},"square":{"file":"55128abc-c264-4065-b278-85229e67cb17-4-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":38185,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/55128abc-c264-4065-b278-85229e67cb17-4-450x450.jpg"},"property-large-image":{"file":"55128abc-c264-4065-b278-85229e67cb17-4-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":103691,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/55128abc-c264-4065-b278-85229e67cb17-4-1170x780.jpg"},"post-thumbnail":{"file":"55128abc-c264-4065-b278-85229e67cb17-4-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":18806,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/55128abc-c264-4065-b278-85229e67cb17-4-150x100.jpg"},"modern-property-child-slider":{"file":"55128abc-c264-4065-b278-85229e67cb17-4-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":54078,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/55128abc-c264-4065-b278-85229e67cb17-4-680x510.jpg"},"property-thumb-image":{"file":"55128abc-c264-4065-b278-85229e67cb17-4-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":36434,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/55128abc-c264-4065-b278-85229e67cb17-4-488x326.jpg"},"property-detail-video-image":{"file":"55128abc-c264-4065-b278-85229e67cb17-4-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":54720,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/55128abc-c264-4065-b278-85229e67cb17-4-818x417.jpg"},"agent-image":{"file":"55128abc-c264-4065-b278-85229e67cb17-4-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":22423,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/55128abc-c264-4065-b278-85229e67cb17-4-210x210.jpg"},"partners-logo":{"file":"55128abc-c264-4065-b278-85229e67cb17-4-600x2132.jpg","width":600,"height":2132,"mime-type":"image\/jpeg","filesize":92165,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/55128abc-c264-4065-b278-85229e67cb17-4-600x2132.jpg"},"post-featured-image":{"file":"55128abc-c264-4065-b278-85229e67cb17-4-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":101731,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/55128abc-c264-4065-b278-85229e67cb17-4-1240x720.jpg"}},"image_meta":{"aperture":"11","credit":"Christian Ribas","camera":"Canon EOS 5D Mark IV","caption":"","created_timestamp":"1749827534","copyright":"www.christianribas.es","focal_length":"17","iso":"400","shutter_speed":"0.3","title":"","orientation":"1","keywords":[]},"original_image":"55128abc-c264-4065-b278-85229e67cb17-4.jpg","ID":"913222","name":"55128abc-c264-4065-b278-85229e67cb17-4-scaled.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2022\/07\/55128abc-c264-4065-b278-85229e67cb17-4-scaled.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/55128abc-c264-4065-b278-85229e67cb17-4-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/55128abc-c264-4065-b278-85229e67cb17-4-scaled.jpg","title":"55128abc-c264-4065-b278-85229e67cb17-4","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/55128abc-c264-4065-b278-85229e67cb17-4-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/55128abc-c264-4065-b278-85229e67cb17-4-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/55128abc-c264-4065-b278-85229e67cb17-4-210x210.jpg 210w"},{"width":150,"height":150,"file":"2022\/07\/6f86a046-9059-41ed-bb00-8becfed1c373-4-scaled.jpg","filesize":424753,"sizes":{"medium":{"file":"6f86a046-9059-41ed-bb00-8becfed1c373-4-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":28107,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/6f86a046-9059-41ed-bb00-8becfed1c373-4-300x200.jpg"},"large":{"file":"6f86a046-9059-41ed-bb00-8becfed1c373-4-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":103219,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/6f86a046-9059-41ed-bb00-8becfed1c373-4-1024x683.jpg"},"thumbnail":{"file":"6f86a046-9059-41ed-bb00-8becfed1c373-4-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":20462,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/6f86a046-9059-41ed-bb00-8becfed1c373-4-150x150.jpg"},"medium_large":{"file":"6f86a046-9059-41ed-bb00-8becfed1c373-4-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":70452,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/6f86a046-9059-41ed-bb00-8becfed1c373-4-768x512.jpg"},"1536x1536":{"file":"6f86a046-9059-41ed-bb00-8becfed1c373-4-1536x1024.jpg","width":1536,"height":1024,"mime-type":"image\/jpeg","filesize":186581,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/6f86a046-9059-41ed-bb00-8becfed1c373-4-1536x1024.jpg"},"2048x2048":{"file":"6f86a046-9059-41ed-bb00-8becfed1c373-4-2048x1365.jpg","width":2048,"height":1365,"mime-type":"image\/jpeg","filesize":295392,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/6f86a046-9059-41ed-bb00-8becfed1c373-4-2048x1365.jpg"},"square":{"file":"6f86a046-9059-41ed-bb00-8becfed1c373-4-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":42057,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/6f86a046-9059-41ed-bb00-8becfed1c373-4-450x450.jpg"},"property-large-image":{"file":"6f86a046-9059-41ed-bb00-8becfed1c373-4-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":124989,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/6f86a046-9059-41ed-bb00-8becfed1c373-4-1170x780.jpg"},"post-thumbnail":{"file":"6f86a046-9059-41ed-bb00-8becfed1c373-4-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":19605,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/6f86a046-9059-41ed-bb00-8becfed1c373-4-150x100.jpg"},"modern-property-child-slider":{"file":"6f86a046-9059-41ed-bb00-8becfed1c373-4-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":62022,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/6f86a046-9059-41ed-bb00-8becfed1c373-4-680x510.jpg"},"property-thumb-image":{"file":"6f86a046-9059-41ed-bb00-8becfed1c373-4-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":42516,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/6f86a046-9059-41ed-bb00-8becfed1c373-4-488x326.jpg"},"property-detail-video-image":{"file":"6f86a046-9059-41ed-bb00-8becfed1c373-4-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":63175,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/6f86a046-9059-41ed-bb00-8becfed1c373-4-818x417.jpg"},"agent-image":{"file":"6f86a046-9059-41ed-bb00-8becfed1c373-4-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":24030,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/6f86a046-9059-41ed-bb00-8becfed1c373-4-210x210.jpg"},"partners-logo":{"file":"6f86a046-9059-41ed-bb00-8becfed1c373-4-600x2132.jpg","width":600,"height":2132,"mime-type":"image\/jpeg","filesize":141865,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/6f86a046-9059-41ed-bb00-8becfed1c373-4-600x2132.jpg"},"post-featured-image":{"file":"6f86a046-9059-41ed-bb00-8becfed1c373-4-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":120291,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/6f86a046-9059-41ed-bb00-8becfed1c373-4-1240x720.jpg"}},"image_meta":{"aperture":"11","credit":"Christian Ribas","camera":"Canon EOS 5D Mark IV","caption":"","created_timestamp":"1749827616","copyright":"www.christianribas.es","focal_length":"17","iso":"400","shutter_speed":"1","title":"","orientation":"1","keywords":[]},"original_image":"6f86a046-9059-41ed-bb00-8becfed1c373-4.jpg","ID":"913226","name":"6f86a046-9059-41ed-bb00-8becfed1c373-4-scaled.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2022\/07\/6f86a046-9059-41ed-bb00-8becfed1c373-4-scaled.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/6f86a046-9059-41ed-bb00-8becfed1c373-4-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/6f86a046-9059-41ed-bb00-8becfed1c373-4-scaled.jpg","title":"6f86a046-9059-41ed-bb00-8becfed1c373-4","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/6f86a046-9059-41ed-bb00-8becfed1c373-4-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/6f86a046-9059-41ed-bb00-8becfed1c373-4-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/6f86a046-9059-41ed-bb00-8becfed1c373-4-210x210.jpg 210w"},{"width":150,"height":150,"file":"2022\/07\/095da214-717a-4537-b96d-2f33df3aca8a-4-scaled.jpg","filesize":358403,"sizes":{"medium":{"file":"095da214-717a-4537-b96d-2f33df3aca8a-4-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":26705,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/095da214-717a-4537-b96d-2f33df3aca8a-4-300x200.jpg"},"large":{"file":"095da214-717a-4537-b96d-2f33df3aca8a-4-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":87246,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/095da214-717a-4537-b96d-2f33df3aca8a-4-1024x683.jpg"},"thumbnail":{"file":"095da214-717a-4537-b96d-2f33df3aca8a-4-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":21234,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/095da214-717a-4537-b96d-2f33df3aca8a-4-150x150.jpg"},"medium_large":{"file":"095da214-717a-4537-b96d-2f33df3aca8a-4-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":61465,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/095da214-717a-4537-b96d-2f33df3aca8a-4-768x512.jpg"},"1536x1536":{"file":"095da214-717a-4537-b96d-2f33df3aca8a-4-1536x1024.jpg","width":1536,"height":1024,"mime-type":"image\/jpeg","filesize":153050,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/095da214-717a-4537-b96d-2f33df3aca8a-4-1536x1024.jpg"},"2048x2048":{"file":"095da214-717a-4537-b96d-2f33df3aca8a-4-2048x1365.jpg","width":2048,"height":1365,"mime-type":"image\/jpeg","filesize":244184,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/095da214-717a-4537-b96d-2f33df3aca8a-4-2048x1365.jpg"},"square":{"file":"095da214-717a-4537-b96d-2f33df3aca8a-4-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":45761,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/095da214-717a-4537-b96d-2f33df3aca8a-4-450x450.jpg"},"property-large-image":{"file":"095da214-717a-4537-b96d-2f33df3aca8a-4-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":103761,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/095da214-717a-4537-b96d-2f33df3aca8a-4-1170x780.jpg"},"post-thumbnail":{"file":"095da214-717a-4537-b96d-2f33df3aca8a-4-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":19438,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/095da214-717a-4537-b96d-2f33df3aca8a-4-150x100.jpg"},"modern-property-child-slider":{"file":"095da214-717a-4537-b96d-2f33df3aca8a-4-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":58429,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/095da214-717a-4537-b96d-2f33df3aca8a-4-680x510.jpg"},"property-thumb-image":{"file":"095da214-717a-4537-b96d-2f33df3aca8a-4-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":38888,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/095da214-717a-4537-b96d-2f33df3aca8a-4-488x326.jpg"},"property-detail-video-image":{"file":"095da214-717a-4537-b96d-2f33df3aca8a-4-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":55498,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/095da214-717a-4537-b96d-2f33df3aca8a-4-818x417.jpg"},"agent-image":{"file":"095da214-717a-4537-b96d-2f33df3aca8a-4-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":25126,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/095da214-717a-4537-b96d-2f33df3aca8a-4-210x210.jpg"},"partners-logo":{"file":"095da214-717a-4537-b96d-2f33df3aca8a-4-600x2132.jpg","width":600,"height":2132,"mime-type":"image\/jpeg","filesize":120326,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/095da214-717a-4537-b96d-2f33df3aca8a-4-600x2132.jpg"},"post-featured-image":{"file":"095da214-717a-4537-b96d-2f33df3aca8a-4-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":101103,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/095da214-717a-4537-b96d-2f33df3aca8a-4-1240x720.jpg"}},"image_meta":{"aperture":"11","credit":"Christian Ribas","camera":"Canon EOS 5D Mark IV","caption":"","created_timestamp":"1749827689","copyright":"www.christianribas.es","focal_length":"19","iso":"400","shutter_speed":"0.8","title":"","orientation":"1","keywords":[]},"original_image":"095da214-717a-4537-b96d-2f33df3aca8a-4.jpg","ID":"913230","name":"095da214-717a-4537-b96d-2f33df3aca8a-4-scaled.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2022\/07\/095da214-717a-4537-b96d-2f33df3aca8a-4-scaled.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/095da214-717a-4537-b96d-2f33df3aca8a-4-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/095da214-717a-4537-b96d-2f33df3aca8a-4-scaled.jpg","title":"095da214-717a-4537-b96d-2f33df3aca8a-4","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/095da214-717a-4537-b96d-2f33df3aca8a-4-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/095da214-717a-4537-b96d-2f33df3aca8a-4-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/095da214-717a-4537-b96d-2f33df3aca8a-4-210x210.jpg 210w"},{"width":150,"height":150,"file":"2022\/07\/553012ec-471f-4339-b84d-1e4f4a841cd6-4-scaled.jpg","filesize":340046,"sizes":{"medium":{"file":"553012ec-471f-4339-b84d-1e4f4a841cd6-4-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":25611,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/553012ec-471f-4339-b84d-1e4f4a841cd6-4-300x200.jpg"},"large":{"file":"553012ec-471f-4339-b84d-1e4f4a841cd6-4-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":82181,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/553012ec-471f-4339-b84d-1e4f4a841cd6-4-1024x683.jpg"},"thumbnail":{"file":"553012ec-471f-4339-b84d-1e4f4a841cd6-4-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":20312,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/553012ec-471f-4339-b84d-1e4f4a841cd6-4-150x150.jpg"},"medium_large":{"file":"553012ec-471f-4339-b84d-1e4f4a841cd6-4-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":57084,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/553012ec-471f-4339-b84d-1e4f4a841cd6-4-768x512.jpg"},"1536x1536":{"file":"553012ec-471f-4339-b84d-1e4f4a841cd6-4-1536x1024.jpg","width":1536,"height":1024,"mime-type":"image\/jpeg","filesize":148733,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/553012ec-471f-4339-b84d-1e4f4a841cd6-4-1536x1024.jpg"},"2048x2048":{"file":"553012ec-471f-4339-b84d-1e4f4a841cd6-4-2048x1365.jpg","width":2048,"height":1365,"mime-type":"image\/jpeg","filesize":236292,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/553012ec-471f-4339-b84d-1e4f4a841cd6-4-2048x1365.jpg"},"square":{"file":"553012ec-471f-4339-b84d-1e4f4a841cd6-4-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":40722,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/553012ec-471f-4339-b84d-1e4f4a841cd6-4-450x450.jpg"},"property-large-image":{"file":"553012ec-471f-4339-b84d-1e4f4a841cd6-4-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":99197,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/553012ec-471f-4339-b84d-1e4f4a841cd6-4-1170x780.jpg"},"post-thumbnail":{"file":"553012ec-471f-4339-b84d-1e4f4a841cd6-4-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":19080,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/553012ec-471f-4339-b84d-1e4f4a841cd6-4-150x100.jpg"},"modern-property-child-slider":{"file":"553012ec-471f-4339-b84d-1e4f4a841cd6-4-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":54302,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/553012ec-471f-4339-b84d-1e4f4a841cd6-4-680x510.jpg"},"property-thumb-image":{"file":"553012ec-471f-4339-b84d-1e4f4a841cd6-4-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":36249,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/553012ec-471f-4339-b84d-1e4f4a841cd6-4-488x326.jpg"},"property-detail-video-image":{"file":"553012ec-471f-4339-b84d-1e4f4a841cd6-4-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":53766,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/553012ec-471f-4339-b84d-1e4f4a841cd6-4-818x417.jpg"},"agent-image":{"file":"553012ec-471f-4339-b84d-1e4f4a841cd6-4-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":23656,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/553012ec-471f-4339-b84d-1e4f4a841cd6-4-210x210.jpg"},"partners-logo":{"file":"553012ec-471f-4339-b84d-1e4f4a841cd6-4-600x2132.jpg","width":600,"height":2132,"mime-type":"image\/jpeg","filesize":108848,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/553012ec-471f-4339-b84d-1e4f4a841cd6-4-600x2132.jpg"},"post-featured-image":{"file":"553012ec-471f-4339-b84d-1e4f4a841cd6-4-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":99720,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/553012ec-471f-4339-b84d-1e4f4a841cd6-4-1240x720.jpg"}},"image_meta":{"aperture":"8","credit":"Christian Ribas","camera":"Canon EOS 5D Mark IV","caption":"","created_timestamp":"1749827747","copyright":"www.christianribas.es","focal_length":"29","iso":"200","shutter_speed":"0.8","title":"","orientation":"1","keywords":[]},"original_image":"553012ec-471f-4339-b84d-1e4f4a841cd6-4.jpg","ID":"913234","name":"553012ec-471f-4339-b84d-1e4f4a841cd6-4-scaled.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2022\/07\/553012ec-471f-4339-b84d-1e4f4a841cd6-4-scaled.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/553012ec-471f-4339-b84d-1e4f4a841cd6-4-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/553012ec-471f-4339-b84d-1e4f4a841cd6-4-scaled.jpg","title":"553012ec-471f-4339-b84d-1e4f4a841cd6-4","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/553012ec-471f-4339-b84d-1e4f4a841cd6-4-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/553012ec-471f-4339-b84d-1e4f4a841cd6-4-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/553012ec-471f-4339-b84d-1e4f4a841cd6-4-210x210.jpg 210w"},{"width":150,"height":150,"file":"2022\/07\/e6e00cae-eb41-4198-99b5-cc71d87b1566-4-scaled.jpg","filesize":355129,"sizes":{"medium":{"file":"e6e00cae-eb41-4198-99b5-cc71d87b1566-4-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":24501,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e6e00cae-eb41-4198-99b5-cc71d87b1566-4-300x200.jpg"},"large":{"file":"e6e00cae-eb41-4198-99b5-cc71d87b1566-4-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":81980,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e6e00cae-eb41-4198-99b5-cc71d87b1566-4-1024x683.jpg"},"thumbnail":{"file":"e6e00cae-eb41-4198-99b5-cc71d87b1566-4-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":19664,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e6e00cae-eb41-4198-99b5-cc71d87b1566-4-150x150.jpg"},"medium_large":{"file":"e6e00cae-eb41-4198-99b5-cc71d87b1566-4-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":56581,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e6e00cae-eb41-4198-99b5-cc71d87b1566-4-768x512.jpg"},"1536x1536":{"file":"e6e00cae-eb41-4198-99b5-cc71d87b1566-4-1536x1024.jpg","width":1536,"height":1024,"mime-type":"image\/jpeg","filesize":151095,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e6e00cae-eb41-4198-99b5-cc71d87b1566-4-1536x1024.jpg"},"2048x2048":{"file":"e6e00cae-eb41-4198-99b5-cc71d87b1566-4-2048x1365.jpg","width":2048,"height":1365,"mime-type":"image\/jpeg","filesize":243518,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e6e00cae-eb41-4198-99b5-cc71d87b1566-4-2048x1365.jpg"},"square":{"file":"e6e00cae-eb41-4198-99b5-cc71d87b1566-4-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":40695,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e6e00cae-eb41-4198-99b5-cc71d87b1566-4-450x450.jpg"},"property-large-image":{"file":"e6e00cae-eb41-4198-99b5-cc71d87b1566-4-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":99443,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e6e00cae-eb41-4198-99b5-cc71d87b1566-4-1170x780.jpg"},"post-thumbnail":{"file":"e6e00cae-eb41-4198-99b5-cc71d87b1566-4-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":18417,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e6e00cae-eb41-4198-99b5-cc71d87b1566-4-150x100.jpg"},"modern-property-child-slider":{"file":"e6e00cae-eb41-4198-99b5-cc71d87b1566-4-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":53561,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e6e00cae-eb41-4198-99b5-cc71d87b1566-4-680x510.jpg"},"property-thumb-image":{"file":"e6e00cae-eb41-4198-99b5-cc71d87b1566-4-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":34949,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e6e00cae-eb41-4198-99b5-cc71d87b1566-4-488x326.jpg"},"property-detail-video-image":{"file":"e6e00cae-eb41-4198-99b5-cc71d87b1566-4-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":49233,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e6e00cae-eb41-4198-99b5-cc71d87b1566-4-818x417.jpg"},"agent-image":{"file":"e6e00cae-eb41-4198-99b5-cc71d87b1566-4-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":23015,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e6e00cae-eb41-4198-99b5-cc71d87b1566-4-210x210.jpg"},"partners-logo":{"file":"e6e00cae-eb41-4198-99b5-cc71d87b1566-4-600x2132.jpg","width":600,"height":2132,"mime-type":"image\/jpeg","filesize":199545,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e6e00cae-eb41-4198-99b5-cc71d87b1566-4-600x2132.jpg"},"post-featured-image":{"file":"e6e00cae-eb41-4198-99b5-cc71d87b1566-4-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":94258,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e6e00cae-eb41-4198-99b5-cc71d87b1566-4-1240x720.jpg"}},"image_meta":{"aperture":"11","credit":"Christian Ribas","camera":"Canon EOS 5D Mark IV","caption":"","created_timestamp":"1749827780","copyright":"www.christianribas.es","focal_length":"17","iso":"400","shutter_speed":"2","title":"","orientation":"1","keywords":[]},"original_image":"e6e00cae-eb41-4198-99b5-cc71d87b1566-4.jpg","ID":"913238","name":"e6e00cae-eb41-4198-99b5-cc71d87b1566-4-scaled.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2022\/07\/e6e00cae-eb41-4198-99b5-cc71d87b1566-4-scaled.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e6e00cae-eb41-4198-99b5-cc71d87b1566-4-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e6e00cae-eb41-4198-99b5-cc71d87b1566-4-scaled.jpg","title":"e6e00cae-eb41-4198-99b5-cc71d87b1566-4","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e6e00cae-eb41-4198-99b5-cc71d87b1566-4-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e6e00cae-eb41-4198-99b5-cc71d87b1566-4-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e6e00cae-eb41-4198-99b5-cc71d87b1566-4-210x210.jpg 210w"},{"width":150,"height":150,"file":"2022\/07\/c9b4c147-9ea5-4ac5-b76b-7a750748e78f-9-scaled.jpg","filesize":537149,"sizes":{"medium":{"file":"c9b4c147-9ea5-4ac5-b76b-7a750748e78f-9-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":30078,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c9b4c147-9ea5-4ac5-b76b-7a750748e78f-9-300x200.jpg"},"large":{"file":"c9b4c147-9ea5-4ac5-b76b-7a750748e78f-9-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":128569,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c9b4c147-9ea5-4ac5-b76b-7a750748e78f-9-1024x683.jpg"},"thumbnail":{"file":"c9b4c147-9ea5-4ac5-b76b-7a750748e78f-9-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":22282,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c9b4c147-9ea5-4ac5-b76b-7a750748e78f-9-150x150.jpg"},"medium_large":{"file":"c9b4c147-9ea5-4ac5-b76b-7a750748e78f-9-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":85083,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c9b4c147-9ea5-4ac5-b76b-7a750748e78f-9-768x512.jpg"},"1536x1536":{"file":"c9b4c147-9ea5-4ac5-b76b-7a750748e78f-9-1536x1024.jpg","width":1536,"height":1024,"mime-type":"image\/jpeg","filesize":237616,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c9b4c147-9ea5-4ac5-b76b-7a750748e78f-9-1536x1024.jpg"},"2048x2048":{"file":"c9b4c147-9ea5-4ac5-b76b-7a750748e78f-9-2048x1365.jpg","width":2048,"height":1365,"mime-type":"image\/jpeg","filesize":375342,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c9b4c147-9ea5-4ac5-b76b-7a750748e78f-9-2048x1365.jpg"},"square":{"file":"c9b4c147-9ea5-4ac5-b76b-7a750748e78f-9-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":57185,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c9b4c147-9ea5-4ac5-b76b-7a750748e78f-9-450x450.jpg"},"property-large-image":{"file":"c9b4c147-9ea5-4ac5-b76b-7a750748e78f-9-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":156660,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c9b4c147-9ea5-4ac5-b76b-7a750748e78f-9-1170x780.jpg"},"post-thumbnail":{"file":"c9b4c147-9ea5-4ac5-b76b-7a750748e78f-9-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":20288,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c9b4c147-9ea5-4ac5-b76b-7a750748e78f-9-150x100.jpg"},"modern-property-child-slider":{"file":"c9b4c147-9ea5-4ac5-b76b-7a750748e78f-9-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":81557,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c9b4c147-9ea5-4ac5-b76b-7a750748e78f-9-680x510.jpg"},"property-thumb-image":{"file":"c9b4c147-9ea5-4ac5-b76b-7a750748e78f-9-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":48326,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c9b4c147-9ea5-4ac5-b76b-7a750748e78f-9-488x326.jpg"},"property-detail-video-image":{"file":"c9b4c147-9ea5-4ac5-b76b-7a750748e78f-9-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":80354,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c9b4c147-9ea5-4ac5-b76b-7a750748e78f-9-818x417.jpg"},"agent-image":{"file":"c9b4c147-9ea5-4ac5-b76b-7a750748e78f-9-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":27428,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c9b4c147-9ea5-4ac5-b76b-7a750748e78f-9-210x210.jpg"},"partners-logo":{"file":"c9b4c147-9ea5-4ac5-b76b-7a750748e78f-9-600x2132.jpg","width":600,"height":2132,"mime-type":"image\/jpeg","filesize":159837,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c9b4c147-9ea5-4ac5-b76b-7a750748e78f-9-600x2132.jpg"},"post-featured-image":{"file":"c9b4c147-9ea5-4ac5-b76b-7a750748e78f-9-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":156900,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c9b4c147-9ea5-4ac5-b76b-7a750748e78f-9-1240x720.jpg"}},"image_meta":{"aperture":"11","credit":"Christian Ribas","camera":"Canon EOS 5D Mark IV","caption":"","created_timestamp":"1749828083","copyright":"www.christianribas.es","focal_length":"17","iso":"400","shutter_speed":"0.1","title":"","orientation":"1","keywords":[]},"original_image":"c9b4c147-9ea5-4ac5-b76b-7a750748e78f-9.jpg","ID":"913245","name":"c9b4c147-9ea5-4ac5-b76b-7a750748e78f-9-scaled.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2022\/07\/c9b4c147-9ea5-4ac5-b76b-7a750748e78f-9-scaled.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c9b4c147-9ea5-4ac5-b76b-7a750748e78f-9-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c9b4c147-9ea5-4ac5-b76b-7a750748e78f-9-scaled.jpg","title":"c9b4c147-9ea5-4ac5-b76b-7a750748e78f-9","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c9b4c147-9ea5-4ac5-b76b-7a750748e78f-9-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c9b4c147-9ea5-4ac5-b76b-7a750748e78f-9-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/c9b4c147-9ea5-4ac5-b76b-7a750748e78f-9-210x210.jpg 210w"},{"width":150,"height":150,"file":"2022\/07\/e3e5368a-b28a-438c-a028-047aec7db357-4-scaled.jpg","filesize":563142,"sizes":{"medium":{"file":"e3e5368a-b28a-438c-a028-047aec7db357-4-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":30393,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e3e5368a-b28a-438c-a028-047aec7db357-4-300x200.jpg"},"large":{"file":"e3e5368a-b28a-438c-a028-047aec7db357-4-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":129258,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e3e5368a-b28a-438c-a028-047aec7db357-4-1024x683.jpg"},"thumbnail":{"file":"e3e5368a-b28a-438c-a028-047aec7db357-4-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":22754,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e3e5368a-b28a-438c-a028-047aec7db357-4-150x150.jpg"},"medium_large":{"file":"e3e5368a-b28a-438c-a028-047aec7db357-4-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":85304,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e3e5368a-b28a-438c-a028-047aec7db357-4-768x512.jpg"},"1536x1536":{"file":"e3e5368a-b28a-438c-a028-047aec7db357-4-1536x1024.jpg","width":1536,"height":1024,"mime-type":"image\/jpeg","filesize":241304,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e3e5368a-b28a-438c-a028-047aec7db357-4-1536x1024.jpg"},"2048x2048":{"file":"e3e5368a-b28a-438c-a028-047aec7db357-4-2048x1365.jpg","width":2048,"height":1365,"mime-type":"image\/jpeg","filesize":387286,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e3e5368a-b28a-438c-a028-047aec7db357-4-2048x1365.jpg"},"square":{"file":"e3e5368a-b28a-438c-a028-047aec7db357-4-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":61208,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e3e5368a-b28a-438c-a028-047aec7db357-4-450x450.jpg"},"property-large-image":{"file":"e3e5368a-b28a-438c-a028-047aec7db357-4-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":157914,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e3e5368a-b28a-438c-a028-047aec7db357-4-1170x780.jpg"},"post-thumbnail":{"file":"e3e5368a-b28a-438c-a028-047aec7db357-4-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":20319,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e3e5368a-b28a-438c-a028-047aec7db357-4-150x100.jpg"},"modern-property-child-slider":{"file":"e3e5368a-b28a-438c-a028-047aec7db357-4-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":81871,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e3e5368a-b28a-438c-a028-047aec7db357-4-680x510.jpg"},"property-thumb-image":{"file":"e3e5368a-b28a-438c-a028-047aec7db357-4-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":48611,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e3e5368a-b28a-438c-a028-047aec7db357-4-488x326.jpg"},"property-detail-video-image":{"file":"e3e5368a-b28a-438c-a028-047aec7db357-4-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":76242,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e3e5368a-b28a-438c-a028-047aec7db357-4-818x417.jpg"},"agent-image":{"file":"e3e5368a-b28a-438c-a028-047aec7db357-4-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":28446,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e3e5368a-b28a-438c-a028-047aec7db357-4-210x210.jpg"},"partners-logo":{"file":"e3e5368a-b28a-438c-a028-047aec7db357-4-600x2132.jpg","width":600,"height":2132,"mime-type":"image\/jpeg","filesize":239107,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e3e5368a-b28a-438c-a028-047aec7db357-4-600x2132.jpg"},"post-featured-image":{"file":"e3e5368a-b28a-438c-a028-047aec7db357-4-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":153040,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e3e5368a-b28a-438c-a028-047aec7db357-4-1240x720.jpg"}},"image_meta":{"aperture":"11","credit":"Christian Ribas","camera":"Canon EOS 5D Mark IV","caption":"","created_timestamp":"1749828129","copyright":"www.christianribas.es","focal_length":"17","iso":"400","shutter_speed":"0.125","title":"","orientation":"1","keywords":[]},"original_image":"e3e5368a-b28a-438c-a028-047aec7db357-4.jpg","ID":"913250","name":"e3e5368a-b28a-438c-a028-047aec7db357-4-scaled.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2022\/07\/e3e5368a-b28a-438c-a028-047aec7db357-4-scaled.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e3e5368a-b28a-438c-a028-047aec7db357-4-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e3e5368a-b28a-438c-a028-047aec7db357-4-scaled.jpg","title":"e3e5368a-b28a-438c-a028-047aec7db357-4","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e3e5368a-b28a-438c-a028-047aec7db357-4-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e3e5368a-b28a-438c-a028-047aec7db357-4-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/e3e5368a-b28a-438c-a028-047aec7db357-4-210x210.jpg 210w"},{"width":150,"height":150,"file":"2022\/07\/7c5cf625-7d12-4216-8a1d-e98af4bae483-4-scaled.jpg","filesize":527055,"sizes":{"medium":{"file":"7c5cf625-7d12-4216-8a1d-e98af4bae483-4-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":28792,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/7c5cf625-7d12-4216-8a1d-e98af4bae483-4-300x200.jpg"},"large":{"file":"7c5cf625-7d12-4216-8a1d-e98af4bae483-4-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":113499,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/7c5cf625-7d12-4216-8a1d-e98af4bae483-4-1024x683.jpg"},"thumbnail":{"file":"7c5cf625-7d12-4216-8a1d-e98af4bae483-4-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":21499,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/7c5cf625-7d12-4216-8a1d-e98af4bae483-4-150x150.jpg"},"medium_large":{"file":"7c5cf625-7d12-4216-8a1d-e98af4bae483-4-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":75773,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/7c5cf625-7d12-4216-8a1d-e98af4bae483-4-768x512.jpg"},"1536x1536":{"file":"7c5cf625-7d12-4216-8a1d-e98af4bae483-4-1536x1024.jpg","width":1536,"height":1024,"mime-type":"image\/jpeg","filesize":214395,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/7c5cf625-7d12-4216-8a1d-e98af4bae483-4-1536x1024.jpg"},"2048x2048":{"file":"7c5cf625-7d12-4216-8a1d-e98af4bae483-4-2048x1365.jpg","width":2048,"height":1365,"mime-type":"image\/jpeg","filesize":352937,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/7c5cf625-7d12-4216-8a1d-e98af4bae483-4-2048x1365.jpg"},"square":{"file":"7c5cf625-7d12-4216-8a1d-e98af4bae483-4-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":51129,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/7c5cf625-7d12-4216-8a1d-e98af4bae483-4-450x450.jpg"},"property-large-image":{"file":"7c5cf625-7d12-4216-8a1d-e98af4bae483-4-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":139208,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/7c5cf625-7d12-4216-8a1d-e98af4bae483-4-1170x780.jpg"},"post-thumbnail":{"file":"7c5cf625-7d12-4216-8a1d-e98af4bae483-4-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":20110,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/7c5cf625-7d12-4216-8a1d-e98af4bae483-4-150x100.jpg"},"modern-property-child-slider":{"file":"7c5cf625-7d12-4216-8a1d-e98af4bae483-4-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":69626,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/7c5cf625-7d12-4216-8a1d-e98af4bae483-4-680x510.jpg"},"property-thumb-image":{"file":"7c5cf625-7d12-4216-8a1d-e98af4bae483-4-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":44498,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/7c5cf625-7d12-4216-8a1d-e98af4bae483-4-488x326.jpg"},"property-detail-video-image":{"file":"7c5cf625-7d12-4216-8a1d-e98af4bae483-4-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":71723,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/7c5cf625-7d12-4216-8a1d-e98af4bae483-4-818x417.jpg"},"agent-image":{"file":"7c5cf625-7d12-4216-8a1d-e98af4bae483-4-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":25905,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/7c5cf625-7d12-4216-8a1d-e98af4bae483-4-210x210.jpg"},"partners-logo":{"file":"7c5cf625-7d12-4216-8a1d-e98af4bae483-4-600x2132.jpg","width":600,"height":2132,"mime-type":"image\/jpeg","filesize":191159,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/7c5cf625-7d12-4216-8a1d-e98af4bae483-4-600x2132.jpg"},"post-featured-image":{"file":"7c5cf625-7d12-4216-8a1d-e98af4bae483-4-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":137852,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/7c5cf625-7d12-4216-8a1d-e98af4bae483-4-1240x720.jpg"}},"image_meta":{"aperture":"8","credit":"Christian Ribas","camera":"Canon EOS 5D Mark IV","caption":"","created_timestamp":"1749828270","copyright":"www.christianribas.es","focal_length":"22","iso":"200","shutter_speed":"0.076923076923077","title":"","orientation":"1","keywords":[]},"original_image":"7c5cf625-7d12-4216-8a1d-e98af4bae483-4.jpg","ID":"913254","name":"7c5cf625-7d12-4216-8a1d-e98af4bae483-4-scaled.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2022\/07\/7c5cf625-7d12-4216-8a1d-e98af4bae483-4-scaled.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/7c5cf625-7d12-4216-8a1d-e98af4bae483-4-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/7c5cf625-7d12-4216-8a1d-e98af4bae483-4-scaled.jpg","title":"7c5cf625-7d12-4216-8a1d-e98af4bae483-4","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/7c5cf625-7d12-4216-8a1d-e98af4bae483-4-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/7c5cf625-7d12-4216-8a1d-e98af4bae483-4-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/7c5cf625-7d12-4216-8a1d-e98af4bae483-4-210x210.jpg 210w"},{"width":150,"height":150,"file":"2022\/07\/14a990d3-1029-490d-9744-0143f06fe26f-4-scaled.jpg","filesize":449106,"sizes":{"medium":{"file":"14a990d3-1029-490d-9744-0143f06fe26f-4-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":30820,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/14a990d3-1029-490d-9744-0143f06fe26f-4-300x200.jpg"},"large":{"file":"14a990d3-1029-490d-9744-0143f06fe26f-4-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":121974,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/14a990d3-1029-490d-9744-0143f06fe26f-4-1024x683.jpg"},"thumbnail":{"file":"14a990d3-1029-490d-9744-0143f06fe26f-4-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":22348,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/14a990d3-1029-490d-9744-0143f06fe26f-4-150x150.jpg"},"medium_large":{"file":"14a990d3-1029-490d-9744-0143f06fe26f-4-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":83282,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/14a990d3-1029-490d-9744-0143f06fe26f-4-768x512.jpg"},"1536x1536":{"file":"14a990d3-1029-490d-9744-0143f06fe26f-4-1536x1024.jpg","width":1536,"height":1024,"mime-type":"image\/jpeg","filesize":211967,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/14a990d3-1029-490d-9744-0143f06fe26f-4-1536x1024.jpg"},"2048x2048":{"file":"14a990d3-1029-490d-9744-0143f06fe26f-4-2048x1365.jpg","width":2048,"height":1365,"mime-type":"image\/jpeg","filesize":323126,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/14a990d3-1029-490d-9744-0143f06fe26f-4-2048x1365.jpg"},"square":{"file":"14a990d3-1029-490d-9744-0143f06fe26f-4-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":55695,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/14a990d3-1029-490d-9744-0143f06fe26f-4-450x450.jpg"},"property-large-image":{"file":"14a990d3-1029-490d-9744-0143f06fe26f-4-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":146260,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/14a990d3-1029-490d-9744-0143f06fe26f-4-1170x780.jpg"},"post-thumbnail":{"file":"14a990d3-1029-490d-9744-0143f06fe26f-4-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":20710,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/14a990d3-1029-490d-9744-0143f06fe26f-4-150x100.jpg"},"modern-property-child-slider":{"file":"14a990d3-1029-490d-9744-0143f06fe26f-4-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":75611,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/14a990d3-1029-490d-9744-0143f06fe26f-4-680x510.jpg"},"property-thumb-image":{"file":"14a990d3-1029-490d-9744-0143f06fe26f-4-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":48769,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/14a990d3-1029-490d-9744-0143f06fe26f-4-488x326.jpg"},"property-detail-video-image":{"file":"14a990d3-1029-490d-9744-0143f06fe26f-4-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":75336,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/14a990d3-1029-490d-9744-0143f06fe26f-4-818x417.jpg"},"agent-image":{"file":"14a990d3-1029-490d-9744-0143f06fe26f-4-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":27570,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/14a990d3-1029-490d-9744-0143f06fe26f-4-210x210.jpg"},"partners-logo":{"file":"14a990d3-1029-490d-9744-0143f06fe26f-4-600x2132.jpg","width":600,"height":2132,"mime-type":"image\/jpeg","filesize":183153,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/14a990d3-1029-490d-9744-0143f06fe26f-4-600x2132.jpg"},"post-featured-image":{"file":"14a990d3-1029-490d-9744-0143f06fe26f-4-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":141162,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/14a990d3-1029-490d-9744-0143f06fe26f-4-1240x720.jpg"}},"image_meta":{"aperture":"7.1","credit":"Christian Ribas","camera":"Canon EOS 5D Mark IV","caption":"","created_timestamp":"1749828345","copyright":"www.christianribas.es","focal_length":"33","iso":"200","shutter_speed":"0.1","title":"","orientation":"1","keywords":[]},"original_image":"14a990d3-1029-490d-9744-0143f06fe26f-4.jpg","ID":"913258","name":"14a990d3-1029-490d-9744-0143f06fe26f-4-scaled.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2022\/07\/14a990d3-1029-490d-9744-0143f06fe26f-4-scaled.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/14a990d3-1029-490d-9744-0143f06fe26f-4-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/14a990d3-1029-490d-9744-0143f06fe26f-4-scaled.jpg","title":"14a990d3-1029-490d-9744-0143f06fe26f-4","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/14a990d3-1029-490d-9744-0143f06fe26f-4-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/14a990d3-1029-490d-9744-0143f06fe26f-4-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/14a990d3-1029-490d-9744-0143f06fe26f-4-210x210.jpg 210w"},{"width":150,"height":150,"file":"2022\/07\/ee775d1e-302b-4380-a2d3-97d900729684-4-scaled.jpg","filesize":756685,"sizes":{"medium":{"file":"ee775d1e-302b-4380-a2d3-97d900729684-4-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":33420,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ee775d1e-302b-4380-a2d3-97d900729684-4-300x200.jpg"},"large":{"file":"ee775d1e-302b-4380-a2d3-97d900729684-4-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":167399,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ee775d1e-302b-4380-a2d3-97d900729684-4-1024x683.jpg"},"thumbnail":{"file":"ee775d1e-302b-4380-a2d3-97d900729684-4-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":23161,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ee775d1e-302b-4380-a2d3-97d900729684-4-150x150.jpg"},"medium_large":{"file":"ee775d1e-302b-4380-a2d3-97d900729684-4-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":107286,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ee775d1e-302b-4380-a2d3-97d900729684-4-768x512.jpg"},"1536x1536":{"file":"ee775d1e-302b-4380-a2d3-97d900729684-4-1536x1024.jpg","width":1536,"height":1024,"mime-type":"image\/jpeg","filesize":322363,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ee775d1e-302b-4380-a2d3-97d900729684-4-1536x1024.jpg"},"2048x2048":{"file":"ee775d1e-302b-4380-a2d3-97d900729684-4-2048x1365.jpg","width":2048,"height":1365,"mime-type":"image\/jpeg","filesize":520615,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ee775d1e-302b-4380-a2d3-97d900729684-4-2048x1365.jpg"},"square":{"file":"ee775d1e-302b-4380-a2d3-97d900729684-4-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":68051,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ee775d1e-302b-4380-a2d3-97d900729684-4-450x450.jpg"},"property-large-image":{"file":"ee775d1e-302b-4380-a2d3-97d900729684-4-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":207995,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ee775d1e-302b-4380-a2d3-97d900729684-4-1170x780.jpg"},"post-thumbnail":{"file":"ee775d1e-302b-4380-a2d3-97d900729684-4-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":21198,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ee775d1e-302b-4380-a2d3-97d900729684-4-150x100.jpg"},"modern-property-child-slider":{"file":"ee775d1e-302b-4380-a2d3-97d900729684-4-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":99131,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ee775d1e-302b-4380-a2d3-97d900729684-4-680x510.jpg"},"property-thumb-image":{"file":"ee775d1e-302b-4380-a2d3-97d900729684-4-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":57234,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ee775d1e-302b-4380-a2d3-97d900729684-4-488x326.jpg"},"property-detail-video-image":{"file":"ee775d1e-302b-4380-a2d3-97d900729684-4-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":100750,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ee775d1e-302b-4380-a2d3-97d900729684-4-818x417.jpg"},"agent-image":{"file":"ee775d1e-302b-4380-a2d3-97d900729684-4-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":29397,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ee775d1e-302b-4380-a2d3-97d900729684-4-210x210.jpg"},"partners-logo":{"file":"ee775d1e-302b-4380-a2d3-97d900729684-4-600x2132.jpg","width":600,"height":2132,"mime-type":"image\/jpeg","filesize":234500,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ee775d1e-302b-4380-a2d3-97d900729684-4-600x2132.jpg"},"post-featured-image":{"file":"ee775d1e-302b-4380-a2d3-97d900729684-4-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":206191,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ee775d1e-302b-4380-a2d3-97d900729684-4-1240x720.jpg"}},"image_meta":{"aperture":"7.1","credit":"Christian Ribas","camera":"Canon EOS 5D Mark IV","caption":"","created_timestamp":"1749828398","copyright":"www.christianribas.es","focal_length":"29","iso":"200","shutter_speed":"0.1","title":"","orientation":"1","keywords":[]},"original_image":"ee775d1e-302b-4380-a2d3-97d900729684-4.jpg","ID":"913262","name":"ee775d1e-302b-4380-a2d3-97d900729684-4-scaled.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2022\/07\/ee775d1e-302b-4380-a2d3-97d900729684-4-scaled.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ee775d1e-302b-4380-a2d3-97d900729684-4-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ee775d1e-302b-4380-a2d3-97d900729684-4-scaled.jpg","title":"ee775d1e-302b-4380-a2d3-97d900729684-4","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ee775d1e-302b-4380-a2d3-97d900729684-4-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ee775d1e-302b-4380-a2d3-97d900729684-4-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ee775d1e-302b-4380-a2d3-97d900729684-4-210x210.jpg 210w"},{"width":150,"height":150,"file":"2022\/07\/a691ba24-a82f-49ed-849e-be84e2793d2c-4-scaled.jpg","filesize":675347,"sizes":{"medium":{"file":"a691ba24-a82f-49ed-849e-be84e2793d2c-4-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":32175,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/a691ba24-a82f-49ed-849e-be84e2793d2c-4-300x200.jpg"},"large":{"file":"a691ba24-a82f-49ed-849e-be84e2793d2c-4-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":150916,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/a691ba24-a82f-49ed-849e-be84e2793d2c-4-1024x683.jpg"},"thumbnail":{"file":"a691ba24-a82f-49ed-849e-be84e2793d2c-4-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":22855,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/a691ba24-a82f-49ed-849e-be84e2793d2c-4-150x150.jpg"},"medium_large":{"file":"a691ba24-a82f-49ed-849e-be84e2793d2c-4-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":97039,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/a691ba24-a82f-49ed-849e-be84e2793d2c-4-768x512.jpg"},"1536x1536":{"file":"a691ba24-a82f-49ed-849e-be84e2793d2c-4-1536x1024.jpg","width":1536,"height":1024,"mime-type":"image\/jpeg","filesize":286429,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/a691ba24-a82f-49ed-849e-be84e2793d2c-4-1536x1024.jpg"},"2048x2048":{"file":"a691ba24-a82f-49ed-849e-be84e2793d2c-4-2048x1365.jpg","width":2048,"height":1365,"mime-type":"image\/jpeg","filesize":463398,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/a691ba24-a82f-49ed-849e-be84e2793d2c-4-2048x1365.jpg"},"square":{"file":"a691ba24-a82f-49ed-849e-be84e2793d2c-4-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":62680,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/a691ba24-a82f-49ed-849e-be84e2793d2c-4-450x450.jpg"},"property-large-image":{"file":"a691ba24-a82f-49ed-849e-be84e2793d2c-4-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":185671,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/a691ba24-a82f-49ed-849e-be84e2793d2c-4-1170x780.jpg"},"post-thumbnail":{"file":"a691ba24-a82f-49ed-849e-be84e2793d2c-4-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":20990,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/a691ba24-a82f-49ed-849e-be84e2793d2c-4-150x100.jpg"},"modern-property-child-slider":{"file":"a691ba24-a82f-49ed-849e-be84e2793d2c-4-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":89893,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/a691ba24-a82f-49ed-849e-be84e2793d2c-4-680x510.jpg"},"property-thumb-image":{"file":"a691ba24-a82f-49ed-849e-be84e2793d2c-4-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":53238,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/a691ba24-a82f-49ed-849e-be84e2793d2c-4-488x326.jpg"},"property-detail-video-image":{"file":"a691ba24-a82f-49ed-849e-be84e2793d2c-4-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":88054,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/a691ba24-a82f-49ed-849e-be84e2793d2c-4-818x417.jpg"},"agent-image":{"file":"a691ba24-a82f-49ed-849e-be84e2793d2c-4-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":28465,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/a691ba24-a82f-49ed-849e-be84e2793d2c-4-210x210.jpg"},"partners-logo":{"file":"a691ba24-a82f-49ed-849e-be84e2793d2c-4-600x2132.jpg","width":600,"height":2132,"mime-type":"image\/jpeg","filesize":248597,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/a691ba24-a82f-49ed-849e-be84e2793d2c-4-600x2132.jpg"},"post-featured-image":{"file":"a691ba24-a82f-49ed-849e-be84e2793d2c-4-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":180720,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/a691ba24-a82f-49ed-849e-be84e2793d2c-4-1240x720.jpg"}},"image_meta":{"aperture":"11","credit":"Christian Ribas","camera":"Canon EOS 5D Mark IV","caption":"","created_timestamp":"1749828454","copyright":"www.christianribas.es","focal_length":"24","iso":"200","shutter_speed":"0.25","title":"","orientation":"1","keywords":[]},"original_image":"a691ba24-a82f-49ed-849e-be84e2793d2c-4.jpg","ID":"913266","name":"a691ba24-a82f-49ed-849e-be84e2793d2c-4-scaled.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2022\/07\/a691ba24-a82f-49ed-849e-be84e2793d2c-4-scaled.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/a691ba24-a82f-49ed-849e-be84e2793d2c-4-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/a691ba24-a82f-49ed-849e-be84e2793d2c-4-scaled.jpg","title":"a691ba24-a82f-49ed-849e-be84e2793d2c-4","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/a691ba24-a82f-49ed-849e-be84e2793d2c-4-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/a691ba24-a82f-49ed-849e-be84e2793d2c-4-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/a691ba24-a82f-49ed-849e-be84e2793d2c-4-210x210.jpg 210w"},{"width":150,"height":150,"file":"2022\/07\/ae987d5e-5720-430f-bd68-e2b1c1063c2e-4-scaled.jpg","filesize":578696,"sizes":{"medium":{"file":"ae987d5e-5720-430f-bd68-e2b1c1063c2e-4-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":31261,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ae987d5e-5720-430f-bd68-e2b1c1063c2e-4-300x200.jpg"},"large":{"file":"ae987d5e-5720-430f-bd68-e2b1c1063c2e-4-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":136631,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ae987d5e-5720-430f-bd68-e2b1c1063c2e-4-1024x683.jpg"},"thumbnail":{"file":"ae987d5e-5720-430f-bd68-e2b1c1063c2e-4-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":22105,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ae987d5e-5720-430f-bd68-e2b1c1063c2e-4-150x150.jpg"},"medium_large":{"file":"ae987d5e-5720-430f-bd68-e2b1c1063c2e-4-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":90717,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ae987d5e-5720-430f-bd68-e2b1c1063c2e-4-768x512.jpg"},"1536x1536":{"file":"ae987d5e-5720-430f-bd68-e2b1c1063c2e-4-1536x1024.jpg","width":1536,"height":1024,"mime-type":"image\/jpeg","filesize":252827,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ae987d5e-5720-430f-bd68-e2b1c1063c2e-4-1536x1024.jpg"},"2048x2048":{"file":"ae987d5e-5720-430f-bd68-e2b1c1063c2e-4-2048x1365.jpg","width":2048,"height":1365,"mime-type":"image\/jpeg","filesize":402229,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ae987d5e-5720-430f-bd68-e2b1c1063c2e-4-2048x1365.jpg"},"square":{"file":"ae987d5e-5720-430f-bd68-e2b1c1063c2e-4-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":56492,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ae987d5e-5720-430f-bd68-e2b1c1063c2e-4-450x450.jpg"},"property-large-image":{"file":"ae987d5e-5720-430f-bd68-e2b1c1063c2e-4-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":167282,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ae987d5e-5720-430f-bd68-e2b1c1063c2e-4-1170x780.jpg"},"post-thumbnail":{"file":"ae987d5e-5720-430f-bd68-e2b1c1063c2e-4-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":20592,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ae987d5e-5720-430f-bd68-e2b1c1063c2e-4-150x100.jpg"},"modern-property-child-slider":{"file":"ae987d5e-5720-430f-bd68-e2b1c1063c2e-4-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":82999,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ae987d5e-5720-430f-bd68-e2b1c1063c2e-4-680x510.jpg"},"property-thumb-image":{"file":"ae987d5e-5720-430f-bd68-e2b1c1063c2e-4-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":50946,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ae987d5e-5720-430f-bd68-e2b1c1063c2e-4-488x326.jpg"},"property-detail-video-image":{"file":"ae987d5e-5720-430f-bd68-e2b1c1063c2e-4-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":83814,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ae987d5e-5720-430f-bd68-e2b1c1063c2e-4-818x417.jpg"},"agent-image":{"file":"ae987d5e-5720-430f-bd68-e2b1c1063c2e-4-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":27129,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ae987d5e-5720-430f-bd68-e2b1c1063c2e-4-210x210.jpg"},"partners-logo":{"file":"ae987d5e-5720-430f-bd68-e2b1c1063c2e-4-600x2132.jpg","width":600,"height":2132,"mime-type":"image\/jpeg","filesize":184369,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ae987d5e-5720-430f-bd68-e2b1c1063c2e-4-600x2132.jpg"},"post-featured-image":{"file":"ae987d5e-5720-430f-bd68-e2b1c1063c2e-4-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":163596,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ae987d5e-5720-430f-bd68-e2b1c1063c2e-4-1240x720.jpg"}},"image_meta":{"aperture":"11","credit":"Christian Ribas","camera":"Canon EOS 5D Mark IV","caption":"","created_timestamp":"1749828592","copyright":"www.christianribas.es","focal_length":"20","iso":"200","shutter_speed":"0.2","title":"","orientation":"1","keywords":[]},"original_image":"ae987d5e-5720-430f-bd68-e2b1c1063c2e-4.jpg","ID":"913270","name":"ae987d5e-5720-430f-bd68-e2b1c1063c2e-4-scaled.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2022\/07\/ae987d5e-5720-430f-bd68-e2b1c1063c2e-4-scaled.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ae987d5e-5720-430f-bd68-e2b1c1063c2e-4-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ae987d5e-5720-430f-bd68-e2b1c1063c2e-4-scaled.jpg","title":"ae987d5e-5720-430f-bd68-e2b1c1063c2e-4","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ae987d5e-5720-430f-bd68-e2b1c1063c2e-4-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ae987d5e-5720-430f-bd68-e2b1c1063c2e-4-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ae987d5e-5720-430f-bd68-e2b1c1063c2e-4-210x210.jpg 210w"},{"width":150,"height":150,"file":"2022\/07\/8bcf6a07-cd16-47a0-9654-0d192a50425d-4-scaled.jpg","filesize":588409,"sizes":{"medium":{"file":"8bcf6a07-cd16-47a0-9654-0d192a50425d-4-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":31855,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/8bcf6a07-cd16-47a0-9654-0d192a50425d-4-300x200.jpg"},"large":{"file":"8bcf6a07-cd16-47a0-9654-0d192a50425d-4-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":141699,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/8bcf6a07-cd16-47a0-9654-0d192a50425d-4-1024x683.jpg"},"thumbnail":{"file":"8bcf6a07-cd16-47a0-9654-0d192a50425d-4-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":22619,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/8bcf6a07-cd16-47a0-9654-0d192a50425d-4-150x150.jpg"},"medium_large":{"file":"8bcf6a07-cd16-47a0-9654-0d192a50425d-4-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":92840,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/8bcf6a07-cd16-47a0-9654-0d192a50425d-4-768x512.jpg"},"1536x1536":{"file":"8bcf6a07-cd16-47a0-9654-0d192a50425d-4-1536x1024.jpg","width":1536,"height":1024,"mime-type":"image\/jpeg","filesize":261626,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/8bcf6a07-cd16-47a0-9654-0d192a50425d-4-1536x1024.jpg"},"2048x2048":{"file":"8bcf6a07-cd16-47a0-9654-0d192a50425d-4-2048x1365.jpg","width":2048,"height":1365,"mime-type":"image\/jpeg","filesize":412174,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/8bcf6a07-cd16-47a0-9654-0d192a50425d-4-2048x1365.jpg"},"square":{"file":"8bcf6a07-cd16-47a0-9654-0d192a50425d-4-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":60199,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/8bcf6a07-cd16-47a0-9654-0d192a50425d-4-450x450.jpg"},"property-large-image":{"file":"8bcf6a07-cd16-47a0-9654-0d192a50425d-4-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":173271,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/8bcf6a07-cd16-47a0-9654-0d192a50425d-4-1170x780.jpg"},"post-thumbnail":{"file":"8bcf6a07-cd16-47a0-9654-0d192a50425d-4-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":20618,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/8bcf6a07-cd16-47a0-9654-0d192a50425d-4-150x100.jpg"},"modern-property-child-slider":{"file":"8bcf6a07-cd16-47a0-9654-0d192a50425d-4-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":86784,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/8bcf6a07-cd16-47a0-9654-0d192a50425d-4-680x510.jpg"},"property-thumb-image":{"file":"8bcf6a07-cd16-47a0-9654-0d192a50425d-4-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":52420,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/8bcf6a07-cd16-47a0-9654-0d192a50425d-4-488x326.jpg"},"property-detail-video-image":{"file":"8bcf6a07-cd16-47a0-9654-0d192a50425d-4-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":82083,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/8bcf6a07-cd16-47a0-9654-0d192a50425d-4-818x417.jpg"},"agent-image":{"file":"8bcf6a07-cd16-47a0-9654-0d192a50425d-4-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":28263,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/8bcf6a07-cd16-47a0-9654-0d192a50425d-4-210x210.jpg"},"partners-logo":{"file":"8bcf6a07-cd16-47a0-9654-0d192a50425d-4-600x2132.jpg","width":600,"height":2132,"mime-type":"image\/jpeg","filesize":218640,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/8bcf6a07-cd16-47a0-9654-0d192a50425d-4-600x2132.jpg"},"post-featured-image":{"file":"8bcf6a07-cd16-47a0-9654-0d192a50425d-4-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":166220,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/8bcf6a07-cd16-47a0-9654-0d192a50425d-4-1240x720.jpg"}},"image_meta":{"aperture":"8","credit":"Christian Ribas","camera":"Canon EOS 5D Mark IV","caption":"","created_timestamp":"1749828651","copyright":"www.christianribas.es","focal_length":"33","iso":"200","shutter_speed":"0.1","title":"","orientation":"1","keywords":[]},"original_image":"8bcf6a07-cd16-47a0-9654-0d192a50425d-4.jpg","ID":"913274","name":"8bcf6a07-cd16-47a0-9654-0d192a50425d-4-scaled.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2022\/07\/8bcf6a07-cd16-47a0-9654-0d192a50425d-4-scaled.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/8bcf6a07-cd16-47a0-9654-0d192a50425d-4-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/8bcf6a07-cd16-47a0-9654-0d192a50425d-4-scaled.jpg","title":"8bcf6a07-cd16-47a0-9654-0d192a50425d-4","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/8bcf6a07-cd16-47a0-9654-0d192a50425d-4-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/8bcf6a07-cd16-47a0-9654-0d192a50425d-4-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/8bcf6a07-cd16-47a0-9654-0d192a50425d-4-210x210.jpg 210w"},{"width":150,"height":150,"file":"2022\/07\/ba950bca-417d-42a8-87bb-8608669a4ff7-4-scaled.jpg","filesize":579133,"sizes":{"medium":{"file":"ba950bca-417d-42a8-87bb-8608669a4ff7-4-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":28706,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ba950bca-417d-42a8-87bb-8608669a4ff7-4-300x200.jpg"},"large":{"file":"ba950bca-417d-42a8-87bb-8608669a4ff7-4-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":138754,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ba950bca-417d-42a8-87bb-8608669a4ff7-4-1024x683.jpg"},"thumbnail":{"file":"ba950bca-417d-42a8-87bb-8608669a4ff7-4-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":20877,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ba950bca-417d-42a8-87bb-8608669a4ff7-4-150x150.jpg"},"medium_large":{"file":"ba950bca-417d-42a8-87bb-8608669a4ff7-4-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":89715,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ba950bca-417d-42a8-87bb-8608669a4ff7-4-768x512.jpg"},"1536x1536":{"file":"ba950bca-417d-42a8-87bb-8608669a4ff7-4-1536x1024.jpg","width":1536,"height":1024,"mime-type":"image\/jpeg","filesize":260919,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ba950bca-417d-42a8-87bb-8608669a4ff7-4-1536x1024.jpg"},"2048x2048":{"file":"ba950bca-417d-42a8-87bb-8608669a4ff7-4-2048x1365.jpg","width":2048,"height":1365,"mime-type":"image\/jpeg","filesize":410459,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ba950bca-417d-42a8-87bb-8608669a4ff7-4-2048x1365.jpg"},"square":{"file":"ba950bca-417d-42a8-87bb-8608669a4ff7-4-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":55389,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ba950bca-417d-42a8-87bb-8608669a4ff7-4-450x450.jpg"},"property-large-image":{"file":"ba950bca-417d-42a8-87bb-8608669a4ff7-4-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":171686,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ba950bca-417d-42a8-87bb-8608669a4ff7-4-1170x780.jpg"},"post-thumbnail":{"file":"ba950bca-417d-42a8-87bb-8608669a4ff7-4-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":19395,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ba950bca-417d-42a8-87bb-8608669a4ff7-4-150x100.jpg"},"modern-property-child-slider":{"file":"ba950bca-417d-42a8-87bb-8608669a4ff7-4-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":82020,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ba950bca-417d-42a8-87bb-8608669a4ff7-4-680x510.jpg"},"property-thumb-image":{"file":"ba950bca-417d-42a8-87bb-8608669a4ff7-4-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":48547,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ba950bca-417d-42a8-87bb-8608669a4ff7-4-488x326.jpg"},"property-detail-video-image":{"file":"ba950bca-417d-42a8-87bb-8608669a4ff7-4-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":80984,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ba950bca-417d-42a8-87bb-8608669a4ff7-4-818x417.jpg"},"agent-image":{"file":"ba950bca-417d-42a8-87bb-8608669a4ff7-4-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":25497,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ba950bca-417d-42a8-87bb-8608669a4ff7-4-210x210.jpg"},"partners-logo":{"file":"ba950bca-417d-42a8-87bb-8608669a4ff7-4-600x2132.jpg","width":600,"height":2132,"mime-type":"image\/jpeg","filesize":194824,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ba950bca-417d-42a8-87bb-8608669a4ff7-4-600x2132.jpg"},"post-featured-image":{"file":"ba950bca-417d-42a8-87bb-8608669a4ff7-4-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":166419,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ba950bca-417d-42a8-87bb-8608669a4ff7-4-1240x720.jpg"}},"image_meta":{"aperture":"10","credit":"Christian Ribas","camera":"Canon EOS 5D Mark IV","caption":"","created_timestamp":"1749828824","copyright":"www.christianribas.es","focal_length":"17","iso":"100","shutter_speed":"0.02","title":"","orientation":"1","keywords":[]},"original_image":"ba950bca-417d-42a8-87bb-8608669a4ff7-4.jpg","ID":"913278","name":"ba950bca-417d-42a8-87bb-8608669a4ff7-4-scaled.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2022\/07\/ba950bca-417d-42a8-87bb-8608669a4ff7-4-scaled.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ba950bca-417d-42a8-87bb-8608669a4ff7-4-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ba950bca-417d-42a8-87bb-8608669a4ff7-4-scaled.jpg","title":"ba950bca-417d-42a8-87bb-8608669a4ff7-4","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ba950bca-417d-42a8-87bb-8608669a4ff7-4-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ba950bca-417d-42a8-87bb-8608669a4ff7-4-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/ba950bca-417d-42a8-87bb-8608669a4ff7-4-210x210.jpg 210w"},{"width":150,"height":150,"file":"2022\/07\/31913954-ec66-4439-b23c-e42cfff5003a-4-scaled.jpg","filesize":687472,"sizes":{"medium":{"file":"31913954-ec66-4439-b23c-e42cfff5003a-4-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":33277,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/31913954-ec66-4439-b23c-e42cfff5003a-4-300x200.jpg"},"large":{"file":"31913954-ec66-4439-b23c-e42cfff5003a-4-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":164144,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/31913954-ec66-4439-b23c-e42cfff5003a-4-1024x683.jpg"},"thumbnail":{"file":"31913954-ec66-4439-b23c-e42cfff5003a-4-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":22439,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/31913954-ec66-4439-b23c-e42cfff5003a-4-150x150.jpg"},"medium_large":{"file":"31913954-ec66-4439-b23c-e42cfff5003a-4-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":106049,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/31913954-ec66-4439-b23c-e42cfff5003a-4-768x512.jpg"},"1536x1536":{"file":"31913954-ec66-4439-b23c-e42cfff5003a-4-1536x1024.jpg","width":1536,"height":1024,"mime-type":"image\/jpeg","filesize":308050,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/31913954-ec66-4439-b23c-e42cfff5003a-4-1536x1024.jpg"},"2048x2048":{"file":"31913954-ec66-4439-b23c-e42cfff5003a-4-2048x1365.jpg","width":2048,"height":1365,"mime-type":"image\/jpeg","filesize":486778,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/31913954-ec66-4439-b23c-e42cfff5003a-4-2048x1365.jpg"},"square":{"file":"31913954-ec66-4439-b23c-e42cfff5003a-4-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":63133,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/31913954-ec66-4439-b23c-e42cfff5003a-4-450x450.jpg"},"property-large-image":{"file":"31913954-ec66-4439-b23c-e42cfff5003a-4-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":202725,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/31913954-ec66-4439-b23c-e42cfff5003a-4-1170x780.jpg"},"post-thumbnail":{"file":"31913954-ec66-4439-b23c-e42cfff5003a-4-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":20946,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/31913954-ec66-4439-b23c-e42cfff5003a-4-150x100.jpg"},"modern-property-child-slider":{"file":"31913954-ec66-4439-b23c-e42cfff5003a-4-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":94315,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/31913954-ec66-4439-b23c-e42cfff5003a-4-680x510.jpg"},"property-thumb-image":{"file":"31913954-ec66-4439-b23c-e42cfff5003a-4-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":56930,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/31913954-ec66-4439-b23c-e42cfff5003a-4-488x326.jpg"},"property-detail-video-image":{"file":"31913954-ec66-4439-b23c-e42cfff5003a-4-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":98798,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/31913954-ec66-4439-b23c-e42cfff5003a-4-818x417.jpg"},"agent-image":{"file":"31913954-ec66-4439-b23c-e42cfff5003a-4-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":28251,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/31913954-ec66-4439-b23c-e42cfff5003a-4-210x210.jpg"},"partners-logo":{"file":"31913954-ec66-4439-b23c-e42cfff5003a-4-600x2132.jpg","width":600,"height":2132,"mime-type":"image\/jpeg","filesize":208676,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/31913954-ec66-4439-b23c-e42cfff5003a-4-600x2132.jpg"},"post-featured-image":{"file":"31913954-ec66-4439-b23c-e42cfff5003a-4-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":199721,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/31913954-ec66-4439-b23c-e42cfff5003a-4-1240x720.jpg"}},"image_meta":{"aperture":"11","credit":"Christian Ribas","camera":"Canon EOS 5D Mark IV","caption":"","created_timestamp":"1749828874","copyright":"www.christianribas.es","focal_length":"17","iso":"100","shutter_speed":"0.016666666666667","title":"","orientation":"1","keywords":[]},"original_image":"31913954-ec66-4439-b23c-e42cfff5003a-4.jpg","ID":"913282","name":"31913954-ec66-4439-b23c-e42cfff5003a-4-scaled.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2022\/07\/31913954-ec66-4439-b23c-e42cfff5003a-4-scaled.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/31913954-ec66-4439-b23c-e42cfff5003a-4-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/31913954-ec66-4439-b23c-e42cfff5003a-4-scaled.jpg","title":"31913954-ec66-4439-b23c-e42cfff5003a-4","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/31913954-ec66-4439-b23c-e42cfff5003a-4-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/31913954-ec66-4439-b23c-e42cfff5003a-4-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2022\/07\/31913954-ec66-4439-b23c-e42cfff5003a-4-210x210.jpg 210w"}],"REAL_HOMES_change_gallery_slider_type":"0","REAL_HOMES_gallery_slider_type":"thumb-on-right","inspiry_floor_plans":[],"inspiry_video_group":[],"REAL_HOMES_360_virtual_tour":"","REAL_HOMES_tour_video_url":"","REAL_HOMES_tour_video_image":[],"REAL_HOMES_agent_display_option":"agent_info","REAL_HOMES_agents":["388607"],"REAL_HOMES_energy_class":"E","REAL_HOMES_energy_performance":"","REAL_HOMES_epc_current_rating":"","REAL_HOMES_epc_potential_rating":"","ere_property_schedule_tour":"global","ere_property_schedule_time_slots":"","ere_property_schedule_description":"","REAL_HOMES_sticky":"0","inspiry_property_label":"","inspiry_property_label_color":"","inspiry_property_tax":"","inspiry_additional_fee":"","REAL_HOMES_attachments":[],"inspiry_property_owner_name":"","inspiry_property_owner_contact":"","inspiry_property_owner_address":"","REAL_HOMES_property_private_note":"","inspiry_message_to_reviewer":"","REAL_HOMES_add_in_slider":"no","REAL_HOMES_slider_image":[],"REAL_HOMES_page_banner_image":[],"REAL_HOMES_hide_property_advance_search":"0"},"_links":{"self":[{"href":"https:\/\/www.locabarcelona.com\/fr\/wp-json\/wp\/v2\/property\/457497"}],"collection":[{"href":"https:\/\/www.locabarcelona.com\/fr\/wp-json\/wp\/v2\/property"}],"about":[{"href":"https:\/\/www.locabarcelona.com\/fr\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/www.locabarcelona.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.locabarcelona.com\/fr\/wp-json\/wp\/v2\/comments?post=457497"}],"version-history":[{"count":15,"href":"https:\/\/www.locabarcelona.com\/fr\/wp-json\/wp\/v2\/property\/457497\/revisions"}],"predecessor-version":[{"id":1042451,"href":"https:\/\/www.locabarcelona.com\/fr\/wp-json\/wp\/v2\/property\/457497\/revisions\/1042451"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.locabarcelona.com\/fr\/wp-json\/wp\/v2\/media\/913166"}],"wp:attachment":[{"href":"https:\/\/www.locabarcelona.com\/fr\/wp-json\/wp\/v2\/media?parent=457497"}],"wp:term":[{"taxonomy":"property-feature","embeddable":true,"href":"https:\/\/www.locabarcelona.com\/fr\/wp-json\/wp\/v2\/property-feature?post=457497"},{"taxonomy":"property-type","embeddable":true,"href":"https:\/\/www.locabarcelona.com\/fr\/wp-json\/wp\/v2\/property-type?post=457497"},{"taxonomy":"property-city","embeddable":true,"href":"https:\/\/www.locabarcelona.com\/fr\/wp-json\/wp\/v2\/property-city?post=457497"},{"taxonomy":"property-status","embeddable":true,"href":"https:\/\/www.locabarcelona.com\/fr\/wp-json\/wp\/v2\/property-status?post=457497"},{"taxonomy":"property-sale-label","embeddable":true,"href":"https:\/\/www.locabarcelona.com\/fr\/wp-json\/wp\/v2\/property-sale-labels?post=457497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}