{"id":426980,"date":"2021-11-30T10:47:04","date_gmt":"2021-11-30T09:47:04","guid":{"rendered":"https:\/\/www.locabarcelona.com\/?post_type=property&#038;p=426980"},"modified":"2026-07-15T15:02:04","modified_gmt":"2026-07-15T13:02:04","slug":"modern-loft-for-rent-with-balcony","status":"publish","type":"property","link":"https:\/\/www.locabarcelona.com\/en\/property\/modern-loft-for-rent-with-balcony\/","title":{"rendered":"Modern loft for rent with balcony"},"content":{"rendered":"<p>AICAT Registration Number 11525<br \/>API Number A13529<br \/>State Reference Index: 770.7 \u20ac\/month.<br \/>The apartment is in perfect condition.<br \/>Status within the last 5 years: Not rented.<br \/>Annual IBI: 276.75 \u20ac<br \/>Ordinary community expenses 63.89 \u20ac.<br \/>Certificate of occupancy: CHB05567919001<br \/>Energy certificate with E . Registration CLZQ2HG4R .<br \/>Annual increase \u2013 IPC.<br \/>The owner is  a large owner<br \/><strong>NRU:<\/strong> in process<\/p>\n<p>This charming one-bedroom apartment is available for short-term rental, making it an ideal choice for your stay in the heart of Barcelona. With 36 square meters of living space, this cozy apartment is located on the second floor, accessible via a staircase, and offers a delightful retreat for your visit.<\/p>\n<p>The apartment features a well-lit bedroom, perfect for unwinding after a day of working. Adjacent to the bedroom, you&#8217;ll find a clean and convenient bathroom. Additionally, the apartment boasts a lovely balcony where you can enjoy your morning coffee or soak in the city&#8217;s atmosphere. The dining room offers a cozy space to enjoy home-cooked meals or gatherings with friends. The bathrooms are equipped with all the necessary amenities, and the kitchen features modern appliances, including oven, dishwasher and washing machine. In terms of equipment, this apartment does not disappoint. In addition to the aforementioned appliances, there is also a comfortable sofa in the living room, ideal for relaxing and watching movies. Wifi is available throughout the apartment, ensuring that you are always connected<\/p>\n<p>Situated in the neighborhood of Raval, this apartment is within easy reach of shops, restaurants, and popular tourist attractions. Whether you&#8217;re in town for business or study, this short-term rental provides a comfortable and convenient base to make the most of your Barcelona experience. Don&#8217;t miss the opportunity to enjoy this gem during your stay in this beautiful city.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AICAT Registration Number 11525API Number A13529State Reference Index: 770.7 \u20ac\/month.The apartment is in perfect condition.Status within the last 5 years: Not rented.Annual IBI: 276.75 \u20acOrdinary community expenses 63.89 \u20ac.Certificate of occupancy: CHB05567919001Energy certificate with E . Registration CLZQ2HG4R .Annual increase \u2013 IPC.The owner is a large ownerNRU: in process This charming one-bedroom apartment is available&#8230;<\/p>\n","protected":false},"author":358,"featured_media":689723,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","property-feature":[428,462,463,429,16,17,188,123,128,23,39,467,469,470,473,26,471,29,464,430,431,475,465,479],"property-type":[40],"property-city":[28,127],"property-status":[52],"property-sale-labels":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.6 (Yoast SEO v22.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Modern loft for rent with balcony | Locabarcelona<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.locabarcelona.com\/en\/property\/modern-loft-for-rent-with-balcony\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Modern loft for rent with balcony | Locabarcelona\" \/>\n<meta property=\"og:description\" content=\"AICAT Registration Number 11525API Number A13529State Reference Index: 770.7 \u20ac\/month.The apartment is in perfect condition.Status within the last 5 years: Not rented.Annual IBI: 276.75 \u20acOrdinary community expenses 63.89 \u20ac.Certificate of occupancy: CHB05567919001Energy certificate with E . Registration CLZQ2HG4R .Annual increase \u2013 IPC.The owner is a large ownerNRU: in process This charming one-bedroom apartment is available...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.locabarcelona.com\/en\/property\/modern-loft-for-rent-with-balcony\/\" \/>\n<meta property=\"og:site_name\" content=\"Locabarcelona\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-15T13:02:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b426fc75-8527-4161-8683-6daece35b843.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.locabarcelona.com\/en\/property\/modern-loft-for-rent-with-balcony\/\",\"url\":\"https:\/\/www.locabarcelona.com\/en\/property\/modern-loft-for-rent-with-balcony\/\",\"name\":\"Modern loft for rent with balcony | Locabarcelona\",\"isPartOf\":{\"@id\":\"https:\/\/www.locabarcelona.com\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.locabarcelona.com\/en\/property\/modern-loft-for-rent-with-balcony\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.locabarcelona.com\/en\/property\/modern-loft-for-rent-with-balcony\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b426fc75-8527-4161-8683-6daece35b843.jpg\",\"datePublished\":\"2021-11-30T09:47:04+00:00\",\"dateModified\":\"2026-07-15T13:02:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.locabarcelona.com\/en\/property\/modern-loft-for-rent-with-balcony\/#breadcrumb\"},\"inLanguage\":\"en\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.locabarcelona.com\/en\/property\/modern-loft-for-rent-with-balcony\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\/\/www.locabarcelona.com\/en\/property\/modern-loft-for-rent-with-balcony\/#primaryimage\",\"url\":\"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b426fc75-8527-4161-8683-6daece35b843.jpg\",\"contentUrl\":\"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b426fc75-8527-4161-8683-6daece35b843.jpg\",\"width\":1500,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.locabarcelona.com\/en\/property\/modern-loft-for-rent-with-balcony\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.locabarcelona.com\/en\/home-2\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Properties\",\"item\":\"https:\/\/www.locabarcelona.com\/fr\/appartement\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Modern loft for rent with balcony\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.locabarcelona.com\/en\/#website\",\"url\":\"https:\/\/www.locabarcelona.com\/en\/\",\"name\":\"Loca Barcelona\",\"description\":\"Real Estate Services\",\"publisher\":{\"@id\":\"https:\/\/www.locabarcelona.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.locabarcelona.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.locabarcelona.com\/en\/#organization\",\"name\":\"Loca Barcelona\",\"url\":\"https:\/\/www.locabarcelona.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en\",\"@id\":\"https:\/\/www.locabarcelona.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/10\/logo_locabarcelona_small.png\",\"contentUrl\":\"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/10\/logo_locabarcelona_small.png\",\"width\":250,\"height\":149,\"caption\":\"Loca Barcelona\"},\"image\":{\"@id\":\"https:\/\/www.locabarcelona.com\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Modern loft for rent with balcony | Locabarcelona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.locabarcelona.com\/en\/property\/modern-loft-for-rent-with-balcony\/","og_locale":"en_US","og_type":"article","og_title":"Modern loft for rent with balcony | Locabarcelona","og_description":"AICAT Registration Number 11525API Number A13529State Reference Index: 770.7 \u20ac\/month.The apartment is in perfect condition.Status within the last 5 years: Not rented.Annual IBI: 276.75 \u20acOrdinary community expenses 63.89 \u20ac.Certificate of occupancy: CHB05567919001Energy certificate with E . Registration CLZQ2HG4R .Annual increase \u2013 IPC.The owner is a large ownerNRU: in process This charming one-bedroom apartment is available...","og_url":"https:\/\/www.locabarcelona.com\/en\/property\/modern-loft-for-rent-with-balcony\/","og_site_name":"Locabarcelona","article_modified_time":"2026-07-15T13:02:04+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b426fc75-8527-4161-8683-6daece35b843.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.locabarcelona.com\/en\/property\/modern-loft-for-rent-with-balcony\/","url":"https:\/\/www.locabarcelona.com\/en\/property\/modern-loft-for-rent-with-balcony\/","name":"Modern loft for rent with balcony | Locabarcelona","isPartOf":{"@id":"https:\/\/www.locabarcelona.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.locabarcelona.com\/en\/property\/modern-loft-for-rent-with-balcony\/#primaryimage"},"image":{"@id":"https:\/\/www.locabarcelona.com\/en\/property\/modern-loft-for-rent-with-balcony\/#primaryimage"},"thumbnailUrl":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b426fc75-8527-4161-8683-6daece35b843.jpg","datePublished":"2021-11-30T09:47:04+00:00","dateModified":"2026-07-15T13:02:04+00:00","breadcrumb":{"@id":"https:\/\/www.locabarcelona.com\/en\/property\/modern-loft-for-rent-with-balcony\/#breadcrumb"},"inLanguage":"en","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.locabarcelona.com\/en\/property\/modern-loft-for-rent-with-balcony\/"]}]},{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/www.locabarcelona.com\/en\/property\/modern-loft-for-rent-with-balcony\/#primaryimage","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b426fc75-8527-4161-8683-6daece35b843.jpg","contentUrl":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b426fc75-8527-4161-8683-6daece35b843.jpg","width":1500,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.locabarcelona.com\/en\/property\/modern-loft-for-rent-with-balcony\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.locabarcelona.com\/en\/home-2\/"},{"@type":"ListItem","position":2,"name":"Properties","item":"https:\/\/www.locabarcelona.com\/fr\/appartement\/"},{"@type":"ListItem","position":3,"name":"Modern loft for rent with balcony"}]},{"@type":"WebSite","@id":"https:\/\/www.locabarcelona.com\/en\/#website","url":"https:\/\/www.locabarcelona.com\/en\/","name":"Loca Barcelona","description":"Real Estate Services","publisher":{"@id":"https:\/\/www.locabarcelona.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.locabarcelona.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en"},{"@type":"Organization","@id":"https:\/\/www.locabarcelona.com\/en\/#organization","name":"Loca Barcelona","url":"https:\/\/www.locabarcelona.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en","@id":"https:\/\/www.locabarcelona.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/10\/logo_locabarcelona_small.png","contentUrl":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/10\/logo_locabarcelona_small.png","width":250,"height":149,"caption":"Loca Barcelona"},"image":{"@id":"https:\/\/www.locabarcelona.com\/en\/#\/schema\/logo\/image\/"}}]}},"property_meta":{"REAL_HOMES_property_price":"889.6525","REAL_HOMES_property_old_price":"","REAL_HOMES_property_price_prefix":"","REAL_HOMES_property_price_postfix":"","REAL_HOMES_property_size":"36","REAL_HOMES_property_size_postfix":"m2","REAL_HOMES_property_lot_size":"","REAL_HOMES_property_lot_size_postfix":"","REAL_HOMES_property_bedrooms":"1","REAL_HOMES_property_bathrooms":"1","REAL_HOMES_property_garage":"","REAL_HOMES_property_id":"TA2SAP232","REAL_HOMES_property_floors":"2","REAL_HOMES_Lift":"0","REAL_HOMES_Wifi_included":"1","REAL_HOMES_Wifi_type":"Fiber 600MB","REAL_HOMES_public_address":"Carrer de Sant Pau","REAL_HOMES_underground_station":"Metro Parallel","REAL_HOMES_Availability":"1","REAL_HOMES_property_startdate_override":"0","REAL_HOMES_property_startdate":"2026-12-24","REAL_HOMES_property_enddate":"","REAL_HOMES_property_starthour":"","REAL_HOMES_property_endhour":"","REAL_HOMES_property_deposit":"1739.305","REAL_HOMES_property_itp":"0","REAL_HOMES_property_agencyfee_3months":"0","REAL_HOMES_property_agencyfee_5months":"0","REAL_HOMES_property_agencyfee_11months":"0","REAL_HOMES_property_agencyfee_long_term":"","REAL_HOMES_property_vat":"0","REAL_HOMES_property_year_built":"","REAL_HOMES_featured":"0","REAL_HOMES_additional_details_list":[],"REAL_HOMES_property_location":{"latitude":"41.3764419","longitude":"2.1691245","zoom":"14"},"REAL_HOMES_property_address":"Barcelona","REAL_HOMES_property_map":"0","REAL_HOMES_property_images":[{"width":150,"height":150,"file":"2021\/11\/b426fc75-8527-4161-8683-6daece35b843-1.jpg","filesize":194083,"sizes":{"medium":{"file":"b426fc75-8527-4161-8683-6daece35b843-1-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":24012,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b426fc75-8527-4161-8683-6daece35b843-1-300x200.jpg"},"large":{"file":"b426fc75-8527-4161-8683-6daece35b843-1-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":119644,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b426fc75-8527-4161-8683-6daece35b843-1-1024x683.jpg"},"thumbnail":{"file":"b426fc75-8527-4161-8683-6daece35b843-1-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":18038,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b426fc75-8527-4161-8683-6daece35b843-1-150x150.jpg"},"medium_large":{"file":"b426fc75-8527-4161-8683-6daece35b843-1-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":74451,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b426fc75-8527-4161-8683-6daece35b843-1-768x512.jpg"},"square":{"file":"b426fc75-8527-4161-8683-6daece35b843-1-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":51591,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b426fc75-8527-4161-8683-6daece35b843-1-450x450.jpg"},"property-large-image":{"file":"b426fc75-8527-4161-8683-6daece35b843-1-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":150870,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b426fc75-8527-4161-8683-6daece35b843-1-1170x780.jpg"},"post-thumbnail":{"file":"b426fc75-8527-4161-8683-6daece35b843-1-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":16048,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b426fc75-8527-4161-8683-6daece35b843-1-150x100.jpg"},"modern-property-child-slider":{"file":"b426fc75-8527-4161-8683-6daece35b843-1-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":70305,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b426fc75-8527-4161-8683-6daece35b843-1-680x510.jpg"},"property-thumb-image":{"file":"b426fc75-8527-4161-8683-6daece35b843-1-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":39931,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b426fc75-8527-4161-8683-6daece35b843-1-488x326.jpg"},"property-detail-video-image":{"file":"b426fc75-8527-4161-8683-6daece35b843-1-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":70065,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b426fc75-8527-4161-8683-6daece35b843-1-818x417.jpg"},"agent-image":{"file":"b426fc75-8527-4161-8683-6daece35b843-1-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":22523,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b426fc75-8527-4161-8683-6daece35b843-1-210x210.jpg"},"partners-logo":{"file":"b426fc75-8527-4161-8683-6daece35b843-1-600x1000.jpg","width":600,"height":1000,"mime-type":"image\/jpeg","filesize":130281,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b426fc75-8527-4161-8683-6daece35b843-1-600x1000.jpg"},"post-featured-image":{"file":"b426fc75-8527-4161-8683-6daece35b843-1-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":149853,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b426fc75-8527-4161-8683-6daece35b843-1-1240x720.jpg"}},"image_meta":{"aperture":"6.7","credit":"","camera":"Canon EOS 6D","caption":"","created_timestamp":"1638189015","copyright":"","focal_length":"16","iso":"200","shutter_speed":"0.033333333333333","title":"","orientation":"1","keywords":[]},"ID":"689727","name":"b426fc75-8527-4161-8683-6daece35b843-1.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2021\/11\/b426fc75-8527-4161-8683-6daece35b843-1.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b426fc75-8527-4161-8683-6daece35b843-1-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b426fc75-8527-4161-8683-6daece35b843-1.jpg","title":"b426fc75-8527-4161-8683-6daece35b843-1","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b426fc75-8527-4161-8683-6daece35b843-1-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b426fc75-8527-4161-8683-6daece35b843-1-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b426fc75-8527-4161-8683-6daece35b843-1-210x210.jpg 210w"},{"width":150,"height":150,"file":"2021\/11\/8ce3ca60-e25d-4afa-8152-2e913518f552.jpg","filesize":211550,"sizes":{"medium":{"file":"8ce3ca60-e25d-4afa-8152-2e913518f552-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":24144,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/8ce3ca60-e25d-4afa-8152-2e913518f552-300x200.jpg"},"large":{"file":"8ce3ca60-e25d-4afa-8152-2e913518f552-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":125230,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/8ce3ca60-e25d-4afa-8152-2e913518f552-1024x683.jpg"},"thumbnail":{"file":"8ce3ca60-e25d-4afa-8152-2e913518f552-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":17417,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/8ce3ca60-e25d-4afa-8152-2e913518f552-150x150.jpg"},"medium_large":{"file":"8ce3ca60-e25d-4afa-8152-2e913518f552-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":77444,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/8ce3ca60-e25d-4afa-8152-2e913518f552-768x512.jpg"},"square":{"file":"8ce3ca60-e25d-4afa-8152-2e913518f552-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":47514,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/8ce3ca60-e25d-4afa-8152-2e913518f552-450x450.jpg"},"property-large-image":{"file":"8ce3ca60-e25d-4afa-8152-2e913518f552-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":157987,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/8ce3ca60-e25d-4afa-8152-2e913518f552-1170x780.jpg"},"post-thumbnail":{"file":"8ce3ca60-e25d-4afa-8152-2e913518f552-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":16053,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/8ce3ca60-e25d-4afa-8152-2e913518f552-150x100.jpg"},"modern-property-child-slider":{"file":"8ce3ca60-e25d-4afa-8152-2e913518f552-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":69819,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/8ce3ca60-e25d-4afa-8152-2e913518f552-680x510.jpg"},"property-thumb-image":{"file":"8ce3ca60-e25d-4afa-8152-2e913518f552-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":40655,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/8ce3ca60-e25d-4afa-8152-2e913518f552-488x326.jpg"},"property-detail-video-image":{"file":"8ce3ca60-e25d-4afa-8152-2e913518f552-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":69787,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/8ce3ca60-e25d-4afa-8152-2e913518f552-818x417.jpg"},"agent-image":{"file":"8ce3ca60-e25d-4afa-8152-2e913518f552-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":21459,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/8ce3ca60-e25d-4afa-8152-2e913518f552-210x210.jpg"},"partners-logo":{"file":"8ce3ca60-e25d-4afa-8152-2e913518f552-600x1000.jpg","width":600,"height":1000,"mime-type":"image\/jpeg","filesize":111970,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/8ce3ca60-e25d-4afa-8152-2e913518f552-600x1000.jpg"},"post-featured-image":{"file":"8ce3ca60-e25d-4afa-8152-2e913518f552-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":155079,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/8ce3ca60-e25d-4afa-8152-2e913518f552-1240x720.jpg"}},"image_meta":{"aperture":"6.7","credit":"","camera":"Canon EOS 6D","caption":"","created_timestamp":"1638188935","copyright":"","focal_length":"16","iso":"250","shutter_speed":"0.05","title":"","orientation":"1","keywords":[]},"ID":"689731","name":"8ce3ca60-e25d-4afa-8152-2e913518f552.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2021\/11\/8ce3ca60-e25d-4afa-8152-2e913518f552.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/8ce3ca60-e25d-4afa-8152-2e913518f552-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/8ce3ca60-e25d-4afa-8152-2e913518f552.jpg","title":"8ce3ca60-e25d-4afa-8152-2e913518f552","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/8ce3ca60-e25d-4afa-8152-2e913518f552-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/8ce3ca60-e25d-4afa-8152-2e913518f552-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/8ce3ca60-e25d-4afa-8152-2e913518f552-210x210.jpg 210w"},{"width":150,"height":150,"file":"2021\/11\/a9ad3f65-21a5-4b44-8391-823125015e2e.jpg","filesize":141528,"sizes":{"medium":{"file":"a9ad3f65-21a5-4b44-8391-823125015e2e-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":23401,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/a9ad3f65-21a5-4b44-8391-823125015e2e-300x200.jpg"},"large":{"file":"a9ad3f65-21a5-4b44-8391-823125015e2e-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":97461,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/a9ad3f65-21a5-4b44-8391-823125015e2e-1024x683.jpg"},"thumbnail":{"file":"a9ad3f65-21a5-4b44-8391-823125015e2e-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":16803,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/a9ad3f65-21a5-4b44-8391-823125015e2e-150x150.jpg"},"medium_large":{"file":"a9ad3f65-21a5-4b44-8391-823125015e2e-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":64213,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/a9ad3f65-21a5-4b44-8391-823125015e2e-768x512.jpg"},"square":{"file":"a9ad3f65-21a5-4b44-8391-823125015e2e-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":36991,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/a9ad3f65-21a5-4b44-8391-823125015e2e-450x450.jpg"},"property-large-image":{"file":"a9ad3f65-21a5-4b44-8391-823125015e2e-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":118629,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/a9ad3f65-21a5-4b44-8391-823125015e2e-1170x780.jpg"},"post-thumbnail":{"file":"a9ad3f65-21a5-4b44-8391-823125015e2e-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":16144,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/a9ad3f65-21a5-4b44-8391-823125015e2e-150x100.jpg"},"modern-property-child-slider":{"file":"a9ad3f65-21a5-4b44-8391-823125015e2e-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":55158,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/a9ad3f65-21a5-4b44-8391-823125015e2e-680x510.jpg"},"property-thumb-image":{"file":"a9ad3f65-21a5-4b44-8391-823125015e2e-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":36963,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/a9ad3f65-21a5-4b44-8391-823125015e2e-488x326.jpg"},"property-detail-video-image":{"file":"a9ad3f65-21a5-4b44-8391-823125015e2e-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":57255,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/a9ad3f65-21a5-4b44-8391-823125015e2e-818x417.jpg"},"agent-image":{"file":"a9ad3f65-21a5-4b44-8391-823125015e2e-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":19851,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/a9ad3f65-21a5-4b44-8391-823125015e2e-210x210.jpg"},"partners-logo":{"file":"a9ad3f65-21a5-4b44-8391-823125015e2e-600x1000.jpg","width":600,"height":1000,"mime-type":"image\/jpeg","filesize":74452,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/a9ad3f65-21a5-4b44-8391-823125015e2e-600x1000.jpg"},"post-featured-image":{"file":"a9ad3f65-21a5-4b44-8391-823125015e2e-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":114225,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/a9ad3f65-21a5-4b44-8391-823125015e2e-1240x720.jpg"}},"image_meta":{"aperture":"6.7","credit":"","camera":"Canon EOS 6D","caption":"","created_timestamp":"1638188917","copyright":"","focal_length":"16","iso":"250","shutter_speed":"0.033333333333333","title":"","orientation":"1","keywords":[]},"ID":"689735","name":"a9ad3f65-21a5-4b44-8391-823125015e2e.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2021\/11\/a9ad3f65-21a5-4b44-8391-823125015e2e.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/a9ad3f65-21a5-4b44-8391-823125015e2e-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/a9ad3f65-21a5-4b44-8391-823125015e2e.jpg","title":"a9ad3f65-21a5-4b44-8391-823125015e2e","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/a9ad3f65-21a5-4b44-8391-823125015e2e-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/a9ad3f65-21a5-4b44-8391-823125015e2e-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/a9ad3f65-21a5-4b44-8391-823125015e2e-210x210.jpg 210w"},{"width":150,"height":150,"file":"2021\/11\/130c8582-bc0c-4237-8048-69fba9a28d6b.jpg","filesize":142788,"sizes":{"medium":{"file":"130c8582-bc0c-4237-8048-69fba9a28d6b-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":23475,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/130c8582-bc0c-4237-8048-69fba9a28d6b-300x200.jpg"},"large":{"file":"130c8582-bc0c-4237-8048-69fba9a28d6b-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":97104,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/130c8582-bc0c-4237-8048-69fba9a28d6b-1024x683.jpg"},"thumbnail":{"file":"130c8582-bc0c-4237-8048-69fba9a28d6b-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":17417,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/130c8582-bc0c-4237-8048-69fba9a28d6b-150x150.jpg"},"medium_large":{"file":"130c8582-bc0c-4237-8048-69fba9a28d6b-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":63752,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/130c8582-bc0c-4237-8048-69fba9a28d6b-768x512.jpg"},"square":{"file":"130c8582-bc0c-4237-8048-69fba9a28d6b-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":42134,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/130c8582-bc0c-4237-8048-69fba9a28d6b-450x450.jpg"},"property-large-image":{"file":"130c8582-bc0c-4237-8048-69fba9a28d6b-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":119242,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/130c8582-bc0c-4237-8048-69fba9a28d6b-1170x780.jpg"},"post-thumbnail":{"file":"130c8582-bc0c-4237-8048-69fba9a28d6b-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":16123,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/130c8582-bc0c-4237-8048-69fba9a28d6b-150x100.jpg"},"modern-property-child-slider":{"file":"130c8582-bc0c-4237-8048-69fba9a28d6b-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":57497,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/130c8582-bc0c-4237-8048-69fba9a28d6b-680x510.jpg"},"property-thumb-image":{"file":"130c8582-bc0c-4237-8048-69fba9a28d6b-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":36908,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/130c8582-bc0c-4237-8048-69fba9a28d6b-488x326.jpg"},"property-detail-video-image":{"file":"130c8582-bc0c-4237-8048-69fba9a28d6b-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":58426,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/130c8582-bc0c-4237-8048-69fba9a28d6b-818x417.jpg"},"agent-image":{"file":"130c8582-bc0c-4237-8048-69fba9a28d6b-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":21163,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/130c8582-bc0c-4237-8048-69fba9a28d6b-210x210.jpg"},"partners-logo":{"file":"130c8582-bc0c-4237-8048-69fba9a28d6b-600x1000.jpg","width":600,"height":1000,"mime-type":"image\/jpeg","filesize":84682,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/130c8582-bc0c-4237-8048-69fba9a28d6b-600x1000.jpg"},"post-featured-image":{"file":"130c8582-bc0c-4237-8048-69fba9a28d6b-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":115681,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/130c8582-bc0c-4237-8048-69fba9a28d6b-1240x720.jpg"}},"image_meta":{"aperture":"6.7","credit":"","camera":"Canon EOS 6D","caption":"","created_timestamp":"1638188963","copyright":"","focal_length":"16","iso":"640","shutter_speed":"0.0055555555555556","title":"","orientation":"1","keywords":[]},"ID":"689739","name":"130c8582-bc0c-4237-8048-69fba9a28d6b.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2021\/11\/130c8582-bc0c-4237-8048-69fba9a28d6b.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/130c8582-bc0c-4237-8048-69fba9a28d6b-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/130c8582-bc0c-4237-8048-69fba9a28d6b.jpg","title":"130c8582-bc0c-4237-8048-69fba9a28d6b","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/130c8582-bc0c-4237-8048-69fba9a28d6b-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/130c8582-bc0c-4237-8048-69fba9a28d6b-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/130c8582-bc0c-4237-8048-69fba9a28d6b-210x210.jpg 210w"},{"width":150,"height":150,"file":"2021\/11\/d3db49ee-02ea-4975-924e-cf1d93edecfe.jpg","filesize":278346,"sizes":{"medium":{"file":"d3db49ee-02ea-4975-924e-cf1d93edecfe-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":26883,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/d3db49ee-02ea-4975-924e-cf1d93edecfe-300x200.jpg"},"large":{"file":"d3db49ee-02ea-4975-924e-cf1d93edecfe-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":156791,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/d3db49ee-02ea-4975-924e-cf1d93edecfe-1024x683.jpg"},"thumbnail":{"file":"d3db49ee-02ea-4975-924e-cf1d93edecfe-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":18319,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/d3db49ee-02ea-4975-924e-cf1d93edecfe-150x150.jpg"},"medium_large":{"file":"d3db49ee-02ea-4975-924e-cf1d93edecfe-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":93976,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/d3db49ee-02ea-4975-924e-cf1d93edecfe-768x512.jpg"},"square":{"file":"d3db49ee-02ea-4975-924e-cf1d93edecfe-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":54003,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/d3db49ee-02ea-4975-924e-cf1d93edecfe-450x450.jpg"},"property-large-image":{"file":"d3db49ee-02ea-4975-924e-cf1d93edecfe-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":201158,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/d3db49ee-02ea-4975-924e-cf1d93edecfe-1170x780.jpg"},"post-thumbnail":{"file":"d3db49ee-02ea-4975-924e-cf1d93edecfe-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":16752,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/d3db49ee-02ea-4975-924e-cf1d93edecfe-150x100.jpg"},"modern-property-child-slider":{"file":"d3db49ee-02ea-4975-924e-cf1d93edecfe-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":82947,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/d3db49ee-02ea-4975-924e-cf1d93edecfe-680x510.jpg"},"property-thumb-image":{"file":"d3db49ee-02ea-4975-924e-cf1d93edecfe-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":47830,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/d3db49ee-02ea-4975-924e-cf1d93edecfe-488x326.jpg"},"property-detail-video-image":{"file":"d3db49ee-02ea-4975-924e-cf1d93edecfe-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":83759,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/d3db49ee-02ea-4975-924e-cf1d93edecfe-818x417.jpg"},"agent-image":{"file":"d3db49ee-02ea-4975-924e-cf1d93edecfe-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":23128,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/d3db49ee-02ea-4975-924e-cf1d93edecfe-210x210.jpg"},"partners-logo":{"file":"d3db49ee-02ea-4975-924e-cf1d93edecfe-600x1000.jpg","width":600,"height":1000,"mime-type":"image\/jpeg","filesize":134578,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/d3db49ee-02ea-4975-924e-cf1d93edecfe-600x1000.jpg"},"post-featured-image":{"file":"d3db49ee-02ea-4975-924e-cf1d93edecfe-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":197298,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/d3db49ee-02ea-4975-924e-cf1d93edecfe-1240x720.jpg"}},"image_meta":{"aperture":"6.7","credit":"","camera":"Canon EOS 6D","caption":"","created_timestamp":"1638189194","copyright":"","focal_length":"16","iso":"500","shutter_speed":"0.016666666666667","title":"","orientation":"1","keywords":[]},"ID":"689743","name":"d3db49ee-02ea-4975-924e-cf1d93edecfe.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2021\/11\/d3db49ee-02ea-4975-924e-cf1d93edecfe.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/d3db49ee-02ea-4975-924e-cf1d93edecfe-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/d3db49ee-02ea-4975-924e-cf1d93edecfe.jpg","title":"d3db49ee-02ea-4975-924e-cf1d93edecfe","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/d3db49ee-02ea-4975-924e-cf1d93edecfe-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/d3db49ee-02ea-4975-924e-cf1d93edecfe-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/d3db49ee-02ea-4975-924e-cf1d93edecfe-210x210.jpg 210w"},{"width":150,"height":150,"file":"2021\/11\/74f1e478-5ede-4a92-88e5-77db56d090b2.jpg","filesize":181610,"sizes":{"medium":{"file":"74f1e478-5ede-4a92-88e5-77db56d090b2-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":24917,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/74f1e478-5ede-4a92-88e5-77db56d090b2-300x200.jpg"},"large":{"file":"74f1e478-5ede-4a92-88e5-77db56d090b2-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":116004,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/74f1e478-5ede-4a92-88e5-77db56d090b2-1024x683.jpg"},"thumbnail":{"file":"74f1e478-5ede-4a92-88e5-77db56d090b2-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":18307,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/74f1e478-5ede-4a92-88e5-77db56d090b2-150x150.jpg"},"medium_large":{"file":"74f1e478-5ede-4a92-88e5-77db56d090b2-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":74223,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/74f1e478-5ede-4a92-88e5-77db56d090b2-768x512.jpg"},"square":{"file":"74f1e478-5ede-4a92-88e5-77db56d090b2-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":49806,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/74f1e478-5ede-4a92-88e5-77db56d090b2-450x450.jpg"},"property-large-image":{"file":"74f1e478-5ede-4a92-88e5-77db56d090b2-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":144147,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/74f1e478-5ede-4a92-88e5-77db56d090b2-1170x780.jpg"},"post-thumbnail":{"file":"74f1e478-5ede-4a92-88e5-77db56d090b2-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":16462,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/74f1e478-5ede-4a92-88e5-77db56d090b2-150x100.jpg"},"modern-property-child-slider":{"file":"74f1e478-5ede-4a92-88e5-77db56d090b2-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":71577,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/74f1e478-5ede-4a92-88e5-77db56d090b2-680x510.jpg"},"property-thumb-image":{"file":"74f1e478-5ede-4a92-88e5-77db56d090b2-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":41118,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/74f1e478-5ede-4a92-88e5-77db56d090b2-488x326.jpg"},"property-detail-video-image":{"file":"74f1e478-5ede-4a92-88e5-77db56d090b2-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":69935,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/74f1e478-5ede-4a92-88e5-77db56d090b2-818x417.jpg"},"agent-image":{"file":"74f1e478-5ede-4a92-88e5-77db56d090b2-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":22709,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/74f1e478-5ede-4a92-88e5-77db56d090b2-210x210.jpg"},"partners-logo":{"file":"74f1e478-5ede-4a92-88e5-77db56d090b2-600x1000.jpg","width":600,"height":1000,"mime-type":"image\/jpeg","filesize":108627,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/74f1e478-5ede-4a92-88e5-77db56d090b2-600x1000.jpg"},"post-featured-image":{"file":"74f1e478-5ede-4a92-88e5-77db56d090b2-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":145148,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/74f1e478-5ede-4a92-88e5-77db56d090b2-1240x720.jpg"}},"image_meta":{"aperture":"6.7","credit":"","camera":"Canon EOS 6D","caption":"","created_timestamp":"1638188827","copyright":"","focal_length":"16","iso":"250","shutter_speed":"0.0055555555555556","title":"","orientation":"1","keywords":[]},"ID":"689747","name":"74f1e478-5ede-4a92-88e5-77db56d090b2.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2021\/11\/74f1e478-5ede-4a92-88e5-77db56d090b2.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/74f1e478-5ede-4a92-88e5-77db56d090b2-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/74f1e478-5ede-4a92-88e5-77db56d090b2.jpg","title":"74f1e478-5ede-4a92-88e5-77db56d090b2","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/74f1e478-5ede-4a92-88e5-77db56d090b2-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/74f1e478-5ede-4a92-88e5-77db56d090b2-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/74f1e478-5ede-4a92-88e5-77db56d090b2-210x210.jpg 210w"},{"width":150,"height":150,"file":"2021\/11\/3821a4e4-b5aa-40ac-8199-faef1f24ca58.jpg","filesize":145813,"sizes":{"medium":{"file":"3821a4e4-b5aa-40ac-8199-faef1f24ca58-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":23737,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3821a4e4-b5aa-40ac-8199-faef1f24ca58-300x200.jpg"},"large":{"file":"3821a4e4-b5aa-40ac-8199-faef1f24ca58-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":99615,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3821a4e4-b5aa-40ac-8199-faef1f24ca58-1024x683.jpg"},"thumbnail":{"file":"3821a4e4-b5aa-40ac-8199-faef1f24ca58-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":17206,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3821a4e4-b5aa-40ac-8199-faef1f24ca58-150x150.jpg"},"medium_large":{"file":"3821a4e4-b5aa-40ac-8199-faef1f24ca58-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":66128,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3821a4e4-b5aa-40ac-8199-faef1f24ca58-768x512.jpg"},"square":{"file":"3821a4e4-b5aa-40ac-8199-faef1f24ca58-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":41494,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3821a4e4-b5aa-40ac-8199-faef1f24ca58-450x450.jpg"},"property-large-image":{"file":"3821a4e4-b5aa-40ac-8199-faef1f24ca58-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":122750,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3821a4e4-b5aa-40ac-8199-faef1f24ca58-1170x780.jpg"},"post-thumbnail":{"file":"3821a4e4-b5aa-40ac-8199-faef1f24ca58-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":16091,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3821a4e4-b5aa-40ac-8199-faef1f24ca58-150x100.jpg"},"modern-property-child-slider":{"file":"3821a4e4-b5aa-40ac-8199-faef1f24ca58-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":59095,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3821a4e4-b5aa-40ac-8199-faef1f24ca58-680x510.jpg"},"property-thumb-image":{"file":"3821a4e4-b5aa-40ac-8199-faef1f24ca58-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":37928,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3821a4e4-b5aa-40ac-8199-faef1f24ca58-488x326.jpg"},"property-detail-video-image":{"file":"3821a4e4-b5aa-40ac-8199-faef1f24ca58-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":60820,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3821a4e4-b5aa-40ac-8199-faef1f24ca58-818x417.jpg"},"agent-image":{"file":"3821a4e4-b5aa-40ac-8199-faef1f24ca58-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":20950,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3821a4e4-b5aa-40ac-8199-faef1f24ca58-210x210.jpg"},"partners-logo":{"file":"3821a4e4-b5aa-40ac-8199-faef1f24ca58-600x1000.jpg","width":600,"height":1000,"mime-type":"image\/jpeg","filesize":78256,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3821a4e4-b5aa-40ac-8199-faef1f24ca58-600x1000.jpg"},"post-featured-image":{"file":"3821a4e4-b5aa-40ac-8199-faef1f24ca58-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":120510,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3821a4e4-b5aa-40ac-8199-faef1f24ca58-1240x720.jpg"}},"image_meta":{"aperture":"6.7","credit":"","camera":"Canon EOS 6D","caption":"","created_timestamp":"1638188850","copyright":"","focal_length":"22","iso":"250","shutter_speed":"0.0055555555555556","title":"","orientation":"1","keywords":[]},"ID":"689751","name":"3821a4e4-b5aa-40ac-8199-faef1f24ca58.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2021\/11\/3821a4e4-b5aa-40ac-8199-faef1f24ca58.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3821a4e4-b5aa-40ac-8199-faef1f24ca58-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3821a4e4-b5aa-40ac-8199-faef1f24ca58.jpg","title":"3821a4e4-b5aa-40ac-8199-faef1f24ca58","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3821a4e4-b5aa-40ac-8199-faef1f24ca58-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3821a4e4-b5aa-40ac-8199-faef1f24ca58-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3821a4e4-b5aa-40ac-8199-faef1f24ca58-210x210.jpg 210w"},{"width":150,"height":150,"file":"2021\/11\/8176287e-c859-4cdd-bea8-181c530a1678.jpg","filesize":79671,"sizes":{"medium":{"file":"8176287e-c859-4cdd-bea8-181c530a1678-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":19224,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/8176287e-c859-4cdd-bea8-181c530a1678-300x200.jpg"},"large":{"file":"8176287e-c859-4cdd-bea8-181c530a1678-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":61497,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/8176287e-c859-4cdd-bea8-181c530a1678-1024x683.jpg"},"thumbnail":{"file":"8176287e-c859-4cdd-bea8-181c530a1678-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":15670,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/8176287e-c859-4cdd-bea8-181c530a1678-150x150.jpg"},"medium_large":{"file":"8176287e-c859-4cdd-bea8-181c530a1678-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":43103,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/8176287e-c859-4cdd-bea8-181c530a1678-768x512.jpg"},"square":{"file":"8176287e-c859-4cdd-bea8-181c530a1678-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":31002,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/8176287e-c859-4cdd-bea8-181c530a1678-450x450.jpg"},"property-large-image":{"file":"8176287e-c859-4cdd-bea8-181c530a1678-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":73441,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/8176287e-c859-4cdd-bea8-181c530a1678-1170x780.jpg"},"post-thumbnail":{"file":"8176287e-c859-4cdd-bea8-181c530a1678-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":14815,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/8176287e-c859-4cdd-bea8-181c530a1678-150x100.jpg"},"modern-property-child-slider":{"file":"8176287e-c859-4cdd-bea8-181c530a1678-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":40470,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/8176287e-c859-4cdd-bea8-181c530a1678-680x510.jpg"},"property-thumb-image":{"file":"8176287e-c859-4cdd-bea8-181c530a1678-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":27375,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/8176287e-c859-4cdd-bea8-181c530a1678-488x326.jpg"},"property-detail-video-image":{"file":"8176287e-c859-4cdd-bea8-181c530a1678-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":38923,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/8176287e-c859-4cdd-bea8-181c530a1678-818x417.jpg"},"agent-image":{"file":"8176287e-c859-4cdd-bea8-181c530a1678-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":17927,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/8176287e-c859-4cdd-bea8-181c530a1678-210x210.jpg"},"partners-logo":{"file":"8176287e-c859-4cdd-bea8-181c530a1678-600x1000.jpg","width":600,"height":1000,"mime-type":"image\/jpeg","filesize":54965,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/8176287e-c859-4cdd-bea8-181c530a1678-600x1000.jpg"},"post-featured-image":{"file":"8176287e-c859-4cdd-bea8-181c530a1678-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":69449,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/8176287e-c859-4cdd-bea8-181c530a1678-1240x720.jpg"}},"image_meta":{"aperture":"6.7","credit":"","camera":"Canon EOS 6D","caption":"","created_timestamp":"1638189032","copyright":"","focal_length":"16","iso":"200","shutter_speed":"0.016666666666667","title":"","orientation":"1","keywords":[]},"ID":"689755","name":"8176287e-c859-4cdd-bea8-181c530a1678.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2021\/11\/8176287e-c859-4cdd-bea8-181c530a1678.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/8176287e-c859-4cdd-bea8-181c530a1678-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/8176287e-c859-4cdd-bea8-181c530a1678.jpg","title":"8176287e-c859-4cdd-bea8-181c530a1678","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/8176287e-c859-4cdd-bea8-181c530a1678-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/8176287e-c859-4cdd-bea8-181c530a1678-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/8176287e-c859-4cdd-bea8-181c530a1678-210x210.jpg 210w"},{"width":150,"height":150,"file":"2021\/11\/362ee80c-ee86-4ad5-8660-9af27dbc10bd.jpg","filesize":83706,"sizes":{"medium":{"file":"362ee80c-ee86-4ad5-8660-9af27dbc10bd-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":19511,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/362ee80c-ee86-4ad5-8660-9af27dbc10bd-300x200.jpg"},"large":{"file":"362ee80c-ee86-4ad5-8660-9af27dbc10bd-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":62901,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/362ee80c-ee86-4ad5-8660-9af27dbc10bd-1024x683.jpg"},"thumbnail":{"file":"362ee80c-ee86-4ad5-8660-9af27dbc10bd-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":15688,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/362ee80c-ee86-4ad5-8660-9af27dbc10bd-150x150.jpg"},"medium_large":{"file":"362ee80c-ee86-4ad5-8660-9af27dbc10bd-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":43448,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/362ee80c-ee86-4ad5-8660-9af27dbc10bd-768x512.jpg"},"square":{"file":"362ee80c-ee86-4ad5-8660-9af27dbc10bd-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":30654,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/362ee80c-ee86-4ad5-8660-9af27dbc10bd-450x450.jpg"},"property-large-image":{"file":"362ee80c-ee86-4ad5-8660-9af27dbc10bd-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":75486,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/362ee80c-ee86-4ad5-8660-9af27dbc10bd-1170x780.jpg"},"post-thumbnail":{"file":"362ee80c-ee86-4ad5-8660-9af27dbc10bd-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":14975,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/362ee80c-ee86-4ad5-8660-9af27dbc10bd-150x100.jpg"},"modern-property-child-slider":{"file":"362ee80c-ee86-4ad5-8660-9af27dbc10bd-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":41672,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/362ee80c-ee86-4ad5-8660-9af27dbc10bd-680x510.jpg"},"property-thumb-image":{"file":"362ee80c-ee86-4ad5-8660-9af27dbc10bd-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":27794,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/362ee80c-ee86-4ad5-8660-9af27dbc10bd-488x326.jpg"},"property-detail-video-image":{"file":"362ee80c-ee86-4ad5-8660-9af27dbc10bd-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":40069,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/362ee80c-ee86-4ad5-8660-9af27dbc10bd-818x417.jpg"},"agent-image":{"file":"362ee80c-ee86-4ad5-8660-9af27dbc10bd-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":18020,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/362ee80c-ee86-4ad5-8660-9af27dbc10bd-210x210.jpg"},"partners-logo":{"file":"362ee80c-ee86-4ad5-8660-9af27dbc10bd-600x1000.jpg","width":600,"height":1000,"mime-type":"image\/jpeg","filesize":53843,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/362ee80c-ee86-4ad5-8660-9af27dbc10bd-600x1000.jpg"},"post-featured-image":{"file":"362ee80c-ee86-4ad5-8660-9af27dbc10bd-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":72742,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/362ee80c-ee86-4ad5-8660-9af27dbc10bd-1240x720.jpg"}},"image_meta":{"aperture":"6.7","credit":"","camera":"Canon EOS 6D","caption":"","created_timestamp":"1638189057","copyright":"","focal_length":"16","iso":"500","shutter_speed":"0.022222222222222","title":"","orientation":"1","keywords":[]},"ID":"689759","name":"362ee80c-ee86-4ad5-8660-9af27dbc10bd.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2021\/11\/362ee80c-ee86-4ad5-8660-9af27dbc10bd.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/362ee80c-ee86-4ad5-8660-9af27dbc10bd-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/362ee80c-ee86-4ad5-8660-9af27dbc10bd.jpg","title":"362ee80c-ee86-4ad5-8660-9af27dbc10bd","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/362ee80c-ee86-4ad5-8660-9af27dbc10bd-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/362ee80c-ee86-4ad5-8660-9af27dbc10bd-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/362ee80c-ee86-4ad5-8660-9af27dbc10bd-210x210.jpg 210w"},{"width":150,"height":150,"file":"2021\/11\/9111a4e1-4de1-42d3-b52b-e500f5606910.jpg","filesize":122723,"sizes":{"medium":{"file":"9111a4e1-4de1-42d3-b52b-e500f5606910-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":22527,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/9111a4e1-4de1-42d3-b52b-e500f5606910-300x200.jpg"},"large":{"file":"9111a4e1-4de1-42d3-b52b-e500f5606910-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":86718,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/9111a4e1-4de1-42d3-b52b-e500f5606910-1024x683.jpg"},"thumbnail":{"file":"9111a4e1-4de1-42d3-b52b-e500f5606910-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":16805,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/9111a4e1-4de1-42d3-b52b-e500f5606910-150x150.jpg"},"medium_large":{"file":"9111a4e1-4de1-42d3-b52b-e500f5606910-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":57948,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/9111a4e1-4de1-42d3-b52b-e500f5606910-768x512.jpg"},"square":{"file":"9111a4e1-4de1-42d3-b52b-e500f5606910-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":37882,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/9111a4e1-4de1-42d3-b52b-e500f5606910-450x450.jpg"},"property-large-image":{"file":"9111a4e1-4de1-42d3-b52b-e500f5606910-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":105126,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/9111a4e1-4de1-42d3-b52b-e500f5606910-1170x780.jpg"},"post-thumbnail":{"file":"9111a4e1-4de1-42d3-b52b-e500f5606910-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":15837,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/9111a4e1-4de1-42d3-b52b-e500f5606910-150x100.jpg"},"modern-property-child-slider":{"file":"9111a4e1-4de1-42d3-b52b-e500f5606910-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":53093,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/9111a4e1-4de1-42d3-b52b-e500f5606910-680x510.jpg"},"property-thumb-image":{"file":"9111a4e1-4de1-42d3-b52b-e500f5606910-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":34387,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/9111a4e1-4de1-42d3-b52b-e500f5606910-488x326.jpg"},"property-detail-video-image":{"file":"9111a4e1-4de1-42d3-b52b-e500f5606910-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":53692,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/9111a4e1-4de1-42d3-b52b-e500f5606910-818x417.jpg"},"agent-image":{"file":"9111a4e1-4de1-42d3-b52b-e500f5606910-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":19972,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/9111a4e1-4de1-42d3-b52b-e500f5606910-210x210.jpg"},"partners-logo":{"file":"9111a4e1-4de1-42d3-b52b-e500f5606910-600x1000.jpg","width":600,"height":1000,"mime-type":"image\/jpeg","filesize":71354,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/9111a4e1-4de1-42d3-b52b-e500f5606910-600x1000.jpg"},"post-featured-image":{"file":"9111a4e1-4de1-42d3-b52b-e500f5606910-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":102119,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/9111a4e1-4de1-42d3-b52b-e500f5606910-1240x720.jpg"}},"image_meta":{"aperture":"6.7","credit":"","camera":"Canon EOS 6D","caption":"","created_timestamp":"1638189079","copyright":"","focal_length":"16","iso":"500","shutter_speed":"0.008","title":"","orientation":"1","keywords":[]},"ID":"689763","name":"9111a4e1-4de1-42d3-b52b-e500f5606910.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2021\/11\/9111a4e1-4de1-42d3-b52b-e500f5606910.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/9111a4e1-4de1-42d3-b52b-e500f5606910-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/9111a4e1-4de1-42d3-b52b-e500f5606910.jpg","title":"9111a4e1-4de1-42d3-b52b-e500f5606910","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/9111a4e1-4de1-42d3-b52b-e500f5606910-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/9111a4e1-4de1-42d3-b52b-e500f5606910-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/9111a4e1-4de1-42d3-b52b-e500f5606910-210x210.jpg 210w"},{"width":150,"height":150,"file":"2021\/11\/b874b748-e7a6-41e9-8171-21d92e246e5e.jpg","filesize":100901,"sizes":{"medium":{"file":"b874b748-e7a6-41e9-8171-21d92e246e5e-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":19851,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b874b748-e7a6-41e9-8171-21d92e246e5e-300x200.jpg"},"large":{"file":"b874b748-e7a6-41e9-8171-21d92e246e5e-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":72126,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b874b748-e7a6-41e9-8171-21d92e246e5e-1024x683.jpg"},"thumbnail":{"file":"b874b748-e7a6-41e9-8171-21d92e246e5e-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":16189,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b874b748-e7a6-41e9-8171-21d92e246e5e-150x150.jpg"},"medium_large":{"file":"b874b748-e7a6-41e9-8171-21d92e246e5e-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":48539,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b874b748-e7a6-41e9-8171-21d92e246e5e-768x512.jpg"},"square":{"file":"b874b748-e7a6-41e9-8171-21d92e246e5e-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":35591,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b874b748-e7a6-41e9-8171-21d92e246e5e-450x450.jpg"},"property-large-image":{"file":"b874b748-e7a6-41e9-8171-21d92e246e5e-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":87659,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b874b748-e7a6-41e9-8171-21d92e246e5e-1170x780.jpg"},"post-thumbnail":{"file":"b874b748-e7a6-41e9-8171-21d92e246e5e-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":14915,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b874b748-e7a6-41e9-8171-21d92e246e5e-150x100.jpg"},"modern-property-child-slider":{"file":"b874b748-e7a6-41e9-8171-21d92e246e5e-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":45887,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b874b748-e7a6-41e9-8171-21d92e246e5e-680x510.jpg"},"property-thumb-image":{"file":"b874b748-e7a6-41e9-8171-21d92e246e5e-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":29189,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b874b748-e7a6-41e9-8171-21d92e246e5e-488x326.jpg"},"property-detail-video-image":{"file":"b874b748-e7a6-41e9-8171-21d92e246e5e-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":42425,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b874b748-e7a6-41e9-8171-21d92e246e5e-818x417.jpg"},"agent-image":{"file":"b874b748-e7a6-41e9-8171-21d92e246e5e-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":18970,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b874b748-e7a6-41e9-8171-21d92e246e5e-210x210.jpg"},"partners-logo":{"file":"b874b748-e7a6-41e9-8171-21d92e246e5e-600x1000.jpg","width":600,"height":1000,"mime-type":"image\/jpeg","filesize":76175,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b874b748-e7a6-41e9-8171-21d92e246e5e-600x1000.jpg"},"post-featured-image":{"file":"b874b748-e7a6-41e9-8171-21d92e246e5e-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":81925,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b874b748-e7a6-41e9-8171-21d92e246e5e-1240x720.jpg"}},"image_meta":{"aperture":"6.7","credit":"","camera":"Canon EOS 6D","caption":"","created_timestamp":"1638189099","copyright":"","focal_length":"16","iso":"500","shutter_speed":"0.016666666666667","title":"","orientation":"1","keywords":[]},"ID":"689767","name":"b874b748-e7a6-41e9-8171-21d92e246e5e.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2021\/11\/b874b748-e7a6-41e9-8171-21d92e246e5e.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b874b748-e7a6-41e9-8171-21d92e246e5e-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b874b748-e7a6-41e9-8171-21d92e246e5e.jpg","title":"b874b748-e7a6-41e9-8171-21d92e246e5e","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b874b748-e7a6-41e9-8171-21d92e246e5e-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b874b748-e7a6-41e9-8171-21d92e246e5e-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/b874b748-e7a6-41e9-8171-21d92e246e5e-210x210.jpg 210w"},{"width":150,"height":150,"file":"2021\/11\/45a8ba36-cd5b-432a-9cc9-c31a740b2740.jpg","filesize":117893,"sizes":{"medium":{"file":"45a8ba36-cd5b-432a-9cc9-c31a740b2740-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":21270,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/45a8ba36-cd5b-432a-9cc9-c31a740b2740-300x200.jpg"},"large":{"file":"45a8ba36-cd5b-432a-9cc9-c31a740b2740-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":83447,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/45a8ba36-cd5b-432a-9cc9-c31a740b2740-1024x683.jpg"},"thumbnail":{"file":"45a8ba36-cd5b-432a-9cc9-c31a740b2740-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":16677,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/45a8ba36-cd5b-432a-9cc9-c31a740b2740-150x150.jpg"},"medium_large":{"file":"45a8ba36-cd5b-432a-9cc9-c31a740b2740-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":55507,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/45a8ba36-cd5b-432a-9cc9-c31a740b2740-768x512.jpg"},"square":{"file":"45a8ba36-cd5b-432a-9cc9-c31a740b2740-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":38531,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/45a8ba36-cd5b-432a-9cc9-c31a740b2740-450x450.jpg"},"property-large-image":{"file":"45a8ba36-cd5b-432a-9cc9-c31a740b2740-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":101085,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/45a8ba36-cd5b-432a-9cc9-c31a740b2740-1170x780.jpg"},"post-thumbnail":{"file":"45a8ba36-cd5b-432a-9cc9-c31a740b2740-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":15363,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/45a8ba36-cd5b-432a-9cc9-c31a740b2740-150x100.jpg"},"modern-property-child-slider":{"file":"45a8ba36-cd5b-432a-9cc9-c31a740b2740-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":52154,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/45a8ba36-cd5b-432a-9cc9-c31a740b2740-680x510.jpg"},"property-thumb-image":{"file":"45a8ba36-cd5b-432a-9cc9-c31a740b2740-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":32448,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/45a8ba36-cd5b-432a-9cc9-c31a740b2740-488x326.jpg"},"property-detail-video-image":{"file":"45a8ba36-cd5b-432a-9cc9-c31a740b2740-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":47768,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/45a8ba36-cd5b-432a-9cc9-c31a740b2740-818x417.jpg"},"agent-image":{"file":"45a8ba36-cd5b-432a-9cc9-c31a740b2740-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":19832,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/45a8ba36-cd5b-432a-9cc9-c31a740b2740-210x210.jpg"},"partners-logo":{"file":"45a8ba36-cd5b-432a-9cc9-c31a740b2740-600x1000.jpg","width":600,"height":1000,"mime-type":"image\/jpeg","filesize":77068,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/45a8ba36-cd5b-432a-9cc9-c31a740b2740-600x1000.jpg"},"post-featured-image":{"file":"45a8ba36-cd5b-432a-9cc9-c31a740b2740-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":94288,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/45a8ba36-cd5b-432a-9cc9-c31a740b2740-1240x720.jpg"}},"image_meta":{"aperture":"6.7","credit":"","camera":"Canon EOS 6D","caption":"","created_timestamp":"1638189109","copyright":"","focal_length":"16","iso":"500","shutter_speed":"0.022222222222222","title":"","orientation":"1","keywords":[]},"ID":"689771","name":"45a8ba36-cd5b-432a-9cc9-c31a740b2740.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2021\/11\/45a8ba36-cd5b-432a-9cc9-c31a740b2740.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/45a8ba36-cd5b-432a-9cc9-c31a740b2740-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/45a8ba36-cd5b-432a-9cc9-c31a740b2740.jpg","title":"45a8ba36-cd5b-432a-9cc9-c31a740b2740","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/45a8ba36-cd5b-432a-9cc9-c31a740b2740-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/45a8ba36-cd5b-432a-9cc9-c31a740b2740-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/45a8ba36-cd5b-432a-9cc9-c31a740b2740-210x210.jpg 210w"},{"width":150,"height":150,"file":"2021\/11\/3e4a1224-7b06-4015-9ad5-2629c1395a25.jpg","filesize":73575,"sizes":{"medium":{"file":"3e4a1224-7b06-4015-9ad5-2629c1395a25-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":18805,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3e4a1224-7b06-4015-9ad5-2629c1395a25-300x200.jpg"},"large":{"file":"3e4a1224-7b06-4015-9ad5-2629c1395a25-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":56646,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3e4a1224-7b06-4015-9ad5-2629c1395a25-1024x683.jpg"},"thumbnail":{"file":"3e4a1224-7b06-4015-9ad5-2629c1395a25-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":15313,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3e4a1224-7b06-4015-9ad5-2629c1395a25-150x150.jpg"},"medium_large":{"file":"3e4a1224-7b06-4015-9ad5-2629c1395a25-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":39913,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3e4a1224-7b06-4015-9ad5-2629c1395a25-768x512.jpg"},"square":{"file":"3e4a1224-7b06-4015-9ad5-2629c1395a25-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":28477,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3e4a1224-7b06-4015-9ad5-2629c1395a25-450x450.jpg"},"property-large-image":{"file":"3e4a1224-7b06-4015-9ad5-2629c1395a25-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":67232,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3e4a1224-7b06-4015-9ad5-2629c1395a25-1170x780.jpg"},"post-thumbnail":{"file":"3e4a1224-7b06-4015-9ad5-2629c1395a25-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":14620,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3e4a1224-7b06-4015-9ad5-2629c1395a25-150x100.jpg"},"modern-property-child-slider":{"file":"3e4a1224-7b06-4015-9ad5-2629c1395a25-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":38607,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3e4a1224-7b06-4015-9ad5-2629c1395a25-680x510.jpg"},"property-thumb-image":{"file":"3e4a1224-7b06-4015-9ad5-2629c1395a25-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":25904,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3e4a1224-7b06-4015-9ad5-2629c1395a25-488x326.jpg"},"property-detail-video-image":{"file":"3e4a1224-7b06-4015-9ad5-2629c1395a25-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":35013,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3e4a1224-7b06-4015-9ad5-2629c1395a25-818x417.jpg"},"agent-image":{"file":"3e4a1224-7b06-4015-9ad5-2629c1395a25-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":17336,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3e4a1224-7b06-4015-9ad5-2629c1395a25-210x210.jpg"},"partners-logo":{"file":"3e4a1224-7b06-4015-9ad5-2629c1395a25-600x1000.jpg","width":600,"height":1000,"mime-type":"image\/jpeg","filesize":44188,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3e4a1224-7b06-4015-9ad5-2629c1395a25-600x1000.jpg"},"post-featured-image":{"file":"3e4a1224-7b06-4015-9ad5-2629c1395a25-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":64350,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3e4a1224-7b06-4015-9ad5-2629c1395a25-1240x720.jpg"}},"image_meta":{"aperture":"6.7","credit":"","camera":"Canon EOS 6D","caption":"","created_timestamp":"1638189129","copyright":"","focal_length":"16","iso":"500","shutter_speed":"0.022222222222222","title":"","orientation":"1","keywords":[]},"ID":"689775","name":"3e4a1224-7b06-4015-9ad5-2629c1395a25.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2021\/11\/3e4a1224-7b06-4015-9ad5-2629c1395a25.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3e4a1224-7b06-4015-9ad5-2629c1395a25-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3e4a1224-7b06-4015-9ad5-2629c1395a25.jpg","title":"3e4a1224-7b06-4015-9ad5-2629c1395a25","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3e4a1224-7b06-4015-9ad5-2629c1395a25-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3e4a1224-7b06-4015-9ad5-2629c1395a25-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3e4a1224-7b06-4015-9ad5-2629c1395a25-210x210.jpg 210w"},{"width":150,"height":150,"file":"2021\/11\/d72ee71b-a7fc-4589-be90-43e37600e7df.jpg","filesize":256859,"sizes":{"medium":{"file":"d72ee71b-a7fc-4589-be90-43e37600e7df-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":27756,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/d72ee71b-a7fc-4589-be90-43e37600e7df-300x200.jpg"},"large":{"file":"d72ee71b-a7fc-4589-be90-43e37600e7df-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":156016,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/d72ee71b-a7fc-4589-be90-43e37600e7df-1024x683.jpg"},"thumbnail":{"file":"d72ee71b-a7fc-4589-be90-43e37600e7df-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":18769,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/d72ee71b-a7fc-4589-be90-43e37600e7df-150x150.jpg"},"medium_large":{"file":"d72ee71b-a7fc-4589-be90-43e37600e7df-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":95704,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/d72ee71b-a7fc-4589-be90-43e37600e7df-768x512.jpg"},"square":{"file":"d72ee71b-a7fc-4589-be90-43e37600e7df-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":58008,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/d72ee71b-a7fc-4589-be90-43e37600e7df-450x450.jpg"},"property-large-image":{"file":"d72ee71b-a7fc-4589-be90-43e37600e7df-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":196256,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/d72ee71b-a7fc-4589-be90-43e37600e7df-1170x780.jpg"},"post-thumbnail":{"file":"d72ee71b-a7fc-4589-be90-43e37600e7df-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":17002,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/d72ee71b-a7fc-4589-be90-43e37600e7df-150x100.jpg"},"modern-property-child-slider":{"file":"d72ee71b-a7fc-4589-be90-43e37600e7df-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":87715,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/d72ee71b-a7fc-4589-be90-43e37600e7df-680x510.jpg"},"property-thumb-image":{"file":"d72ee71b-a7fc-4589-be90-43e37600e7df-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":49278,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/d72ee71b-a7fc-4589-be90-43e37600e7df-488x326.jpg"},"property-detail-video-image":{"file":"d72ee71b-a7fc-4589-be90-43e37600e7df-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":92343,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/d72ee71b-a7fc-4589-be90-43e37600e7df-818x417.jpg"},"agent-image":{"file":"d72ee71b-a7fc-4589-be90-43e37600e7df-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":24147,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/d72ee71b-a7fc-4589-be90-43e37600e7df-210x210.jpg"},"partners-logo":{"file":"d72ee71b-a7fc-4589-be90-43e37600e7df-600x1000.jpg","width":600,"height":1000,"mime-type":"image\/jpeg","filesize":140090,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/d72ee71b-a7fc-4589-be90-43e37600e7df-600x1000.jpg"},"post-featured-image":{"file":"d72ee71b-a7fc-4589-be90-43e37600e7df-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":199711,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/d72ee71b-a7fc-4589-be90-43e37600e7df-1240x720.jpg"}},"image_meta":{"aperture":"8","credit":"","camera":"Canon EOS 6D","caption":"","created_timestamp":"1638188867","copyright":"","focal_length":"16","iso":"400","shutter_speed":"0.008","title":"","orientation":"1","keywords":[]},"ID":"689779","name":"d72ee71b-a7fc-4589-be90-43e37600e7df.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2021\/11\/d72ee71b-a7fc-4589-be90-43e37600e7df.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/d72ee71b-a7fc-4589-be90-43e37600e7df-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/d72ee71b-a7fc-4589-be90-43e37600e7df.jpg","title":"d72ee71b-a7fc-4589-be90-43e37600e7df","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/d72ee71b-a7fc-4589-be90-43e37600e7df-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/d72ee71b-a7fc-4589-be90-43e37600e7df-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/d72ee71b-a7fc-4589-be90-43e37600e7df-210x210.jpg 210w"},{"width":150,"height":150,"file":"2021\/11\/3ea944be-2206-4608-9015-14845607d7da.jpg","filesize":286949,"sizes":{"medium":{"file":"3ea944be-2206-4608-9015-14845607d7da-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":28595,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3ea944be-2206-4608-9015-14845607d7da-300x200.jpg"},"large":{"file":"3ea944be-2206-4608-9015-14845607d7da-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":169332,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3ea944be-2206-4608-9015-14845607d7da-1024x683.jpg"},"thumbnail":{"file":"3ea944be-2206-4608-9015-14845607d7da-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":19253,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3ea944be-2206-4608-9015-14845607d7da-150x150.jpg"},"medium_large":{"file":"3ea944be-2206-4608-9015-14845607d7da-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":102832,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3ea944be-2206-4608-9015-14845607d7da-768x512.jpg"},"square":{"file":"3ea944be-2206-4608-9015-14845607d7da-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":63120,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3ea944be-2206-4608-9015-14845607d7da-450x450.jpg"},"property-large-image":{"file":"3ea944be-2206-4608-9015-14845607d7da-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":213586,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3ea944be-2206-4608-9015-14845607d7da-1170x780.jpg"},"post-thumbnail":{"file":"3ea944be-2206-4608-9015-14845607d7da-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":17237,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3ea944be-2206-4608-9015-14845607d7da-150x100.jpg"},"modern-property-child-slider":{"file":"3ea944be-2206-4608-9015-14845607d7da-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":94785,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3ea944be-2206-4608-9015-14845607d7da-680x510.jpg"},"property-thumb-image":{"file":"3ea944be-2206-4608-9015-14845607d7da-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":51695,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3ea944be-2206-4608-9015-14845607d7da-488x326.jpg"},"property-detail-video-image":{"file":"3ea944be-2206-4608-9015-14845607d7da-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":98707,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3ea944be-2206-4608-9015-14845607d7da-818x417.jpg"},"agent-image":{"file":"3ea944be-2206-4608-9015-14845607d7da-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":25021,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3ea944be-2206-4608-9015-14845607d7da-210x210.jpg"},"partners-logo":{"file":"3ea944be-2206-4608-9015-14845607d7da-600x1000.jpg","width":600,"height":1000,"mime-type":"image\/jpeg","filesize":168057,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3ea944be-2206-4608-9015-14845607d7da-600x1000.jpg"},"post-featured-image":{"file":"3ea944be-2206-4608-9015-14845607d7da-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":216427,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3ea944be-2206-4608-9015-14845607d7da-1240x720.jpg"}},"image_meta":{"aperture":"9","credit":"","camera":"Canon EOS 6D","caption":"","created_timestamp":"1638188877","copyright":"","focal_length":"16","iso":"400","shutter_speed":"0.00625","title":"","orientation":"1","keywords":[]},"ID":"689783","name":"3ea944be-2206-4608-9015-14845607d7da.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2021\/11\/3ea944be-2206-4608-9015-14845607d7da.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3ea944be-2206-4608-9015-14845607d7da-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3ea944be-2206-4608-9015-14845607d7da.jpg","title":"3ea944be-2206-4608-9015-14845607d7da","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3ea944be-2206-4608-9015-14845607d7da-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3ea944be-2206-4608-9015-14845607d7da-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/3ea944be-2206-4608-9015-14845607d7da-210x210.jpg 210w"},{"width":150,"height":150,"file":"2021\/11\/08589ac8-e1e3-47b9-8fa7-315e4a25c568.jpg","filesize":263362,"sizes":{"medium":{"file":"08589ac8-e1e3-47b9-8fa7-315e4a25c568-300x200.jpg","width":300,"height":200,"mime-type":"image\/jpeg","filesize":26548,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/08589ac8-e1e3-47b9-8fa7-315e4a25c568-300x200.jpg"},"large":{"file":"08589ac8-e1e3-47b9-8fa7-315e4a25c568-1024x683.jpg","width":1024,"height":683,"mime-type":"image\/jpeg","filesize":153420,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/08589ac8-e1e3-47b9-8fa7-315e4a25c568-1024x683.jpg"},"thumbnail":{"file":"08589ac8-e1e3-47b9-8fa7-315e4a25c568-150x150.jpg","width":150,"height":150,"mime-type":"image\/jpeg","filesize":18310,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/08589ac8-e1e3-47b9-8fa7-315e4a25c568-150x150.jpg"},"medium_large":{"file":"08589ac8-e1e3-47b9-8fa7-315e4a25c568-768x512.jpg","width":768,"height":512,"mime-type":"image\/jpeg","filesize":92591,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/08589ac8-e1e3-47b9-8fa7-315e4a25c568-768x512.jpg"},"square":{"file":"08589ac8-e1e3-47b9-8fa7-315e4a25c568-450x450.jpg","width":450,"height":450,"mime-type":"image\/jpeg","filesize":56193,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/08589ac8-e1e3-47b9-8fa7-315e4a25c568-450x450.jpg"},"property-large-image":{"file":"08589ac8-e1e3-47b9-8fa7-315e4a25c568-1170x780.jpg","width":1170,"height":780,"mime-type":"image\/jpeg","filesize":195037,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/08589ac8-e1e3-47b9-8fa7-315e4a25c568-1170x780.jpg"},"post-thumbnail":{"file":"08589ac8-e1e3-47b9-8fa7-315e4a25c568-150x100.jpg","width":150,"height":100,"mime-type":"image\/jpeg","filesize":16629,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/08589ac8-e1e3-47b9-8fa7-315e4a25c568-150x100.jpg"},"modern-property-child-slider":{"file":"08589ac8-e1e3-47b9-8fa7-315e4a25c568-680x510.jpg","width":680,"height":510,"mime-type":"image\/jpeg","filesize":83842,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/08589ac8-e1e3-47b9-8fa7-315e4a25c568-680x510.jpg"},"property-thumb-image":{"file":"08589ac8-e1e3-47b9-8fa7-315e4a25c568-488x326.jpg","width":488,"height":326,"mime-type":"image\/jpeg","filesize":46866,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/08589ac8-e1e3-47b9-8fa7-315e4a25c568-488x326.jpg"},"property-detail-video-image":{"file":"08589ac8-e1e3-47b9-8fa7-315e4a25c568-818x417.jpg","width":818,"height":417,"mime-type":"image\/jpeg","filesize":92538,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/08589ac8-e1e3-47b9-8fa7-315e4a25c568-818x417.jpg"},"agent-image":{"file":"08589ac8-e1e3-47b9-8fa7-315e4a25c568-210x210.jpg","width":210,"height":210,"mime-type":"image\/jpeg","filesize":23385,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/08589ac8-e1e3-47b9-8fa7-315e4a25c568-210x210.jpg"},"partners-logo":{"file":"08589ac8-e1e3-47b9-8fa7-315e4a25c568-600x1000.jpg","width":600,"height":1000,"mime-type":"image\/jpeg","filesize":146669,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/08589ac8-e1e3-47b9-8fa7-315e4a25c568-600x1000.jpg"},"post-featured-image":{"file":"08589ac8-e1e3-47b9-8fa7-315e4a25c568-1240x720.jpg","width":1240,"height":720,"mime-type":"image\/jpeg","filesize":202081,"url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/08589ac8-e1e3-47b9-8fa7-315e4a25c568-1240x720.jpg"}},"image_meta":{"aperture":"8","credit":"","camera":"Canon EOS 6D","caption":"","created_timestamp":"1638188885","copyright":"","focal_length":"16","iso":"400","shutter_speed":"0.00625","title":"","orientation":"1","keywords":[]},"ID":"689787","name":"08589ac8-e1e3-47b9-8fa7-315e4a25c568.jpg","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2021\/11\/08589ac8-e1e3-47b9-8fa7-315e4a25c568.jpg","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/08589ac8-e1e3-47b9-8fa7-315e4a25c568-150x150.jpg","full_url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/08589ac8-e1e3-47b9-8fa7-315e4a25c568.jpg","title":"08589ac8-e1e3-47b9-8fa7-315e4a25c568","caption":"","description":"","alt":"","srcset":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/08589ac8-e1e3-47b9-8fa7-315e4a25c568-150x150.jpg 150w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/08589ac8-e1e3-47b9-8fa7-315e4a25c568-450x450.jpg 450w, https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2021\/11\/08589ac8-e1e3-47b9-8fa7-315e4a25c568-210x210.jpg 210w"}],"REAL_HOMES_change_gallery_slider_type":"0","REAL_HOMES_gallery_slider_type":"thumb-on-right","inspiry_floor_plans":[{"inspiry_floor_plan_bedrooms":"1","inspiry_floor_plan_bathrooms":"1"}],"inspiry_video_group":[],"REAL_HOMES_360_virtual_tour":"","REAL_HOMES_tour_video_url":"","REAL_HOMES_tour_video_image":[],"REAL_HOMES_agent_display_option":"agent_info","REAL_HOMES_agents":["388607"],"REAL_HOMES_energy_class":"E","REAL_HOMES_energy_performance":"","REAL_HOMES_epc_current_rating":"","REAL_HOMES_epc_potential_rating":"","ere_property_schedule_tour":"global","ere_property_schedule_time_slots":"","ere_property_schedule_description":"","REAL_HOMES_sticky":"0","inspiry_property_label":"","inspiry_property_label_color":"","inspiry_property_tax":"0","inspiry_additional_fee":"0","REAL_HOMES_attachments":[{"sizes":{"full":{"file":"How-to-book-2-pdf.jpg","width":1059,"height":1497,"mime-type":"image\/jpeg","filesize":236102},"medium":{"file":"How-to-book-2-pdf-212x300.jpg","width":212,"height":300,"mime-type":"image\/jpeg","filesize":15602},"large":{"file":"How-to-book-2-pdf-724x1024.jpg","width":724,"height":1024,"mime-type":"image\/jpeg","filesize":111817},"thumbnail":{"file":"How-to-book-2-pdf-106x150.jpg","width":106,"height":150,"mime-type":"image\/jpeg","filesize":6662}},"filesize":1469979,"ID":"483150","name":"How-to-book-2.pdf","path":"\/home\/locabarcelona.com\/www\/wp-content\/uploads\/2023\/06\/How-to-book-2.pdf","url":"https:\/\/www.locabarcelona.com\/wp-content\/uploads\/2023\/06\/How-to-book-2.pdf","title":"How-to-book-2"}],"inspiry_property_owner_name":"","inspiry_property_owner_contact":"","inspiry_property_owner_address":"","REAL_HOMES_property_private_note":"","inspiry_message_to_reviewer":"","REAL_HOMES_add_in_slider":"no","REAL_HOMES_slider_image":[],"REAL_HOMES_page_banner_image":[],"REAL_HOMES_hide_property_advance_search":"0"},"_links":{"self":[{"href":"https:\/\/www.locabarcelona.com\/en\/wp-json\/wp\/v2\/property\/426980"}],"collection":[{"href":"https:\/\/www.locabarcelona.com\/en\/wp-json\/wp\/v2\/property"}],"about":[{"href":"https:\/\/www.locabarcelona.com\/en\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/www.locabarcelona.com\/en\/wp-json\/wp\/v2\/users\/358"}],"replies":[{"embeddable":true,"href":"https:\/\/www.locabarcelona.com\/en\/wp-json\/wp\/v2\/comments?post=426980"}],"version-history":[{"count":13,"href":"https:\/\/www.locabarcelona.com\/en\/wp-json\/wp\/v2\/property\/426980\/revisions"}],"predecessor-version":[{"id":1120399,"href":"https:\/\/www.locabarcelona.com\/en\/wp-json\/wp\/v2\/property\/426980\/revisions\/1120399"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.locabarcelona.com\/en\/wp-json\/wp\/v2\/media\/689723"}],"wp:attachment":[{"href":"https:\/\/www.locabarcelona.com\/en\/wp-json\/wp\/v2\/media?parent=426980"}],"wp:term":[{"taxonomy":"property-feature","embeddable":true,"href":"https:\/\/www.locabarcelona.com\/en\/wp-json\/wp\/v2\/property-feature?post=426980"},{"taxonomy":"property-type","embeddable":true,"href":"https:\/\/www.locabarcelona.com\/en\/wp-json\/wp\/v2\/property-type?post=426980"},{"taxonomy":"property-city","embeddable":true,"href":"https:\/\/www.locabarcelona.com\/en\/wp-json\/wp\/v2\/property-city?post=426980"},{"taxonomy":"property-status","embeddable":true,"href":"https:\/\/www.locabarcelona.com\/en\/wp-json\/wp\/v2\/property-status?post=426980"},{"taxonomy":"property-sale-label","embeddable":true,"href":"https:\/\/www.locabarcelona.com\/en\/wp-json\/wp\/v2\/property-sale-labels?post=426980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}